{"id":3088,"date":"2023-04-29T17:22:59","date_gmt":"2023-04-29T15:22:59","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/de\/?p=3088"},"modified":"2023-05-01T11:24:27","modified_gmt":"2023-05-01T09:24:27","slug":"der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/","title":{"rendered":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott"},"content":{"rendered":"<p><strong>Ein Dasein ohne Rhythmus und Bedeutung <\/strong><\/p>\n<p>Vergegenw\u00e4rtigen wir uns diese M\u00e4nner und diese Frauen, diese Familien und dieses Volk, die das Elend unserer Zeit verk\u00f6rpern \u2013 Erben jener Armen, die sich vor zweitausend Jahren auf dem Weg Jesu Christi dr\u00e4ngten oder auf den Hohlwegen au\u00dferhalb der St\u00e4dte verbargen; Erben der Armen, die im Mittelalter die Siechen- und Krankenh\u00e4user bev\u00f6lkerten oder unter den Strebepfeilern der Kathedralen Schutz suchten; Erben der Bewohner der anr\u00fcchigen Viertel, und schlie\u00dflich der Slums und der Unterst\u00e4dte zu Anfang dieses Jahrhunderts. Heute finden wir sie abseits, am Rand unserer St\u00e4dte, in Siedlungen, die eigentliche Deponien sind, in den bauf\u00e4lligsten Wohnungen unserer D\u00f6rfer oder auch ganz isoliert an den abgelegensten Orten auf dem Land.<\/p>\n<p>Was offenbaren uns die Armen auf den verborgenen Pfaden unserer Zeit von Gott, vom Glauben an den Gott der Evangelien? Steigen wir hinab auf diesen \u201etiefsten Grund der Welt\u201c, wo sich die Familie Beauchamp aufh\u00e4lt. (&#8230;)<\/p>\n<p><em>Den vollst\u00e4ndigen Text unten herunterladen<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Dasein ohne Rhythmus und Bedeutung Vergegenw\u00e4rtigen wir uns diese M\u00e4nner und diese Frauen, diese Familien und dieses Volk, die (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/\">Weiterlesen &#8230; <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[81,70,83],"tags":[],"class_list":["post-3088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausschnitte-aus-buechern","category-schriften","category-spirituelle-texte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE\" \/>\n<meta property=\"og:description\" content=\"Ein Dasein ohne Rhythmus und Bedeutung Vergegenw\u00e4rtigen wir uns diese M\u00e4nner und diese Frauen, diese Familien und dieses Volk, die (...) Weiterlesen ... &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski DE\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T15:22:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-01T09:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"560\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott\",\"datePublished\":\"2023-04-29T15:22:59+00:00\",\"dateModified\":\"2023-05-01T09:24:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/\"},\"wordCount\":184,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/79943-e4mr9irndo-whr-560x400-1.jpg\",\"articleSection\":[\"Ausschnitte aus B\u00fcchern\",\"Schriften\",\"Spirituelle Texte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/\",\"name\":\"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/79943-e4mr9irndo-whr-560x400-1.jpg\",\"datePublished\":\"2023-04-29T15:22:59+00:00\",\"dateModified\":\"2023-05-01T09:24:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/79943-e4mr9irndo-whr-560x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/79943-e4mr9irndo-whr-560x400-1.jpg\",\"width\":560,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/\",\"name\":\"Joseph Wresinski DE\",\"description\":\"Eine Webseite des  Joseph-Wresinski-Zentrums\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/","og_locale":"de_DE","og_type":"article","og_title":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE","og_description":"Ein Dasein ohne Rhythmus und Bedeutung Vergegenw\u00e4rtigen wir uns diese M\u00e4nner und diese Frauen, diese Familien und dieses Volk, die (...) Weiterlesen ... &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/","og_site_name":"Joseph Wresinski DE","article_published_time":"2023-04-29T15:22:59+00:00","article_modified_time":"2023-05-01T09:24:27+00:00","og_image":[{"width":560,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jean Tonglet","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott","datePublished":"2023-04-29T15:22:59+00:00","dateModified":"2023-05-01T09:24:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/"},"wordCount":184,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg","articleSection":["Ausschnitte aus B\u00fcchern","Schriften","Spirituelle Texte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/","url":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/","name":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott - Joseph Wresinski DE","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg","datePublished":"2023-04-29T15:22:59+00:00","dateModified":"2023-05-01T09:24:27+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/79943-e4mr9irndo-whr-560x400-1.jpg","width":560,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/de\/der-glaube-in-der-vierten-welt-wenn-nichts-mehr-da-ist-als-gott\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.joseph-wresinski.org\/de\/"},{"@type":"ListItem","position":2,"name":"Der Glaube in der Vierten Welt \u2013 wenn nichts mehr da ist als Gott"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/de\/#website","url":"https:\/\/www.joseph-wresinski.org\/de\/","name":"Joseph Wresinski DE","description":"Eine Webseite des  Joseph-Wresinski-Zentrums","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/de\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/comments?post=3088"}],"version-history":[{"count":3,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3088\/revisions"}],"predecessor-version":[{"id":3101,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3088\/revisions\/3101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/media\/3089"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/media?parent=3088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/categories?post=3088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/tags?post=3088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}