{"id":3104,"date":"2023-04-29T22:00:30","date_gmt":"2023-04-29T20:00:30","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/de\/?p=3104"},"modified":"2023-05-01T11:34:24","modified_gmt":"2023-05-01T09:34:24","slug":"die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/","title":{"rendered":"Die Liebe in der Vierten Welt &#8211; was wir zu verwirklichen haben"},"content":{"rendered":"<p>Glaube, Hoffnung, Liebe in der Vierten Welt \u2013 es scheint, dass unsere Betrachtung uns zutiefst in die W\u00fcste menschlichen Daseins f\u00fchrt, w\u00e4hrend sie uns gleichzeitig das Wunderbarste enth\u00fcllt, was die Menschheit\u00a0 \u00fcber Gottes Gegenwart in der Welt zu Tage f\u00f6rdern kann.<\/p>\n<p>Wir suchten Glauben und fanden seine sch\u00fcchternen Anf\u00e4nge am tiefsten Punkt einer zerst\u00f6rten Existenz. Nichts schien den Menschen zu erlauben, noch an irgendjemanden zu glauben. Und trotzdem kommt Glaube zaghaft wieder zum Vorschein, wie eine Blume, die sich weigert zu sterben und inmitten der W\u00fcste hartn\u00e4ckig immer wieder aufbl\u00fcht.<\/p>\n<p>Wir suchten Hoffnung und fanden keine. Aber gleichsam eine verborgene Erwartung liegt im ewigen Neuanfang, den diese Leben darstellen, in ihrem t\u00f6richten Hoffen bei jeder neuen Begegnung, in ihrer hartn\u00e4ckigen Weigerung, ihre W\u00fcrde preiszugeben.<\/p>\n<p>Und wir wissen \u2013 weil es uns der Glaube sagt \u2013\u00a0 dass hier das Geheimnis liegt, das zu verstehen wir nicht verdient haben: Jenseits aller Mutlosigkeit und Verzweiflung spricht Gott zu diesen Menschen. Er wendet sich ihnen besonders zu, und unsere Hoffnung kann der ihren nur zum Durchbruch verhelfen.<\/p>\n<p>Unsere Betrachtung zeigt uns Abgr\u00fcnde auf, die wir geschaffen haben, weil wir das Elend zugelassen haben. Und wir h\u00f6ren die Antwort Gottes, der diese Gr\u00e4ben auff\u00fcllt, weil er den Grundstein seines Reiches genau dort setzen will. Wir h\u00f6ren Gottes Ruf, ihm in die Tiefe zu folgen und an seinem Werk teilzuhaben. Aber wir sind noch nicht am Ende unseres Weges. Wir wollen in der Vierten Welt auch das suchen, was Paulus die gr\u00f6\u00dfte der drei Tugenden nannte: die Liebe.<\/p>\n<p><em>Den vollst\u00e4ndigen Text unten herunterladen<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Glaube, Hoffnung, Liebe in der Vierten Welt \u2013 es scheint, dass unsere Betrachtung uns zutiefst in die W\u00fcste menschlichen Daseins (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/\">Weiterlesen &#8230; <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[81,70,83],"tags":[],"class_list":["post-3104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausschnitte-aus-buechern","category-schriften","category-spirituelle-texte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE\" \/>\n<meta property=\"og:description\" content=\"Glaube, Hoffnung, Liebe in der Vierten Welt \u2013 es scheint, dass unsere Betrachtung uns zutiefst in die W\u00fcste menschlichen Daseins (...) Weiterlesen ... &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski DE\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T20:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-01T09:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"586\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Die Liebe in der Vierten Welt &#8211; was wir zu verwirklichen haben\",\"datePublished\":\"2023-04-29T20:00:30+00:00\",\"dateModified\":\"2023-05-01T09:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/\"},\"wordCount\":287,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg\",\"articleSection\":[\"Ausschnitte aus B\u00fcchern\",\"Schriften\",\"Spirituelle Texte\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/\",\"name\":\"Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg\",\"datePublished\":\"2023-04-29T20:00:30+00:00\",\"dateModified\":\"2023-05-01T09:34:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2023\\\/04\\\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg\",\"width\":586,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Liebe in der Vierten Welt &#8211; was wir zu verwirklichen haben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/\",\"name\":\"Joseph Wresinski DE\",\"description\":\"Eine Webseite des  Joseph-Wresinski-Zentrums\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/de\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/","og_locale":"de_DE","og_type":"article","og_title":"Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE","og_description":"Glaube, Hoffnung, Liebe in der Vierten Welt \u2013 es scheint, dass unsere Betrachtung uns zutiefst in die W\u00fcste menschlichen Daseins (...) Weiterlesen ... &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/","og_site_name":"Joseph Wresinski DE","article_published_time":"2023-04-29T20:00:30+00:00","article_modified_time":"2023-05-01T09:34:24+00:00","og_image":[{"width":586,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Jean Tonglet","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Die Liebe in der Vierten Welt &#8211; was wir zu verwirklichen haben","datePublished":"2023-04-29T20:00:30+00:00","dateModified":"2023-05-01T09:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/"},"wordCount":287,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg","articleSection":["Ausschnitte aus B\u00fcchern","Schriften","Spirituelle Texte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/","url":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/","name":"Die Liebe in der Vierten Welt - was wir zu verwirklichen haben - Joseph Wresinski DE","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg","datePublished":"2023-04-29T20:00:30+00:00","dateModified":"2023-05-01T09:34:24+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg","contentUrl":"https:\/\/www.joseph-wresinski.org\/de\/wp-content\/uploads\/sites\/17\/2023\/04\/Hodler-BUON-SAMARITANO1885-di-Ferdinand-Hodler-1853-1918-Switzerland-586x400-1.jpeg","width":586,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/de\/die-liebe-in-der-vierten-welt-was-wir-zu-verwirklichen-haben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.joseph-wresinski.org\/de\/"},{"@type":"ListItem","position":2,"name":"Die Liebe in der Vierten Welt &#8211; was wir zu verwirklichen haben"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/de\/#website","url":"https:\/\/www.joseph-wresinski.org\/de\/","name":"Joseph Wresinski DE","description":"Eine Webseite des  Joseph-Wresinski-Zentrums","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/de\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/de\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/comments?post=3104"}],"version-history":[{"count":3,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3104\/revisions"}],"predecessor-version":[{"id":3108,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/posts\/3104\/revisions\/3108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/media\/3090"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/media?parent=3104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/categories?post=3104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/de\/wp-json\/wp\/v2\/tags?post=3104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}