{"id":129,"count":25,"description":"","link":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/","name":"Teksty","slug":"teksty","taxonomy":"category","parent":58,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teksty Archives - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teksty Archives - Joseph Wresinski EN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/polski\\\/teksty\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/polski\\\/teksty\\\/\",\"name\":\"Teksty Archives - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/polski\\\/teksty\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/polski\\\/teksty\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Other languages\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"POLSKI\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/category\\\/other-languages\\\/polski\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Teksty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teksty Archives - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/","og_locale":"en_US","og_type":"article","og_title":"Teksty Archives - Joseph Wresinski EN","og_url":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/","og_site_name":"Joseph Wresinski EN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/","url":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/","name":"Teksty Archives - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/teksty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"Other languages","item":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/"},{"@type":"ListItem","position":3,"name":"POLSKI","item":"https:\/\/www.joseph-wresinski.org\/en\/category\/other-languages\/polski\/"},{"@type":"ListItem","position":4,"name":"Teksty"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories\/58"}],"wp:post_type":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts?categories=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}