{"id":3195,"date":"2020-10-08T18:25:39","date_gmt":"2020-10-08T16:25:39","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/en\/?page_id=3195"},"modified":"2020-10-08T18:30:33","modified_gmt":"2020-10-08T16:30:33","slug":"about-this-website-on-joseph-wresinski","status":"publish","type":"page","link":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/","title":{"rendered":"About this Website on Joseph Wresinski"},"content":{"rendered":"<h2><\/h2>\n<p>For the hundredth anniversary of Joseph Wresinski&#8217;s birth on February 12, 1917 the Joseph Wresinski Centre has updated and create this new web site.<\/p>\n<p>A major effort will be made to ensure that the maximum number of documents are available in as many languages as possible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>For the hundredth anniversary of Joseph Wresinski&#8217;s birth on February 12, 1917 the Joseph Wresinski Centre has updated and create (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/\">Read more <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":1818,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"class_list":["post-3195","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About this Website on Joseph Wresinski - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About this Website on Joseph Wresinski - Joseph Wresinski EN\" \/>\n<meta property=\"og:description\" content=\"For the hundredth anniversary of Joseph Wresinski&#8217;s birth on February 12, 1917 the Joseph Wresinski Centre has updated and create (...) Read more &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T16:30:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2016\/12\/Qui-sommes-nous.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1286\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/\",\"name\":\"About this Website on Joseph Wresinski - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/12\\\/Qui-sommes-nous.jpg\",\"datePublished\":\"2020-10-08T16:25:39+00:00\",\"dateModified\":\"2020-10-08T16:30:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/12\\\/Qui-sommes-nous.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2016\\\/12\\\/Qui-sommes-nous.jpg\",\"width\":1286,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/about-this-website-on-joseph-wresinski\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About this Website on Joseph Wresinski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About this Website on Joseph Wresinski - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/","og_locale":"en_US","og_type":"article","og_title":"About this Website on Joseph Wresinski - Joseph Wresinski EN","og_description":"For the hundredth anniversary of Joseph Wresinski&#8217;s birth on February 12, 1917 the Joseph Wresinski Centre has updated and create (...) Read more &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/","og_site_name":"Joseph Wresinski EN","article_modified_time":"2020-10-08T16:30:33+00:00","og_image":[{"width":1286,"height":530,"url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2016\/12\/Qui-sommes-nous.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/","url":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/","name":"About this Website on Joseph Wresinski - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2016\/12\/Qui-sommes-nous.jpg","datePublished":"2020-10-08T16:25:39+00:00","dateModified":"2020-10-08T16:30:33+00:00","breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2016\/12\/Qui-sommes-nous.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2016\/12\/Qui-sommes-nous.jpg","width":1286,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/about-this-website-on-joseph-wresinski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"About this Website on Joseph Wresinski"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/pages\/3195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/comments?post=3195"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/pages\/3195\/revisions"}],"predecessor-version":[{"id":3199,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/pages\/3195\/revisions\/3199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media\/1818"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media?parent=3195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}