{"id":1107,"date":"2009-05-10T16:45:08","date_gmt":"2009-05-10T14:45:08","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/"},"modified":"2021-01-17T13:50:00","modified_gmt":"2021-01-17T12:50:00","slug":"dou-testemunho-de-vos","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/","title":{"rendered":"Dou testemunho de v\u00f3s"},"content":{"rendered":"<h2>ESTROFES \u00c0 GL\u00d3RIA DO QUARTO MUNDO DE TODOS OS TEMPOS<\/h2>\n<p>Milhares e milhares de crian\u00e7as, de m\u00e3es e de pais<br \/>\nque morrestes de mis\u00e9ria, de fome<br \/>\ne de quem n\u00f3s somos os herdeiros!<\/p>\n<p>V\u00f3s que est\u00e1veis entre os vivos,<br \/>\nn\u00e3o \u00e9 a vossa morte que eu evoco hoje,<br \/>\nneste Terreiro das Liberdades,<br \/>\ndos Direitos Humanos e do Cidad\u00e3o.<br \/>\n\u00c9 da vossa vida que dou testemunho.<\/p>\n<p>Dou testemunho de v\u00f3s, m\u00e3es<br \/>\ncujos filhos condenados \u00e0 mis\u00e9ria<br \/>\nest\u00e3o a mais neste mundo.<\/p>\n<p>Dou testemunho de v\u00f3s, crian\u00e7as<br \/>\nretorcidas pelas dores da fome<br \/>\ne que, j\u00e1 tendo perdido o sorriso,<br \/>\nainda n\u00e3o perdestes a vontade de amar.<\/p>\n<p>Dou testemunho de todos estes milhares de jovens,<br \/>\nque, sem motivos para acreditar ou para\u00a0 existir,<br \/>\nainda procuram, em v\u00e3o, um futuro,<br \/>\nneste mundo insensato.<\/p>\n<p>Dou testemunho de v\u00f3s, pobres de todos os tempos,<br \/>\nainda hoje for\u00e7ados a caminhar sem destino,<br \/>\nfugindo de terra em terra, desprezados e desonrados.<\/p>\n<p>Trabalhadores sem profiss\u00e3o,<br \/>\nEsmagados, de gera\u00e7\u00e3o em gera\u00e7\u00e3o, pelo peso do labor.<br \/>\nTrabalhadores cujas m\u00e3os, nos dias que correm,<br \/>\npara nada servem.<\/p>\n<p>Milhares de homens, mulheres e crian\u00e7as<br \/>\ncujos cora\u00e7\u00f5es ainda batem fortemente para lutar,<br \/>\ncujo esp\u00edrito se revolta contra a injusta sorte que lhes foi imposta,<br \/>\ncuja coragem exige o direito \u00e0 inestim\u00e1vel dignidade.<\/p>\n<p>Dou testemunho de v\u00f3s, crian\u00e7as, mulheres e homens<br \/>\nque n\u00e3o quereis amaldi\u00e7oar,<br \/>\nmas sim amar e orar, trabalhar e unir-vos<br \/>\npara que nas\u00e7a uma terra solid\u00e1ria.<br \/>\nUma terra que seja a nossa terra,<br \/>\nonde cada homem, antes de morrer,<br \/>\npoderia dar o melhor dele mesmo.<\/p>\n<p>Dou testemunho de v\u00f3s, homens, mulheres e crian\u00e7as<br \/>\ncujo renome est\u00e1 doravante gravado<br \/>\npelo cora\u00e7\u00e3o, pela m\u00e3o e pelo cinzel<br \/>\nno m\u00e1rmore desta Laje, no Terreiro das Liberdades.<br \/>\nDou testemunho de v\u00f3s para que os homens,<br \/>\nfinalmente, tenham o Homem em considera\u00e7\u00e3o<br \/>\ne recusem para sempre a mis\u00e9ria como obra do destino.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTROFES \u00c0 GL\u00d3RIA DO QUARTO MUNDO DE TODOS OS TEMPOS Milhares e milhares de crian\u00e7as, de m\u00e3es e de pais (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/\">Read more <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-1107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dou testemunho de v\u00f3s - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dou testemunho de v\u00f3s - Joseph Wresinski EN\" \/>\n<meta property=\"og:description\" content=\"ESTROFES \u00c0 GL\u00d3RIA DO QUARTO MUNDO DE TODOS OS TEMPOS Milhares e milhares de crian\u00e7as, de m\u00e3es e de pais (...) Read more &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-10T14:45:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-17T12:50:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Dou testemunho de v\u00f3s\",\"datePublished\":\"2009-05-10T14:45:08+00:00\",\"dateModified\":\"2021-01-17T12:50:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/\"},\"wordCount\":346,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2009\\\/05\\\/21-1987-JW-0071-001-001-22.jpg\",\"articleSection\":[\"PORTUGU\u00caS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/\",\"name\":\"Dou testemunho de v\u00f3s - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2009\\\/05\\\/21-1987-JW-0071-001-001-22.jpg\",\"datePublished\":\"2009-05-10T14:45:08+00:00\",\"dateModified\":\"2021-01-17T12:50:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2009\\\/05\\\/21-1987-JW-0071-001-001-22.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2009\\\/05\\\/21-1987-JW-0071-001-001-22.jpg\",\"width\":\"700\",\"height\":\"542\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/dou-testemunho-de-vos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dou testemunho de v\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dou testemunho de v\u00f3s - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/","og_locale":"en_US","og_type":"article","og_title":"Dou testemunho de v\u00f3s - Joseph Wresinski EN","og_description":"ESTROFES \u00c0 GL\u00d3RIA DO QUARTO MUNDO DE TODOS OS TEMPOS Milhares e milhares de crian\u00e7as, de m\u00e3es e de pais (...) Read more &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/","og_site_name":"Joseph Wresinski EN","article_published_time":"2009-05-10T14:45:08+00:00","article_modified_time":"2021-01-17T12:50:00+00:00","og_image":[{"width":700,"height":542,"url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"Written by":"webmestre","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Dou testemunho de v\u00f3s","datePublished":"2009-05-10T14:45:08+00:00","dateModified":"2021-01-17T12:50:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/"},"wordCount":346,"commentCount":1,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg","articleSection":["PORTUGU\u00caS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/","url":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/","name":"Dou testemunho de v\u00f3s - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg","datePublished":"2009-05-10T14:45:08+00:00","dateModified":"2021-01-17T12:50:00+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2009\/05\/21-1987-JW-0071-001-001-22.jpg","width":"700","height":"542"},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/dou-testemunho-de-vos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"Dou testemunho de v\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/en\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":6,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"predecessor-version":[{"id":3431,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/1107\/revisions\/3431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media\/2095"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}