{"id":4385,"date":"2023-01-14T13:56:40","date_gmt":"2023-01-14T12:56:40","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/en\/?p=4385"},"modified":"2023-01-14T13:56:40","modified_gmt":"2023-01-14T12:56:40","slug":"justica-no-coracao","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/","title":{"rendered":"Justi\u00e7a no Cora\u00e7\u00e3o"},"content":{"rendered":"<p><em>Dirigindo-se a uma assembleia de membros da ATD Quarto Mundo na Holanda em 15 de novembro de 1986, em Heerlen, o Padre Joseph Wresinski explica as raz\u00f5es que o levaram a propor o slogan &#8220;Justi\u00e7a no Cora\u00e7\u00e3o&#8221; para a campanha realizada em 1987, h\u00e1 apenas 20 anos, para comemorar o 30\u00ba anivers\u00e1rio da cria\u00e7\u00e3o da ATD Quarto Mundo. A campanha culminou com a inaugura\u00e7\u00e3o, no dia 17 de outubro de 1987, do Atrium de Liberdades e Direitos Humanos, de uma placa comemorativa em homenagem \u00e0s v\u00edtimas da pobreza.<\/em><\/p>\n<p>Parar a injusti\u00e7a&#8230;&#8221; \u00e9 o que aparece como um grito ao longo do filme que acabamos de ver: &#8220;Basta, h\u00e1 um limite para tudo&#8230;&#8221;! Mas as pessoas tamb\u00e9m nos falam desta maneira, a m\u00e3e que diz: &#8220;Parem a injusti\u00e7a&#8221;! O que eles realmente querem dizer com isso?<\/p>\n<p>Querem dizer que a justi\u00e7a deve finalmente chegar. Mas o que isso significa para eles? Novas leis, \u00e9 claro, nova legisla\u00e7\u00e3o para garantir uma renda garantida, seguran\u00e7a no emprego, moradia digna? Naturalmente, as fam\u00edlias desta favela francesa e as outras fam\u00edlias de diferentes partes do mundo que vemos no filme, reunidas em uma mobiliza\u00e7\u00e3o internacional em Paris, querem tudo isso. \u00c9 um direito deles e \u00e9 nossa responsabilidade garantir que eles obtenham toda essa seguran\u00e7a, protegida por lei. Entretanto, todas estas fam\u00edlias que vivem em grandes dificuldades, que conhe\u00e7o h\u00e1 trinta anos, em toda a Fran\u00e7a, na Europa e no mundo, nunca ficaram satisfeitas com esta justi\u00e7a legislativa, esta justi\u00e7a baseada unicamente na lei. Em Paris e Marselha, em Londres e Munique, em Dakar e Porto Pr\u00edncipe, as fam\u00edlias sempre me falaram de outra justi\u00e7a, a justi\u00e7a do cora\u00e7\u00e3o.<\/p>\n<p>&#8220;Como as pessoas podem ver meus filhos sofrerem na escola sem ficarem com o cora\u00e7\u00e3o partido?&#8221; &#8230; &#8220;Como um homem de neg\u00f3cios pode ser t\u00e3o insens\u00edvel e despedir meu marido? &#8220;Como um assistente social pode ser t\u00e3o duro e injusto a ponto de me acusar de n\u00e3o ser uma boa m\u00e3e? O verdadeiro grito das fam\u00edlias, o grito de voc\u00eas, fam\u00edlias na Holanda, n\u00e3o \u00e9 isso em primeiro lugar?&#8221; &#8220;Como voc\u00eas t\u00eam sido t\u00e3o duros a ponto de nos machucar, desprezar, humilhar, constantemente nos fazer sentir que n\u00e3o somos nada?&#8221;<\/p>\n<p>&#8220;N\u00e3o \u00e9 justo, antes de tudo, isto \u00e9 o que n\u00e3o \u00e9 justo&#8221;, voc\u00ea costuma dizer quando nos encontramos na fazenda em Wijhe [sede da ATD Quarto Mundo na Holanda e Casa de F\u00e9rias Familiares]. A primeira injusti\u00e7a, a primeira que deve acabar, \u00e9 a injusti\u00e7a do cora\u00e7\u00e3o. A injusti\u00e7a mais terr\u00edvel \u00e9 a injusti\u00e7a que faz um ser humano acreditar que \u00e9 superior a outro, que ele acredita que tem o direito de desprez\u00e1-lo.<\/p>\n<p>Penso nesta holandesa de Koevorden que me contou como, quando crian\u00e7a e quando jovem, ela vivia com seus pais em uma barca\u00e7a.<\/p>\n<p>&#8220;Nossa casa estava bem, estava limpa&#8221;, disse-me ela, mas as pessoas da aldeia n\u00e3o achavam que assim fosse. Eles nos olhavam com desprezo, pensavam que n\u00e3o \u00e9ramos pessoas limpas e meus colegas de classe n\u00e3o podiam vir brincar em minha casa, no batel\u00e3o.<\/p>\n<p>Foi esta injusti\u00e7a do cora\u00e7\u00e3o, esta injusti\u00e7a aos olhos do ambiente que fez a jovem, que mais tarde se tornou esposa e m\u00e3e, entender todas as outras injusti\u00e7as, as das leis. Hoje ela entende por que \u00e9 obrigada a viver com sua fam\u00edlia em um apartamento que est\u00e1 esperando h\u00e1 mais de dez anos para ser consertado. Ela espera ano ap\u00f3s ano porque a cidade tem uma pol\u00edtica de economia de dinheiro. Entretanto, \u00e9 sempre o edif\u00edcio em que ela vive que acaba sendo retirado do or\u00e7amento municipal.<\/p>\n<p>Uma injusti\u00e7a escandalosa, uma vez que a prefeitura proporciona a outras fam\u00edlias mais meios para uma boa moradia. Mas a pr\u00f3pria m\u00e3e sabe de onde vem esta injusti\u00e7a na gest\u00e3o de sua cidade. Os funcion\u00e1rios p\u00fablicos que tratavam de seu processo nas secretarias municipais eram crian\u00e7as quando ela era pequena. Na escola, foi-lhes dito que havia pessoas sujas vivendo nas barca\u00e7as, crian\u00e7as com as quais n\u00e3o se devia brincar. Quando crian\u00e7as, estes funcion\u00e1rios n\u00e3o aprenderam a justi\u00e7a do cora\u00e7\u00e3o que afirma que toda crian\u00e7a \u00e9 um irm\u00e3o, um companheiro.<\/p>\n<p>Ent\u00e3o, hoje, como poderia haver justi\u00e7a em seus processos, em suas leis?<\/p>\n<p>Esta m\u00e3e de quem estou falando, que nos contava tudo isto, desta maneira simples, tamb\u00e9m dizia: &#8220;Durante muito tempo n\u00e3o pude falar sobre todas estas coisas com ningu\u00e9m. Hoje, aqui, posso dizer o que vivi, porque aqui, h\u00e1 pessoas com quem podemos conversar&#8221;.<\/p>\n<p>Os direitos humanos s\u00e3o, antes de tudo, uma quest\u00e3o de seres humanos.<\/p>\n<p>&#8220;Pessoas com quem podemos conversar&#8221;, disse esta m\u00e3e. Isto \u00e9 o que dizem todas as fam\u00edlias que v\u00eam \u00e0 fazenda de Wijhe. &#8220;H\u00e1 pessoas aqui com quem podemos conversar&#8221;.<\/p>\n<p>Por que podemos falar com essas pessoas? Porque eles t\u00eam um profundo e poderoso desejo de ouvir, de entender, de compartilhar. Porque a justi\u00e7a n\u00e3o \u00e9 algo que existe apenas em suas cabe\u00e7as e em seu discurso, mas est\u00e1 em seus cora\u00e7\u00f5es. Esta justi\u00e7a que significa que quando outra pessoa sofre, n\u00f3s mesmos sofremos. Quando humilhamos o outro, n\u00f3s mesmos nos sentimos humilhados.<\/p>\n<p>Gostaria de lhes dizer algumas palavras sobre esses volunt\u00e1rios &#8220;com quem se pode falar&#8221;, e a quem voc\u00eas chamam, com raz\u00e3o, &#8221; permanentes&#8221;.<\/p>\n<p>Em que eles s\u00e3o permanentes? Eles s\u00e3o permanentes na justi\u00e7a do cora\u00e7\u00e3o que os faz trabalhar, agir e viver com as fam\u00edlias durante o dia. Justi\u00e7a do cora\u00e7\u00e3o que faz voc\u00ea, mesmo \u00e0 noite, acordar preocupado com o fato de n\u00e3o ter feito o suficiente. Preocupados com o que precisa ser feito amanh\u00e3 para deter a injusti\u00e7a no cora\u00e7\u00e3o das pessoas. Porque ent\u00e3o, esta injusti\u00e7a tamb\u00e9m deixar\u00e1 de existir nas leis.<\/p>\n<p>Estes &#8220;permanentes&#8221;, estes volunt\u00e1rios, aprenderam das fam\u00edlias do Quarto Mundo que a pobreza extrema \u00e9 a mais absoluta viola\u00e7\u00e3o dos direitos humanos.<\/p>\n<p>No Quarto Mundo, n\u00e3o existe nem o direito \u00e0 educa\u00e7\u00e3o nem o direito ao trabalho. N\u00e3o existe a liberdade de escolher uma casa, nem os meios para aderir livremente a uma organiza\u00e7\u00e3o de sua escolha.<\/p>\n<p>&#8220;Outras pessoas n\u00e3o nos veem, \u00e9 como se n\u00f3s n\u00e3o exist\u00edssemos&#8221;, dizem as fam\u00edlias. E aqueles que n\u00e3o existem, que lugar teriam em nossos sindicatos ou partidos pol\u00edticos, em nossas igrejas ou associa\u00e7\u00f5es?<\/p>\n<p>A pobreza extrema \u00e9 uma nega\u00e7\u00e3o de todos os direitos humanos, sejam eles pol\u00edticos, econ\u00f4micos, sociais ou culturais. As fam\u00edlias do Quarto Mundo e os volunt\u00e1rios permanentes aprenderam isso, eles o entenderam juntos. E voc\u00eas, nossos aliados que vieram juntar-se a eles, tamb\u00e9m o entenderam. Assim, em trinta anos, o Quarto Mundo ATD, um movimento de direitos humanos, cresceu e se fortaleceu.<\/p>\n<p>Mas existem muitas organiza\u00e7\u00f5es de direitos humanos no mundo. Somos diferentes? Penso que, gra\u00e7as a voc\u00eas, fam\u00edlias da ATD Quarto Mundo, n\u00e3o somos uma organiza\u00e7\u00e3o como qualquer outra. Por qu\u00ea?<\/p>\n<p>Porque para n\u00f3s, os direitos humanos s\u00f3 existem se forem garantidos at\u00e9 mesmo \u00e0 fam\u00edlia mais desfavorecida, a mais esquecida, a mais rejeitada, a mais desprezada. E porque para n\u00f3s, os direitos humanos s\u00e3o garantidos, a longo prazo, quando s\u00e3o respeitados n\u00e3o somente na legisla\u00e7\u00e3o, mas sobretudo no cora\u00e7\u00e3o e na vida pessoal dos seres humanos.<\/p>\n<p>Desde o final da Segunda Guerra Mundial, n\u00f3s, em nossos pa\u00edses da Europa Ocidental, temos visto um grande avan\u00e7o em mat\u00e9ria de direitos humanos. Ningu\u00e9m pode neg\u00e1-lo: nossos pa\u00edses se dotaram de uma boa legisla\u00e7\u00e3o. Mas os holandeses, os franceses, os belgas, os alem\u00e3es e os brit\u00e2nicos n\u00e3o t\u00eam mantido o ideal de justi\u00e7a no cora\u00e7\u00e3o. Gradualmente, eles se convenceram de que a justi\u00e7a poderia ser reduzida a uma quest\u00e3o de legisla\u00e7\u00e3o.<\/p>\n<p>Os direitos humanos, no entanto, haviam surgido no cora\u00e7\u00e3o das pessoas. Homens e mulheres haviam lutado por eles, porque seus cora\u00e7\u00f5es acreditavam no car\u00e1ter \u00fanico e no valor de todos os seres humanos. E pouco a pouco, sem nos darmos conta, temos feito desta quest\u00e3o do ser humano pelo ser humano, desta quest\u00e3o de f\u00e9 e cora\u00e7\u00e3o, uma quest\u00e3o exclusivamente das estruturas pol\u00edticas e jur\u00eddicas de nossas sociedades.<\/p>\n<p>\u00c9 por isso que nossos cora\u00e7\u00f5es ficavam em sil\u00eancio quando v\u00edamos uma fam\u00edlia vivendo em um barraco, crian\u00e7as profundamente infelizes, exclu\u00eddas e rejeitadas em turmas de escola separadas. Nossos cora\u00e7\u00f5es estavam vazios de justi\u00e7a e pudemos suportar fam\u00edlias, crian\u00e7as, trabalhadores que vivessem na mis\u00e9ria. Com freq\u00fc\u00eancia terminamos por desprez\u00e1-las por sua pobreza. Os repreendemos porque n\u00e3o se aproveitaram de nossas leis. A voca\u00e7\u00e3o da ATD Quarto Mundo \u00e9 nos lembrar a verdadeira hist\u00f3ria dos direitos humanos. As fam\u00edlias do Quarto Mundo nos lembram que devemos retomar o fio da hist\u00f3ria de um ideal nascido do cora\u00e7\u00e3o de todos os seres humanos, porque eles amaram a humanidade. Os direitos humanos s\u00e3o uma quest\u00e3o do cora\u00e7\u00e3o, uma quest\u00e3o de f\u00e9, uma quest\u00e3o de civiliza\u00e7\u00e3o. Uma quest\u00e3o de todo ser humano: eles s\u00e3o homens e mulheres que acreditam que \u00e9 algo que lhes diz respeito, a causa de sua vida, eles s\u00e3o as pessoas que comp\u00f5em este servi\u00e7o volunt\u00e1rio cujas fam\u00edlias pensam que podem compartilhar todo o sofrimento causado por esta injusti\u00e7a do cora\u00e7\u00e3o, muito mais do que a injusti\u00e7a das leis os faz sofrer.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dirigindo-se a uma assembleia de membros da ATD Quarto Mundo na Holanda em 15 de novembro de 1986, em Heerlen, (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/\">Read more <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3808,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[159,187],"tags":[],"class_list":["post-4385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-other-languages","category-portugues-brasileiro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN\" \/>\n<meta property=\"og:description\" content=\"Dirigindo-se a uma assembleia de membros da ATD Quarto Mundo na Holanda em 15 de novembro de 1986, em Heerlen, (...) Read more &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-14T12:56:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Justi\u00e7a no Cora\u00e7\u00e3o\",\"datePublished\":\"2023-01-14T12:56:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/\"},\"wordCount\":1685,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/12\\\/AR0300126006.jpg\",\"articleSection\":[\"Other languages\",\"PORTUGU\u00caS BRASILEIRO\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/\",\"name\":\"Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/12\\\/AR0300126006.jpg\",\"datePublished\":\"2023-01-14T12:56:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/12\\\/AR0300126006.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2019\\\/12\\\/AR0300126006.jpg\",\"width\":775,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/justica-no-coracao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justi\u00e7a no Cora\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/","og_locale":"en_US","og_type":"article","og_title":"Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN","og_description":"Dirigindo-se a uma assembleia de membros da ATD Quarto Mundo na Holanda em 15 de novembro de 1986, em Heerlen, (...) Read more &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/","og_site_name":"Joseph Wresinski EN","article_published_time":"2023-01-14T12:56:40+00:00","og_image":[{"width":775,"height":1100,"url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean Tonglet","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Justi\u00e7a no Cora\u00e7\u00e3o","datePublished":"2023-01-14T12:56:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/"},"wordCount":1685,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg","articleSection":["Other languages","PORTUGU\u00caS BRASILEIRO"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/","url":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/","name":"Justi\u00e7a no Cora\u00e7\u00e3o - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg","datePublished":"2023-01-14T12:56:40+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2019\/12\/AR0300126006.jpg","width":775,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/justica-no-coracao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"Justi\u00e7a no Cora\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/en\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/comments?post=4385"}],"version-history":[{"count":1,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4385\/revisions"}],"predecessor-version":[{"id":4386,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4385\/revisions\/4386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media\/3808"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media?parent=4385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories?post=4385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/tags?post=4385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}