{"id":4679,"date":"2023-09-17T00:00:23","date_gmt":"2023-09-16T22:00:23","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/en\/?p=4679"},"modified":"2023-09-23T12:52:11","modified_gmt":"2023-09-23T10:52:11","slug":"na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/","title":{"rendered":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os  Direitos Humanos"},"content":{"rendered":"<p>(&#8230;) A mis\u00e9ria, a extrema pobreza, nos tempos que correm, \u00e9 de tal modo gritante que se tornou\u00a0 inevit\u00e1vel que, a um dado momento da hist\u00f3ria, passasse a ser necess\u00e1rio lan\u00e7ar uma iniciativa, por assim dizer, universal de maneira a manifestar-se como um memorial em honra das v\u00edtimas da grande pobreza atrav\u00e9s\u00a0 do mundo.<\/p>\n<p>Com efeito, os que vivem na mis\u00e9ria ensinaram-nos que o maior perigo que podem correr seria o de criar uma distin\u00e7\u00e3o, uma separa\u00e7\u00e3o entre as liberdades civis e pol\u00edticas, por um lado, e os direitos econ\u00f3micos, sociais e culturais por outro lado. \u00c9 porque n\u00f3s fizemos essa distin\u00e7\u00e3o que a grande pobreza acabou por vir \u00e0 superf\u00edcie nos \u00faltimos anos nos nossos pa\u00edses ricos. A grande pobreza j\u00e1 existia, mas acabou por vir \u00e0 superf\u00edcie, precisamente porque n\u00f3s est\u00e1vamos muito preocupados e obstinados sobre os direitos civis e pol\u00edticos, tendo esquecido, vezes sem conta, os direitos econ\u00f3micos e sociais. Sendo assim, acab\u00e1mos por n\u00e3o tomar as disposi\u00e7\u00f5es necess\u00e1rias para eliminar a grande pobreza, at\u00e9 porque j\u00e1 t\u00ednhamos perdido a consci\u00eancia de que ela existia. Com efeito, as nossas preocupa\u00e7\u00f5es e os nossos combates, de uma certa maneira, eram de outra ordem.<\/p>\n<p>Esquecemos que um desempregado de longa dura\u00e7\u00e3o rapidamente passa a ser um assistido. Por que raz\u00e3o passa a ser um assistido? Porque deixou de ser um benefici\u00e1rio social, porque deixou de fazer parte de um sindicato, de um partido pol\u00edtico, porque deixou de ser consultado e, sendo assim, deixou de ser livre. Passou a ser um homem dependente dos que o ajudam e que\u00a0 pouco ou nada conta para ningu\u00e9m. Foi assim que acab\u00e1mos por descobrir que este homem j\u00e1 n\u00e3o \u00e9 um homem livre e participante; que aquele que \u00e9 despejado do seu apartamento, passando a vaguear sem destino certo, acaba por perder o direito a um cart\u00e3o de eleitor, pois deixou de ser um cidad\u00e3o. Sem trabalho este homem n\u00e3o faz parte de nenhum sindicato, de nenhum partido pol\u00edtico; sem alojamento este homem, esta fam\u00edlia pobre que encontramos na rua j\u00e1 n\u00e3o vivem como cidad\u00e3os, j\u00e1 n\u00e3o t\u00eam o direito de votar.<\/p>\n<p>Tamb\u00e9m fic\u00e1mos a saber que estes homens, estas fam\u00edlias sem domic\u00edlio reconhecido n\u00e3o podem participar em nenhuma associa\u00e7\u00e3o que tenha por objetivo a defesa dos arrendat\u00e1rios. Coisa semelhante pode acontecer a uma pessoa em situa\u00e7\u00e3o de grande pobreza que se encontre atormentada pela doen\u00e7a, visto que deve evitar a ida a um hospital, porque, muito provavelmente,\u00a0 a entrada lhe ser\u00e1 recusada pelo pr\u00f3prio hospital.<\/p>\n<p>Assim, a pouco e pouco, nos vamos dando conta de que sem sa\u00fade, sem dinheiro e com o esp\u00edrito obcecado pelos problemas de subsist\u00eancia pessoal ou familiar, as fam\u00edlias em grande pobreza, homens e mulheres em extema pobreza acabam por se encontrar na impossibilidade de terem ruma vida associativa. Os seus filhos sair\u00e3o da escola sem dominarem nem a leitura, nem a escrita; o que acaba por conden\u00e1-los a n\u00e3o terem um trabalho amanh\u00e3. Por conseguinte, estar\u00e3o condenados, n\u00e3o s\u00f3, a n\u00e3o terem uma vida de fam\u00edlia, mas tamb\u00e9m a n\u00e3o terem uma vida profissional capaz, est\u00e1vel, a n\u00e3o poderem ter ( e talvez isto seja o pior ) uma vida sindical e pol\u00edtica digna que lhes permitiria serem capazes, como \u00e9 pr\u00f3prio de todo e qualquer homem, de se exprimirem, de se sentirem parte integrante do desenvolvimento do pa\u00eds em que vivem.<\/p>\n<p>Nisto consiste o grande progresso que a opini\u00e3o p\u00fablica fez, gra\u00e7as aos mais pobres: a indivisibilidade dos Direitos Humanos <span id='easy-footnote-1-4679' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#easy-footnote-bottom-1-4679' title='A este prop\u00f3sito aconselhamos a leitura do pequeno livro &lt;a href=&quot;https:\/\/www.joseph-wresinski.org\/en\/os-mais-pobres-reveladores-da\/&quot;&gt;&lt;strong&gt;&amp;#8220;Os mais pobres, reveladores da indivisibilidade dos Direitos Humanos&amp;#8221; &lt;\/strong&gt;&lt;\/a&gt;tamb\u00e9m traduzido em portug\u00eas.'><sup>1<\/sup><\/a><\/span> \u00e9 cada vez menos contestada, passando a ser cada vez mais reconhecida.<\/p>\n<p>Eis aqui a raz\u00e3o pela qual a manifesta\u00e7\u00e3o do dia 17 de outubro <span id='easy-footnote-2-4679' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#easy-footnote-bottom-2-4679' title='No dia 17 de outubro de 1987 realizou-se em Paris, no Terreiro dos Direitos Humanos uma grande manifesta\u00e7\u00e3o cujo sentido se encontra resumido na seguinte frase :&lt;strong&gt;&amp;#8220;Onde os homens est\u00e3o condenados a viver na mis\u00e9ria, a\u00ed os Direitos humanos s\u00e3o violados. Unir-se para os fazer respeitar \u00e9 um dever sagrado.&amp;#8221; &lt;\/strong&gt;Em 1992 as Na\u00e7\u00f5es Unidas proclamaram o dia 17 de outubro como Jornada mundial para a erradica\u00e7\u00e3o da pobreza'><sup>2<\/sup><\/a><\/span> se far\u00e1: \u00e9 muito importante assinalar o passo em frente que se foi dando na maneira de pensar os Direitos Humanos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(&#8230;) A mis\u00e9ria, a extrema pobreza, nos tempos que correm, \u00e9 de tal modo gritante que se tornou\u00a0 inevit\u00e1vel que, (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/\">Read more <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,159,59],"tags":[],"class_list":["post-4679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-other-languages","category-portugues"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN\" \/>\n<meta property=\"og:description\" content=\"(&#8230;) A mis\u00e9ria, a extrema pobreza, nos tempos que correm, \u00e9 de tal modo gritante que se tornou\u00a0 inevit\u00e1vel que, (...) Read more &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-16T22:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-23T10:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"1178\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos\",\"datePublished\":\"2023-09-16T22:00:23+00:00\",\"dateModified\":\"2023-09-23T10:52:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/\"},\"wordCount\":804,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/PJW_SEL20.jpg\",\"articleSection\":[\"News\",\"Other languages\",\"PORTUGU\u00caS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/\",\"name\":\"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/PJW_SEL20.jpg\",\"datePublished\":\"2023-09-16T22:00:23+00:00\",\"dateModified\":\"2023-09-23T10:52:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/PJW_SEL20.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/PJW_SEL20.jpg\",\"width\":848,\"height\":1178},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/","og_locale":"en_US","og_type":"article","og_title":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN","og_description":"(&#8230;) A mis\u00e9ria, a extrema pobreza, nos tempos que correm, \u00e9 de tal modo gritante que se tornou\u00a0 inevit\u00e1vel que, (...) Read more &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/","og_site_name":"Joseph Wresinski EN","article_published_time":"2023-09-16T22:00:23+00:00","article_modified_time":"2023-09-23T10:52:11+00:00","og_image":[{"width":848,"height":1178,"url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean Tonglet","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos","datePublished":"2023-09-16T22:00:23+00:00","dateModified":"2023-09-23T10:52:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/"},"wordCount":804,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg","articleSection":["News","Other languages","PORTUGU\u00caS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/","url":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/","name":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg","datePublished":"2023-09-16T22:00:23+00:00","dateModified":"2023-09-23T10:52:11+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2023\/09\/PJW_SEL20.jpg","width":848,"height":1178},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/na-origem-do-dia-17-de-outubro-assinalar-um-passo-em-frente-na-maneira-de-pensar-os-direitos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"Na origem do dia 17 de outubro: assinalar um passo em frente na maneira de pensar os Direitos Humanos"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/en\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/comments?post=4679"}],"version-history":[{"count":3,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4679\/revisions"}],"predecessor-version":[{"id":4682,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/4679\/revisions\/4682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media\/4656"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media?parent=4679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories?post=4679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/tags?post=4679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}