{"id":5212,"date":"2025-12-19T12:00:57","date_gmt":"2025-12-19T11:00:57","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/en\/?p=5212"},"modified":"2025-12-22T13:36:27","modified_gmt":"2025-12-22T12:36:27","slug":"az-ido-surget-2","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/","title":{"rendered":"Az id\u0151 s\u00fcrget\u2026"},"content":{"rendered":"<p style=\"text-align: center\"><strong>\u00a0<\/strong>Az id\u0151 s\u00fcrget,<br \/>\nideje meg\u00e9rteni,<br \/>\nhogy nincs \u00fcnnep,<br \/>\nha az nem mindenki\u00e9.<\/p>\n<p style=\"text-align: center\">Ideje akarni,<br \/>\nhogy az \u00fcnnep \u00f6sszegy\u0171jts\u00f6n mindny\u00e1junkat.<\/p>\n<p style=\"text-align: center\">Hogy kar\u00e1csony \u00e9jjel\u00e9n v\u00e9gre visszakapcsolj\u00e1k a villanyt,<br \/>\n\u00e9s hogy legal\u00e1bb egyszer elf\u00fajhassuk a gyerty\u00e1t.<\/p>\n<p style=\"text-align: center\">Hogy a kilakoltat\u00e1s r\u00e9me t\u00f6bb\u00e9 ne nehezedj\u00e9k r\u00e1nk,<br \/>\nmert az \u00f6sszes lakb\u00e9rh\u00e1tral\u00e9kot kifizett\u00fck.<\/p>\n<p style=\"text-align: center\">Ideje, hogy v\u00e9gre ne kelljen \u00fajra att\u00f3l rettegni,<br \/>\nhogy visszat\u00e9r a\u00a0 h\u00f3v\u00e9gi napok k\u00ednz\u00f3 \u00e9hez\u00e9se.<\/p>\n<p style=\"text-align: center\">Ideje, hogy t\u00f6bb\u00e9 ne lehessen olyan hajl\u00e9k, melyben,<br \/>\nmint hajdan, nem lobog t\u0171z.<\/p>\n<p style=\"text-align: center\">S vajon annak is elj\u00f6n-e az ideje, hogy aki munka n\u00e9lk\u00fcl maradt, ne maradjon seg\u00edts\u00e9g n\u00e9lk\u00fcl is,<br \/>\nhogy a gyerekeket ne ruhaadom\u00e1nyokb\u00f3l \u00f6lt\u00f6ztess\u00e9k,<br \/>\nhogy a szeg\u00e9nyeknek ne kelljen sz\u00e9gyenszemre nyesed\u00e9ket koldulniuk<br \/>\npiacz\u00e1r\u00e1skor, mert csak azzal d\u00fas\u00edthatj\u00e1k krumplivacsor\u00e1jukat?<\/p>\n<p style=\"text-align: center\">Az id\u0151 s\u00fcrget\u2026<br \/>\nElj\u00f6tt-e az id\u0151, amikor a szeg\u00e9nyeknek t\u00f6bb\u00e9 nem kell f\u00e9lni\u00fck,<br \/>\ns v\u00e9gre meg\u00fclhetj\u00fck az \u00fcnnepet?<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Az id\u0151 s\u00fcrget, ideje meg\u00e9rteni, hogy nincs \u00fcnnep, ha az nem mindenki\u00e9. Ideje akarni, hogy az \u00fcnnep \u00f6sszegy\u0171jts\u00f6n mindny\u00e1junkat. Hogy (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/\">Read more <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[184,159],"tags":[],"class_list":["post-5212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magyar","category-other-languages"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN\" \/>\n<meta property=\"og:description\" content=\"\u00a0Az id\u0151 s\u00fcrget, ideje meg\u00e9rteni, hogy nincs \u00fcnnep, ha az nem mindenki\u00e9. Ideje akarni, hogy az \u00fcnnep \u00f6sszegy\u0171jts\u00f6n mindny\u00e1junkat. Hogy (...) Read more &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski EN\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T11:00:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T12:36:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"989\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Az id\u0151 s\u00fcrget\u2026\",\"datePublished\":\"2025-12-19T11:00:57+00:00\",\"dateModified\":\"2025-12-22T12:36:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/\"},\"wordCount\":194,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/262522484_4950419784976643_2546760390636815534_n.jpg\",\"articleSection\":[\"MAGYAR\",\"Other languages\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/\",\"name\":\"Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/262522484_4950419784976643_2546760390636815534_n.jpg\",\"datePublished\":\"2025-12-19T11:00:57+00:00\",\"dateModified\":\"2025-12-22T12:36:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/262522484_4950419784976643_2546760390636815534_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/12\\\/262522484_4950419784976643_2546760390636815534_n.jpg\",\"width\":780,\"height\":989},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/az-ido-surget-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Az id\u0151 s\u00fcrget\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/\",\"name\":\"Joseph Wresinski EN\",\"description\":\"A website coordinated by the Joseph Wresinski Centre\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/en\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/","og_locale":"en_US","og_type":"article","og_title":"Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN","og_description":"\u00a0Az id\u0151 s\u00fcrget, ideje meg\u00e9rteni, hogy nincs \u00fcnnep, ha az nem mindenki\u00e9. Ideje akarni, hogy az \u00fcnnep \u00f6sszegy\u0171jts\u00f6n mindny\u00e1junkat. Hogy (...) Read more &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/","og_site_name":"Joseph Wresinski EN","article_published_time":"2025-12-19T11:00:57+00:00","article_modified_time":"2025-12-22T12:36:27+00:00","og_image":[{"width":780,"height":989,"url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean Tonglet","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Az id\u0151 s\u00fcrget\u2026","datePublished":"2025-12-19T11:00:57+00:00","dateModified":"2025-12-22T12:36:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/"},"wordCount":194,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg","articleSection":["MAGYAR","Other languages"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/","url":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/","name":"Az id\u0151 s\u00fcrget\u2026 - Joseph Wresinski EN","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg","datePublished":"2025-12-19T11:00:57+00:00","dateModified":"2025-12-22T12:36:27+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/en\/wp-content\/uploads\/sites\/3\/2021\/12\/262522484_4950419784976643_2546760390636815534_n.jpg","width":780,"height":989},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/en\/az-ido-surget-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/en\/"},{"@type":"ListItem","position":2,"name":"Az id\u0151 s\u00fcrget\u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/en\/#website","url":"https:\/\/www.joseph-wresinski.org\/en\/","name":"Joseph Wresinski EN","description":"A website coordinated by the Joseph Wresinski Centre","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/en\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/en\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/5212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/comments?post=5212"}],"version-history":[{"count":1,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/5212\/revisions"}],"predecessor-version":[{"id":5213,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/posts\/5212\/revisions\/5213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media\/3986"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/media?parent=5212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/categories?post=5212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/en\/wp-json\/wp\/v2\/tags?post=5212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}