{"id":1226,"date":"2018-04-04T18:47:36","date_gmt":"2018-04-04T16:47:36","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/es\/?p=1226"},"modified":"2020-10-13T14:35:45","modified_gmt":"2020-10-13T12:35:45","slug":"evento-etica-en-la-investigacion-sobre-la-pobreza","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/","title":{"rendered":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza"},"content":{"rendered":"<p><strong>Martes, 12 de abril de 2018<\/strong><\/p>\n<p><strong>10:00 am Nueva York | 3:00 pm Londres | 5:00 pm Cape Town<\/strong><\/p>\n<p><strong>Se requiere <a href=\"https:\/\/register.gotowebinar.com\/register\/5192191163862166787\" target=\"_blank\" rel=\"noopener noreferrer\">inscripci\u00f3n previa<\/a>.<br \/>\n<\/strong><\/p>\n<h1><strong>\u00c9tica en la investigaci\u00f3n sobre la pobreza<\/strong><\/h1>\n<p>Este evento, que se desarrollar\u00e1 en ingl\u00e9s, es el primero de un total de tres seminarios <em>a distancia<\/em> en torno al tema: <em>Ante la miseria, repensar el mundo; con <a href=\"http:\/\/www.atd-cuartomundo.org\/quienes-somos\/nuestra-historia\/joseph-wresinski\/\" target=\"_blank\" rel=\"noopener noreferrer\">Joseph Wresinski<\/a>.<\/em><\/p>\n<p><em>\u00abNo hemos reflexionado bastante en cuanto a que, en el conocimiento global sobre la pobreza y la exclusi\u00f3n, que debe a un tiempo informar, explicar y movilizar, la investigaci\u00f3n cient\u00edfica debe reconocerse como un componente entre varios. Es el componente informativo, un conocimiento \u00abinerte\u00bb, si se puede decir as\u00ed, que seguir\u00e1 siendo \u00abinerte\u00bb mientras no vaya acompa\u00f1ado de otros dos elementos del conocimiento:<\/em><\/p>\n<ul>\n<li><em>\u00a0el conocimiento que poseen las personas en situaci\u00f3n de pobreza, los excluidos, que viven, desde dentro, a la vez la realidad de su condici\u00f3n de pobreza y la realidad del mundo que le impone dicha pobreza;<\/em><\/li>\n<li><em>\u00a0y el conocimiento de quienes act\u00faan en zonas de extrema pobreza y exclusi\u00f3n, entre las v\u00edctimas y con ellas\u00bb<\/em>.<\/li>\n<\/ul>\n<p>\u2013 <strong>Joseph Wresinski<\/strong> \u2013 <em>El pensamiento de los pobres en un conocimiento que conduce a la lucha<\/em>, Unesco, 1980<\/p>\n<p>Estas exigentes palabras de Joseph Wresinski entran directamente en materia: el desaf\u00edo fundamental es la construcci\u00f3n de un conocimiento que libere a las personas de la pobreza. En las investigaciones, con frecuencia, se solicita a las comunidades en situaci\u00f3n de exclusi\u00f3n para que acepten la realizaci\u00f3n de las mismas sobre sus comunidades; sin embargo, a pesar de que se les invita a aportar una informaci\u00f3n significativa, tanto su plena participaci\u00f3n como la obtenci\u00f3n de un beneficio directo en los procesos de investigaci\u00f3n constituye m\u00e1s bien una excepci\u00f3n a la regla. Una verdadera inclusi\u00f3n de las personas en situaci\u00f3n m\u00e1s grave de exclusi\u00f3n en los procesos de investigaci\u00f3n es una propuesta \u00e9tica que requiere reciprocidad entre quienes est\u00e1n directamente afectados por la pobreza y el personal investigador que busca aprender de estas personas y de sus comunidades.<\/p>\n<p>En base a varios ejemplos proporcionados por <a href=\"http:\/\/www.atd-cuartomundo.org\/quienes-somos\/nuestros-miembros\/militantes-cuarto-mundo\/\" target=\"_blank\" rel=\"noopener noreferrer\">militantes Cuarto Mundo<\/a> y acad\u00e9micos de Sud\u00e1frica, Francia y de los EE.UU. este seminario <em>a distancia<\/em> explorar\u00e1 los aspectos \u00e9ticos de las investigaciones sobre pobreza, as\u00ed como enfoques metodol\u00f3gicos y pr\u00e1cticos, por parte de las organizaciones sin \u00e1nimo de lucro e instituciones acad\u00e9micas, a la hora de producir un conocimiento con la participaci\u00f3n de personas en situaci\u00f3n de pobreza. Analizaremos los dilemas \u00e9ticos comunes a muchas investigaciones en el \u00e1mbito de las ciencias sociales y propondremos v\u00edas para una significativa inclusi\u00f3n, participaci\u00f3n y empoderamiento de las personas directamente afectadas por la pobreza durante el proceso de elaboraci\u00f3n del conocimiento.<\/p>\n<h1>Ponentes:<\/h1>\n<p><strong>Stacy Randell-Shaheen<\/strong> (EE.UU) es Directora del <a href=\"https:\/\/www.northshore.edu\/adult_learning\/\" target=\"_blank\" rel=\"noopener noreferrer\">Centro de Educaci\u00f3n de Adultos en el North Shore Community College<\/a> en Danvers, MA, donde contribuye a la formaci\u00f3n de estudiantes de todas las edades, que no han terminado la educaci\u00f3n secundaria, a finalizarla y obtener los t\u00edtulos necesarios para acceder a estudios universitarios u otros procesos de formaci\u00f3n de grado superior.<\/p>\n<p><strong>Bonita Bennett<\/strong> (Sud\u00e1frica) es directora del <a href=\"http:\/\/www.districtsix.co.za\/\" target=\"_blank\" rel=\"noopener noreferrer\">District Six Museum<\/a> desde 2008, durante los tres a\u00f1os previos trabaj\u00f3 en la direcci\u00f3n de archivos y en el trabajo de memoria de las v\u00edctimas de realojo forzoso del Distrito Seis de Cape Town, y de manera m\u00e1s general, con personas y comunidades v\u00edctimas de expulsiones forzosas.<\/p>\n<p><strong>Donna Haig Friedman<\/strong> (EE.UU.) durante cerca de 18 a\u00f1os fue directora del <a href=\"https:\/\/www.umb.edu\/csp\" target=\"_blank\" rel=\"noopener noreferrer\">UMass Boston\u2019s Center for Social Policy<\/a> [Centro de Pol\u00edticas Sociales de la Universidad de Massachussets, Boston. Como responsable, Donna dirigi\u00f3 el equipo del Centro de Pol\u00edticas Sociales en sus trabajos de investigaci\u00f3n y evaluaci\u00f3n en Massachusetts y en los Estados Unidos. La mayor\u00eda de trabajos se centraron en la evaluaci\u00f3n de las intervenciones y el progreso de las pol\u00edticas sociales dirigidas a prevenir la falta de vivienda.<\/p>\n<p><strong>Amelia Mallona<\/strong> (EE.UU.) es profesora de Educaci\u00f3n en el <a href=\"http:\/\/www.merrimack.edu\/index.php\" target=\"_blank\" rel=\"noopener noreferrer\">Merrimack College\u00a0de Massachusetts<\/a>. Su labor como docente incluye cursos sobre el desarrollo a lo largo de toda la vida y sobre contextos socio hist\u00f3ricos y culturales donde tiene lugar ese desarrollo, abordando cuestiones de diversidad, justicia social y \u00e9tica en entornos educativos.<\/p>\n<p><strong>Bruno Tardieu<\/strong> (Francia) es director del <a href=\"http:\/\/www.joseph-wresinski.org\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">Centro Internacional Joseph Wresinski<\/a> , para la investigaci\u00f3n y la historia, en Baillet, Francia. A iniciativa del Movimiento Internacional ATD Cuarto Mundo, este centro trabaja en tareas de recopilaci\u00f3n y archivo de la historia de resistencia de las personas y comunidades que viven en situaci\u00f3n de extrema pobreza, as\u00ed como en iniciativas de investigaci\u00f3n que permitan entender como superar la extrema pobreza.<\/p>\n<p><strong>Este evento, organizado en colaboraci\u00f3n con el Merrimack College, tiene su origen en una mesa redonda realizada en junio de 2017, en el Centro Cultural Internacional de Cerisy la Salle, Francia, en el<a href=\"http:\/\/www.atd-cuartomundo.org\/coloquio-internacional-cerisy-repensar-la-pobreza\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Coloquio Internacional, Ante la miseria, repensar lo humano; con Joseph Wresinski<\/a> . Este acontecimiento hist\u00f3rico reuni\u00f3 a cerca de 80 acad\u00e9micos, profesionales activos en la lucha contra la extrema pobreza y personas en situaci\u00f3n de pobreza de 15 pa\u00edses para debatir sobre c\u00f3mo la extrema pobreza desaf\u00eda nuestro modo de pensar y entender.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martes, 12 de abril de 2018 10:00 am Nueva York | 3:00 pm Londres | 5:00 pm Cape Town Se (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":1227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,76,105],"tags":[],"class_list":["post-1226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidades","category-estudios","category-otros-simposios-y-seminarios"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"Martes, 12 de abril de 2018 10:00 am Nueva York | 3:00 pm Londres | 5:00 pm Cape Town Se (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-04T16:47:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T12:35:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"708\" \/>\n\t<meta property=\"og:image:height\" content=\"449\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jaime\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jaime\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/\"},\"author\":{\"name\":\"jaime\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/6c1313273b2a28138fe42fe4e7e7e319\"},\"headline\":\"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza\",\"datePublished\":\"2018-04-04T16:47:36+00:00\",\"dateModified\":\"2020-10-13T12:35:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/\"},\"wordCount\":906,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2018\\\/04\\\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg\",\"articleSection\":[\"Actualidades\",\"Estudios y seminarios\",\"Otros simposios y seminarios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/\",\"name\":\"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2018\\\/04\\\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg\",\"datePublished\":\"2018-04-04T16:47:36+00:00\",\"dateModified\":\"2020-10-13T12:35:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/6c1313273b2a28138fe42fe4e7e7e319\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2018\\\/04\\\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2018\\\/04\\\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg\",\"width\":708,\"height\":449},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/evento-etica-en-la-investigacion-sobre-la-pobreza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/6c1313273b2a28138fe42fe4e7e7e319\",\"name\":\"jaime\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g\",\"caption\":\"jaime\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/jaime\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/","og_locale":"es_ES","og_type":"article","og_title":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES","og_description":"Martes, 12 de abril de 2018 10:00 am Nueva York | 3:00 pm Londres | 5:00 pm Cape Town Se (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2018-04-04T16:47:36+00:00","article_modified_time":"2020-10-13T12:35:45+00:00","og_image":[{"width":708,"height":449,"url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg","type":"image\/jpeg"}],"author":"jaime","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jaime","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/"},"author":{"name":"jaime","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/6c1313273b2a28138fe42fe4e7e7e319"},"headline":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza","datePublished":"2018-04-04T16:47:36+00:00","dateModified":"2020-10-13T12:35:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/"},"wordCount":906,"commentCount":2,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg","articleSection":["Actualidades","Estudios y seminarios","Otros simposios y seminarios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/","url":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/","name":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg","datePublished":"2018-04-04T16:47:36+00:00","dateModified":"2020-10-13T12:35:45+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/6c1313273b2a28138fe42fe4e7e7e319"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2018\/04\/2018-04-04-PEPs-ArtSi-EventWebinairEtics-Photo-mosaique-cerisy-B.jpg","width":708,"height":449},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/evento-etica-en-la-investigacion-sobre-la-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Evento: \u00c9tica en la investigaci\u00f3n sobre la pobreza"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/6c1313273b2a28138fe42fe4e7e7e319","name":"jaime","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94e8865d14248786fbf63f441c5f4e74b36113a44b13412e379a210446cfec5b?s=96&d=mm&r=g","caption":"jaime"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/jaime\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/1226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=1226"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/1226\/revisions"}],"predecessor-version":[{"id":1789,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/1226\/revisions\/1789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media\/1227"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=1226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=1226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=1226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}