{"id":2864,"date":"2023-11-20T00:00:09","date_gmt":"2023-11-19T23:00:09","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/es\/?p=2864"},"modified":"2023-11-19T13:33:49","modified_gmt":"2023-11-19T12:33:49","slug":"todo-gesto-de-amor-funda-la-esperanza-de-los-pobres","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/","title":{"rendered":"Todo gesto de amor funda la esperanza de los pobres"},"content":{"rendered":"<p>Los ni\u00f1os est\u00e1n en torno a Georgette,<br \/>\nse aprietan contra ella,<br \/>\nson como violetas que se esconden en el musgo.<\/p>\n<p>Once cr\u00edos.<br \/>\nSantiago dice: \u201cTengo fr\u00edo\u201d, y Claudine dice: \u201cEs feo\u201d.<br \/>\nLo que es feo es la destrucci\u00f3n del asentamiento.<br \/>\nChabola tras chabola.<br \/>\nDesde el fondo de su coraz\u00f3n<br \/>\nlos ni\u00f1os detestan el asentamiento.<br \/>\nAll\u00ed siempre han tenido fr\u00edo, siempre estaba sucio.<br \/>\nIncluso las flores,<br \/>\nplantadas a lo largo de las paredes, parec\u00edan feas.<br \/>\nPero hoy es todav\u00eda peor.<br \/>\nCada chabola destruida deja un agujero horrible,<br \/>\ncada chabola destruida se queda,<br \/>\nplantada sobre ella misma, formando una monta\u00f1a<br \/>\nde escombros, de maderas podridas,<br \/>\nde chapas que sobresalen por aqu\u00ed, por all\u00e1\u2026<\/p>\n<p>\u00a1Los ni\u00f1os tienen miedo de este universo!<br \/>\nNo es sorprendente que estos ni\u00f1os<br \/>\ndetesten su asentamiento<br \/>\nPor suerte, est\u00e1 pap\u00e1, mam\u00e1, los hermanos y hermanas.<br \/>\nSin embargo, no siempre les quieren.<br \/>\nPor suerte, no pasa lo mismo con los animales,<br \/>\nlos perros, los gatos, aunque est\u00e9n delgados.<br \/>\nPor suerte, est\u00e1 Georgette.<br \/>\nPorque en este ins\u00f3lito universo, en este desorden,<br \/>\nGeorgette contin\u00faa con su jard\u00edn de infancia,<br \/>\nincluso, \u00a1ha querido hacer m\u00e1s que antes!<br \/>\nCada ma\u00f1ana, va de chabola en chabola,<br \/>\nentre los desperdicios que se apilan<br \/>\ny los escombros que se amontonan<br \/>\ntomando formas definitivas.<br \/>\nVa a buscar a cada ni\u00f1o a su casa.<br \/>\nEspera a que est\u00e9n listos,<br \/>\nayuda a mam\u00e1 a vestirles si hace falta.<br \/>\nConsuela a la peque\u00f1a Rosita<br \/>\nque tiene miedo de salir de su casa,<br \/>\nporque le asusta tanto desorden.<br \/>\nAdem\u00e1s, est\u00e1 tambi\u00e9n el peligro para Rosita:<br \/>\na su hermano peque\u00f1o<br \/>\nse le ha ca\u00eddo una plancha de madera en el pie<br \/>\nest\u00e1 tumbado all\u00ed, en la cama.<\/p>\n<p>Para Georgette hace falta que cada d\u00eda<br \/>\nlos once ni\u00f1os est\u00e9n ah\u00ed.<br \/>\nNo quiere perder a ninguno hoy,<br \/>\npero, sobre todo, no quiere que ma\u00f1ana<br \/>\nsean miserables como lo son hoy.<br \/>\nMuchas veces Georgette dice:<br \/>\n\u201cNo hay que dejar que por culpa de este desorden<br \/>\nsu inteligencia se pare.<br \/>\nTienen que seguir vi\u00e9ndose juntos<br \/>\npara que se sientan seguros.<br \/>\nEl jard\u00edn de infancia tiene que ser muy bonito,<br \/>\nm\u00e1s bonito que antes y que sea muy c\u00e1lido.\u201d<br \/>\nPero no es f\u00e1cil.<br \/>\nEstos \u00faltimos d\u00edas, han destruido la chabola<br \/>\nque estaba al lado del jard\u00edn de infancia.<br \/>\nLos paneles de escayola se han agrietado.<br \/>\n\u201cTienen que tener una buena merienda,<br \/>\nmejor que antes, m\u00e1s abundante. No hay que dejar<br \/>\nque la destrucci\u00f3n de su universo les traumatice\u201d, dice.<\/p>\n<p>Y la ven ir,<br \/>\na trav\u00e9s del asentamiento en fase de demolici\u00f3n.<br \/>\nUna demolici\u00f3n que dura desde hace varios meses.<br \/>\nRodeada de sus peque\u00f1os,<br \/>\nparece muy grande en medio de ellos.<br \/>\nSe pasea con su peque\u00f1o mundo por las calles vecinas<br \/>\nah\u00ed donde todo se ha quedado como antes,<br \/>\ndonde los \u00e1rboles crecen rectos y felices,<br \/>\ndonde las flores siempre sonr\u00eden.<\/p>\n<p>Al final de a\u00f1o, Georgette ha ganado la partida<br \/>\na pesar de las excavadoras,<br \/>\na pesar de las demoliciones,<br \/>\na pesar del miedo.<br \/>\nLas pruebas demostraban que ning\u00fan ni\u00f1o<br \/>\nhab\u00eda suspendido la evoluci\u00f3n de su inteligencia,<br \/>\ny aquellos que ten\u00edan la edad<br \/>\npudieron entrar en maternal.<br \/>\n\u00bfSe acordar\u00e1n de Georgette, esos ni\u00f1os?<br \/>\n\u00bfSe acordar\u00e1n de su imaginaci\u00f3n?<br \/>\nDe la ternura, del coraje para mantenerlos as\u00ed,<br \/>\ncogidos de los brazos, por encima del desastre.<br \/>\nA lo mejor se olvidar\u00e1n de Georgette,<br \/>\npero todo ese amor, no se perder\u00e1.<br \/>\nSer\u00e1n hombres y mujeres ma\u00f1ana,<br \/>\ny si sus caminos se vuelven a cruzar, a lo mejor dir\u00e1n<br \/>\n\u201cHe aqu\u00ed a la persona que nos hizo querer al colegio.\u201d<br \/>\nTodo esto, porque alguien fue,<br \/>\na pesar de su horror, de su miedo,<br \/>\nhasta el final de su camino para amar todav\u00eda m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los ni\u00f1os est\u00e1n en torno a Georgette, se aprietan contra ella, son como violetas que se esconden en el musgo. (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":2863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,68,63],"tags":[],"class_list":["post-2864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidades","category-extractos-de-libros","category-recopilacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"Los ni\u00f1os est\u00e1n en torno a Georgette, se aprietan contra ella, son como violetas que se esconden en el musgo. (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-19T23:00:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Todo gesto de amor funda la esperanza de los pobres\",\"datePublished\":\"2023-11-19T23:00:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/\"},\"wordCount\":671,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/11\\\/Jurg_Kreienbuhl_La_zone_1972.jpeg\",\"articleSection\":[\"Actualidades\",\"Extractos de libros\",\"Textos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/\",\"name\":\"Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/11\\\/Jurg_Kreienbuhl_La_zone_1972.jpeg\",\"datePublished\":\"2023-11-19T23:00:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/11\\\/Jurg_Kreienbuhl_La_zone_1972.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2023\\\/11\\\/Jurg_Kreienbuhl_La_zone_1972.jpeg\",\"width\":768,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo gesto de amor funda la esperanza de los pobres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/","og_locale":"es_ES","og_type":"article","og_title":"Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES","og_description":"Los ni\u00f1os est\u00e1n en torno a Georgette, se aprietan contra ella, son como violetas que se esconden en el musgo. (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2023-11-19T23:00:09+00:00","og_image":[{"width":768,"height":500,"url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jean Tonglet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Todo gesto de amor funda la esperanza de los pobres","datePublished":"2023-11-19T23:00:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/"},"wordCount":671,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg","articleSection":["Actualidades","Extractos de libros","Textos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/","url":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/","name":"Todo gesto de amor funda la esperanza de los pobres - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg","datePublished":"2023-11-19T23:00:09+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg","contentUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2023\/11\/Jurg_Kreienbuhl_La_zone_1972.jpeg","width":768,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/todo-gesto-de-amor-funda-la-esperanza-de-los-pobres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Todo gesto de amor funda la esperanza de los pobres"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/2864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=2864"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/2864\/revisions"}],"predecessor-version":[{"id":2868,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/2864\/revisions\/2868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media\/2863"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=2864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=2864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=2864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}