{"id":3093,"date":"2026-01-30T14:00:33","date_gmt":"2026-01-30T13:00:33","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/es\/?p=3093"},"modified":"2026-02-11T10:11:28","modified_gmt":"2026-02-11T09:11:28","slug":"los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/","title":{"rendered":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia."},"content":{"rendered":"<p>La condici\u00f3n de los m\u00e1s pobres <span id='easy-footnote-1-3093' class='easy-footnote-margin-adjust'><\/span><span class='easy-footnote'><a href='https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#easy-footnote-bottom-1-3093' title='El autor hace referencia a la \u201ccondici\u00f3n subproletaria\u201d, t\u00e9rmino que resulta m\u00e1s relevante ese el contexto original que en el actual. En todo el texto se ha traducido como \u201clos m\u00e1s pobres\u201d'><sup>1<\/sup><\/a><\/span> es una afronta a nuestros principios democr\u00e1ticos. Sin una base s\u00f3lida de respeto a las minor\u00edas no hay democracia. Las mayor\u00edas deben defender y asegurar que las minor\u00edas se puedan expresar; de lo contrario, la democracia se vuelve una mera usurpaci\u00f3n de poder por parte de los fuertes.<\/p>\n<p>Tenemos la responsabilidad de garantizar que nuestras democracias proporcionen a las minor\u00edas los medios necesarios para poder actuar a t\u00edtulo propio y participar en los mismos t\u00e9rminos que los dem\u00e1s.<\/p>\n<p>No obstante, nuestras democracias, que se jactan de estar fundadas sobre la igualdad de oportunidades, son profundamente desiguales. Desde hace casi dos siglos, una parte de la sociedad ha tomado control de los poderes econ\u00f3micos, pol\u00edticos, sociales y religiosos. Sin importar el r\u00e9gimen en turno, este sector ha seguido protegiendo los privilegios obtenidos a lo largo de siglos.<\/p>\n<p>Quienes nos revelan la realidad profunda de nuestras sociedades son los m\u00e1s pobres: se les ha dejado despojados: despojados de todo medio de expresi\u00f3n y de toda posibilidad de llevar una vida digna. Se les ha reducido a seguir el juego de los dem\u00e1s \u2014de administraciones, grupos de caridad, iniciativas sociales\u2014. Se les ha convertido en objetos, no se les reconoce como sujetos conscientes con voz propia. Se les ha obligado a actuar, a fingir y a \u201cseguir la corriente\u201d para obtener alg\u00fan medio de subsistencia.<\/p>\n<p>A\u00fan as\u00ed, si nos acercamos a estas familias, no deja de sorprender la fuerza de su valor humano. Porque el ser humano no se deja aplastar ni diluir, el ser humano resiste.<\/p>\n<p>Como aquel hombre que conoc\u00ed en el este de Francia. Por motivos graves se hab\u00eda quedado sin empleo y ahora, en esa regi\u00f3n, no volver\u00eda a encontrar trabajo. He aqu\u00ed una familia en una situaci\u00f3n desesperada, dejada a su suerte, sin m\u00e1s recurso que la mendicidad y la piller\u00eda para poder criar a sus cuatro hijos, porque la sociedad \u2014y esa sociedad somos nosotros\u2014 no proporciona el m\u00ednimo soporte a sus miembros para simplemente poder sobrevivir.<\/p>\n<p>Y no obstante, este hombre es un trabajador. Lo conozco desde hace doce a\u00f1os. Encontraba trabajo, lo perd\u00eda y no descansaba hasta encontrar otro. Hace no mucho tiempo lo visit\u00e9, y al entrar a su casa, lo encontr\u00e9 recargado en la mesa de la cocina. Recobr\u00f3 la compostura, me recibi\u00f3 con dignidad, me cont\u00f3 de sus dificultades, sus aspiraciones y su gran deseo de trabajar.<\/p>\n<p>Esta es la experiencia de los m\u00e1s pobres: generaciones de trabajadores orillados a labores irregulares y provisionales. Porque se les juzga inferiores, se les da una formaci\u00f3n inferior. Y he aqu\u00ed, frente a m\u00ed, un descendiente de estas generaciones, un hombre de 35 a\u00f1os, sin oficio, que desde el otro lado de la mesa exclama con todo su ser: \u201cencu\u00e9ntreme trabajo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La condici\u00f3n de los m\u00e1s pobres es una afronta a nuestros principios democr\u00e1ticos. Sin una base s\u00f3lida de respeto a (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":3092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,79,63],"tags":[],"class_list":["post-3093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidades","category-articulos","category-recopilacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"La condici\u00f3n de los m\u00e1s pobres es una afronta a nuestros principios democr\u00e1ticos. Sin una base s\u00f3lida de respeto a (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T13:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T09:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"742\" \/>\n\t<meta property=\"og:image:height\" content=\"495\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia.\",\"datePublished\":\"2026-01-30T13:00:33+00:00\",\"dateModified\":\"2026-02-11T09:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/\"},\"wordCount\":544,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/01\\\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg\",\"articleSection\":[\"Actualidades\",\"Art\u00edculos\",\"Textos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/\",\"name\":\"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/01\\\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg\",\"datePublished\":\"2026-01-30T13:00:33+00:00\",\"dateModified\":\"2026-02-11T09:11:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/01\\\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2026\\\/01\\\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg\",\"width\":742,\"height\":495},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/","og_locale":"es_ES","og_type":"article","og_title":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES","og_description":"La condici\u00f3n de los m\u00e1s pobres es una afronta a nuestros principios democr\u00e1ticos. Sin una base s\u00f3lida de respeto a (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2026-01-30T13:00:33+00:00","article_modified_time":"2026-02-11T09:11:28+00:00","og_image":[{"width":742,"height":495,"url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jean Tonglet","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia.","datePublished":"2026-01-30T13:00:33+00:00","dateModified":"2026-02-11T09:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/"},"wordCount":544,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg","articleSection":["Actualidades","Art\u00edculos","Textos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/","url":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/","name":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia. - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg","datePublished":"2026-01-30T13:00:33+00:00","dateModified":"2026-02-11T09:11:28+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2026\/01\/2018-07-01-BO-ProyectoDimensionesPobrezaAchocalla-0018-Slide1.jpg","width":742,"height":495},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-mas-pobres-pueden-ser-el-fermento-de-una-verdadera-democracia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los m\u00e1s pobres pueden ser el fermento de una verdadera democracia."}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/3093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=3093"}],"version-history":[{"count":4,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/3093\/revisions"}],"predecessor-version":[{"id":3101,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/3093\/revisions\/3101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media\/3092"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=3093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=3093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=3093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}