{"id":785,"date":"2016-02-10T18:41:05","date_gmt":"2016-02-10T17:41:05","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/"},"modified":"2020-10-08T12:57:19","modified_gmt":"2020-10-08T10:57:19","slug":"te-tengo-miedo-senor","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/","title":{"rendered":"Te tengo miedo Se\u00f1or"},"content":{"rendered":"<p>Palabras para ma&ntilde;ana, Padre Joseph Wresinski, Ediciones Cuarto Mundo, Madrid, 1999.<\/p>\n<p>Te tengo miedo Se&ntilde;or<\/p>\n<p>Tengo miedo de atarme a Ti, de entregar mi suerte a tus manos,  porque me da miedo el sufrimiento, la injusticia y la soledad. Es por eso que no puedo decirte: &ldquo;Haz de m&iacute; Tu amor y mold&eacute;ame como T&uacute; quieras, como el esposo moldea a la esposa&rdquo;. Tengo miedo de ese lugar desconocido donde me puedes llevar y donde quedaremos solos T&uacute; y yo, Yo solo frente a Ti. All&iacute; donde T&uacute; voluntad sea quiz&aacute;s tan opuesta a la m&iacute;a que har&aacute; cambiar toda mi vida.<\/p>\n<p>Sin embargo Se&ntilde;or, s&eacute; que mi destino queda totalmente en Tus manos. S&eacute; que haga lo que haga te pertenece la &uacute;ltima palabra, que mi alma es Tuya porque me amas.<\/p>\n<p>Yo tambi&eacute;n te amo. Entonces, &iquest;qu&eacute; es lo que me da miedo? &iquest;De d&oacute;nde vienen mis reticencias y a veces mi rebeli&oacute;n? Ser&aacute; quiz&aacute;s porque me falta la Fe. S&iacute;, eso es Se&ntilde;or, no tengo bastante Fe. Sin embargo hay algo m&aacute;s&hellip; En estos tiempos T&uacute; quieres ser  el &uacute;ltimo de los &uacute;ltimos, el zarrapastroso, el humillado,  el desconocido de las chabolas miserables. Has querido ser de esos, esos hombres que me dan miedo.<\/p>\n<p>Como ya lo hicieron tantas veces, de d&iacute;a y de noche, T&uacute; tambi&eacute;n me llevar&aacute;s de renuncia en renuncia, cuestion&aacute;ndome cada vez, me expondr&aacute;s desnudo ante mis hermanos humillados, me entregar&aacute;s a sus manos, a su miseria, a su soledad.<\/p>\n<p>Es por eso que te tengo miedo, porque me dices desde lo m&aacute;s hondo de tus entra&ntilde;as: Estos ni&ntilde;os son mis hermanos,  estas mujeres son mi madre, y Yo, soy ese L&aacute;zaro que te repatea,  esa Mar&iacute;a Magdalena que te tienta, los ladrones que te roban y te agravian. Soy el leproso demacrado e ignorante que te espanta.<\/p>\n<p>Se&ntilde;or, por piedad, no me entregues atado de pies y manos a estos hermanos. No me entregues sin defensa a Tu amor. &iexcl;No! esto no, Se&ntilde;or, ten piedad, no lo permitas.<\/p>\n<p>Pero si T&uacute; lo exiges me dejar&eacute; hacer. A pesar de todo, te tengo miedo Se&ntilde;or.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palabras para ma&ntilde;ana, Padre Joseph Wresinski, Ediciones Cuarto Mundo, Madrid, 1999. Te tengo miedo Se&ntilde;or Tengo miedo de atarme a (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[64,68,63],"tags":[],"class_list":["post-785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escritos-spirituales","category-extractos-de-libros","category-recopilacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Te tengo miedo Se\u00f1or - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Te tengo miedo Se\u00f1or - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"Palabras para ma&ntilde;ana, Padre Joseph Wresinski, Ediciones Cuarto Mundo, Madrid, 1999. Te tengo miedo Se&ntilde;or Tengo miedo de atarme a (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-10T17:41:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T10:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"434\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Te tengo miedo Se\u00f1or\",\"datePublished\":\"2016-02-10T17:41:05+00:00\",\"dateModified\":\"2020-10-08T10:57:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/\"},\"wordCount\":432,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2020\\\/10\\\/49-434x400-1.jpg\",\"articleSection\":[\"Escritos spirituales\",\"Extractos de libros\",\"Textos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/\",\"name\":\"Te tengo miedo Se\u00f1or - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2020\\\/10\\\/49-434x400-1.jpg\",\"datePublished\":\"2016-02-10T17:41:05+00:00\",\"dateModified\":\"2020-10-08T10:57:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2020\\\/10\\\/49-434x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2020\\\/10\\\/49-434x400-1.jpg\",\"width\":434,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/te-tengo-miedo-senor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Te tengo miedo Se\u00f1or\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Te tengo miedo Se\u00f1or - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/","og_locale":"es_ES","og_type":"article","og_title":"Te tengo miedo Se\u00f1or - Joseph Wresinski ES","og_description":"Palabras para ma&ntilde;ana, Padre Joseph Wresinski, Ediciones Cuarto Mundo, Madrid, 1999. Te tengo miedo Se&ntilde;or Tengo miedo de atarme a (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2016-02-10T17:41:05+00:00","article_modified_time":"2020-10-08T10:57:19+00:00","og_image":[{"width":434,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webmestre","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Te tengo miedo Se\u00f1or","datePublished":"2016-02-10T17:41:05+00:00","dateModified":"2020-10-08T10:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/"},"wordCount":432,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg","articleSection":["Escritos spirituales","Extractos de libros","Textos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/","url":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/","name":"Te tengo miedo Se\u00f1or - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg","datePublished":"2016-02-10T17:41:05+00:00","dateModified":"2020-10-08T10:57:19+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2020\/10\/49-434x400-1.jpg","width":434,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/te-tengo-miedo-senor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Te tengo miedo Se\u00f1or"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=785"}],"version-history":[{"count":1,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/785\/revisions"}],"predecessor-version":[{"id":928,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/785\/revisions\/928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media\/1552"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}