{"id":892,"date":"2007-04-12T17:45:52","date_gmt":"2007-04-12T15:45:52","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/"},"modified":"2020-10-09T15:31:16","modified_gmt":"2020-10-09T13:31:16","slug":"los-tres-rechazos-del-movimiento","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/","title":{"rendered":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo"},"content":{"rendered":"<h2>Paris, 17 de noviembre de 1977<\/h2>\n<p>17 de Noviembre de 1977: reuni\u00f3n publica del Movimiento ATD Cuarto Mundo, en la Mutualidad en Par\u00eds. Durante esta reuni\u00f3n, el Padre Joseph Wresinski dirige la palabra a todos, familias del Cuarto Mundo, voluntarios y aliados. Lanza el desaf\u00edo de la lucha contra el analfabetismo y el acceso de todos a un trabajo.<\/p>\n<h3>documents<\/h3>\n<figure class=\"alignnone wp-caption\"><a href=\"\/wp-content\/uploads\/sites\/13\/2016\/09\/Los_3_Rechazos_del_Movimiento_ATD_Cuarto_Mundo.doc\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" style=\"height: 52px;width: 52px\" src=\"\/wp-content\/uploads\/sites\/13\/2016\/09\/doc-50de0.png\" alt=\"\" width=\"52\" height=\"52\" \/><\/a><\/figure>\n<figure class=\"alignnone wp-caption\"><a href=\"\/wp-content\/uploads\/sites\/13\/2016\/09\/Los_3_Rechazos_del_Movimiento_ATD_Cuarto_Mundo.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" style=\"height: 52px;width: 52px\" src=\"\/wp-content\/uploads\/sites\/13\/2016\/09\/pdf-d7486.png\" alt=\"\" width=\"52\" height=\"52\" \/><\/a><\/figure>\n<p>Los 3 Rechazos del Movimiento ATD Curto Mundo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris, 17 de noviembre de 1977 17 de Noviembre de 1977: reuni\u00f3n publica del Movimiento ATD Cuarto Mundo, en la (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69,63],"tags":[],"class_list":["post-892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-discursos","category-recopilacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"Paris, 17 de noviembre de 1977 17 de Noviembre de 1977: reuni\u00f3n publica del Movimiento ATD Cuarto Mundo, en la (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2007-04-12T15:45:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-09T13:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"565\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Los 3 Rechazos del Movimiento ATD Cuarto Mundo\",\"datePublished\":\"2007-04-12T15:45:52+00:00\",\"dateModified\":\"2020-10-09T13:31:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/\"},\"wordCount\":74,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2007\\\/04\\\/0903-002-09-02-1-565x400-1.jpg\",\"articleSection\":[\"Discursos\",\"Textos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/\",\"name\":\"Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2007\\\/04\\\/0903-002-09-02-1-565x400-1.jpg\",\"datePublished\":\"2007-04-12T15:45:52+00:00\",\"dateModified\":\"2020-10-09T13:31:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2007\\\/04\\\/0903-002-09-02-1-565x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2007\\\/04\\\/0903-002-09-02-1-565x400-1.jpg\",\"width\":565,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/los-tres-rechazos-del-movimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los 3 Rechazos del Movimiento ATD Cuarto Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES","og_description":"Paris, 17 de noviembre de 1977 17 de Noviembre de 1977: reuni\u00f3n publica del Movimiento ATD Cuarto Mundo, en la (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2007-04-12T15:45:52+00:00","article_modified_time":"2020-10-09T13:31:16+00:00","og_image":[{"width":565,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webmestre"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo","datePublished":"2007-04-12T15:45:52+00:00","dateModified":"2020-10-09T13:31:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/"},"wordCount":74,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg","articleSection":["Discursos","Textos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/","url":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/","name":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg","datePublished":"2007-04-12T15:45:52+00:00","dateModified":"2020-10-09T13:31:16+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/es\/wp-content\/uploads\/sites\/13\/2007\/04\/0903-002-09-02-1-565x400-1.jpg","width":565,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/los-tres-rechazos-del-movimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Los 3 Rechazos del Movimiento ATD Cuarto Mundo"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=892"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/892\/revisions"}],"predecessor-version":[{"id":1746,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/892\/revisions\/1746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media\/1745"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}