{"id":897,"date":"2007-02-22T16:18:19","date_gmt":"2007-02-22T15:18:19","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/"},"modified":"2007-02-22T16:18:19","modified_gmt":"2007-02-22T15:18:19","slug":"palabras-de-inauguration-del","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/","title":{"rendered":"Inauguraci\u00f3n del Centro International Joseph Wresinski"},"content":{"rendered":"<h2>Discurso pronunciado por Marco Aurelio Ugarte Ochoa<\/h2>\n<p>Discurso pronunciado por Marco Aurelio Ugarte Ochoa con motivo de la inauguraci&oacute;n del Centro Internacional Joseph Wresinski, Baillet-en-France, el 10 de Febrero, 2007<\/p>\n<h3> <strong>Discurso en la Inauguraci&oacute;n del Centro Internacional Joseph Wresinski<\/strong> <\/h3>\n<h3>Marco Aurelio Ugarte Ochoa<\/h3>\n<p><strong>Para los pa&iacute;ses de todos los continentes y en especial para el continente americano<\/strong>, el d&iacute;a de hoy tiene una significaci&oacute;n especial, por inaugurarse el CIJW, que es la &laquo; Casa de la Memoria &raquo;, donde se acoger&aacute; y desde donde se irradiar&aacute; el conocimiento de los m&aacute;s pobres del mundo. Este es un hecho sin precedentes en la historia.<\/p>\n<p>El Continente Americano, como ustedes saben es multi&eacute;tnico y multicultural, su desarrollo aut&oacute;nomo fue interrumpido a causa del descubrimiento, la conquista,  colonizaci&oacute;n, y la independencia,  cuyas consecuencias todav&iacute;a hoy las enfrentamos.<\/p>\n<p>Sin temor a equivocarnos podemos decir, que la historia contada y escrita sobre el Continenete Americano, es la historia generalmente escrita por los vencedores. Los vencidos, aprendieron a guardar un silencio prudente para poder preservar su conocimiento ; es decir, su cultura material y espiritual, forjada en apr&oacute;ximadamente 20 mil a&ntilde;os, en la que construyeron importantes civilizaciones,  como la cultura Maya, Azteca, Tiyawanaku e Inka.<\/p>\n<p>Por ser herederos de &eacute;sta tradici&oacute;n, es que los americanos decimos  que somos pa&iacute;ses con una fuerte identidad &eacute;tnica y cultural, puesto que sabemos de donde venimos y  hacia donde vamos.<\/p>\n<p>El Centro Internacional Joseph Wresinski,  que hoy inauguramos, <strong>permitir&aacute; romper el silencio, escuchando la voz de los excluidos<\/strong>,  escribiendo, contando, testimoniando, la historia de los m&aacute;s pobres, de todos aquellos que no son reconocidos como personas con todos sus derechos y que puedan asumir sus responsabilidades.<\/p>\n<p>Se romper&aacute; ese silencio gracias a un hombre, el Padre Joseph Wresinski, quien hace 50 a&ntilde;os comenz&oacute; a vislumbrar un &laquo; proyecto de civilizaci&oacute;n &raquo;  para la humanidad, se&ntilde;alando como punto de partida, que todos los hombres : &laquo; Cualquiera que sea su modo de vida o su pensamiento, su situaci&oacute;n social, religiosa, o sus medios econ&oacute;micos, su origen &eacute;tnico o racial &raquo; guarda su dignidad de hombre. Plantea como un objetivo fundamental construir <strong>&laquo;una cultura universal de rechazo a la miseria&raquo;, oponiendo a la violencia la paz, al odio y al rencor el amor, a la intolerancia la tolerancia, a la desuni&oacute;n la unidad y la fraternidad<\/strong>.<\/p>\n<p>Cuando en algunos pa&iacute;ses de Am&eacute;rica conocimos el pensamiento y la acci&oacute;n del Padre  Joseph Wresinski, de inmediato nos adscribimos a ella, puesto que expresaban tambi&eacute;n nuestros ideales largo tiempo guardados o deliveradamente silenciados.<\/p>\n<p>Escucharle decir : Que el paternalismo y asistencialismo, denigraba a los seres humanos y hac&iacute;a que la dependencia se perpet&uacute;e ; es una verdad irrefutable, puesto que los pa&iacute;ses llamados del tercer mundo, tenemos un rico conocimiento y somos capaces de conducir nuestro propio desarrollo.<\/p>\n<p>Que la miseria no era una fatalidad, que la miseria fue creada por los hombres y que s&oacute;lo ellos pod&iacute;an destruirla.<\/p>\n<p>Que la miseria no era culpa de quienes la padec&iacute;an, sino de la sociedad, que no les di&oacute; la oportunidad a quienes estaban atrapados dentro de ella para poder liberarse.<\/p>\n<p>Que los m&aacute;s pobres quieren la paz y que todos los hombres son indispensables, ricos y pobres, para construir una sociedad sin miseria ni exclusi&oacute;n . Su frase : &laquo;No hay enemigos que derrotar sino amigos que hemos de ganar&raquo; nos revela su esperanza para construir la unidad de toda la humanidad.<\/p>\n<p>Este pensamiento y la puesta en marcha por el Movimiento ATD Cuarto Mundo, de compromisos de personas junto a los m&aacute;s pobres del mundo, para que unidos podamos  destruir la miseria,  y liberarnos de uno de los m&aacute;s grandes flagelos que enfrenta la humanidad, nos devuelve la esperanza. En Am&eacute;rica la filosof&iacute;a Wresinski, tiene una especial significaci&oacute;n, puesto que siempre estuvimos confrontados unos a otros, pensando que la lucha de clases era la soluci&oacute;n para la erradicaci&oacute;n de la miseria. .<\/p>\n<p>Este Centro permitir&aacute; que se encuentren : de una parte, el conocimiento del Cuarto Mundo ; es decir, el conocimiento de los m&aacute;s pobres y de todos aquellos para quienes la miseria es insoportable y que comprometen  su vida o parte de ella para caminar junto a ellos ; y de otro,  el conocimiento universitario, acad&eacute;mico. Del encuentro de estos conocimientos en  en &eacute;ste lugar com&uacute;n, en &eacute;ste lugar de encuentro, en este lugar donde se confrontar&aacute;n y cruzar&aacute;n saberes e ideas, surgir&aacute; un nuevo conocimiento, para construir una civilizaci&oacute;n sin miseria ni exclusi&oacute;n.<\/p>\n<p>He seleccionado este objeto que a nombre de los pueblos americanos lo ofrecemos a &eacute;ste Centro, objeto que es parte de la vida espiritual de los pueblos andinos y que es utilizado hoy en d&iacute;a en sus rituales religiosos, el agua que introducir&eacute; representa el conocimiento de estos pueblos, el que a simple vista permanecera escondido, pero luego de recorrer por sus &laquo; k&rsquo;enkos &raquo; o cavidades escondidas. Si le damos la oportunidad, surgir&aacute; con fluidez  y claridad, que es lo que representa para nosotros,  el CIJW.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discurso pronunciado por Marco Aurelio Ugarte Ochoa Discurso pronunciado por Marco Aurelio Ugarte Ochoa con motivo de la inauguraci&oacute;n del (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/\">Leer m\u00e1s <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-897","post","type-post","status-publish","format-standard","hentry","category-actualidades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES\" \/>\n<meta property=\"og:description\" content=\"Discurso pronunciado por Marco Aurelio Ugarte Ochoa Discurso pronunciado por Marco Aurelio Ugarte Ochoa con motivo de la inauguraci&oacute;n del (...) Leer m\u00e1s &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski ES\" \/>\n<meta property=\"article:published_time\" content=\"2007-02-22T15:18:19+00:00\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Inauguraci\u00f3n del Centro International Joseph Wresinski\",\"datePublished\":\"2007-02-22T15:18:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/\"},\"wordCount\":939,\"commentCount\":0,\"articleSection\":[\"Actualidades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/\",\"name\":\"Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\"},\"datePublished\":\"2007-02-22T15:18:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/palabras-de-inauguration-del\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inauguraci\u00f3n del Centro International Joseph Wresinski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/\",\"name\":\"Joseph Wresinski ES\",\"description\":\"Un sitio web propuesto por el Centro Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/es\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/","og_locale":"es_ES","og_type":"article","og_title":"Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES","og_description":"Discurso pronunciado por Marco Aurelio Ugarte Ochoa Discurso pronunciado por Marco Aurelio Ugarte Ochoa con motivo de la inauguraci&oacute;n del (...) Leer m\u00e1s &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/","og_site_name":"Joseph Wresinski ES","article_published_time":"2007-02-22T15:18:19+00:00","author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"webmestre","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Inauguraci\u00f3n del Centro International Joseph Wresinski","datePublished":"2007-02-22T15:18:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/"},"wordCount":939,"commentCount":0,"articleSection":["Actualidades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/","url":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/","name":"Inauguraci\u00f3n del Centro International Joseph Wresinski - Joseph Wresinski ES","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#website"},"datePublished":"2007-02-22T15:18:19+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/es\/palabras-de-inauguration-del\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.joseph-wresinski.org\/es\/"},{"@type":"ListItem","position":2,"name":"Inauguraci\u00f3n del Centro International Joseph Wresinski"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/es\/#website","url":"https:\/\/www.joseph-wresinski.org\/es\/","name":"Joseph Wresinski ES","description":"Un sitio web propuesto por el Centro Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/es\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/es\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":0,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/es\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}