{"id":1777,"date":"2017-07-13T10:45:26","date_gmt":"2017-07-13T08:45:26","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/?p=1777"},"modified":"2018-07-03T09:25:18","modified_gmt":"2018-07-03T07:25:18","slug":"droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/","title":{"rendered":"Droits culturels et pauvret\u00e9s. Observer la honte  | P. Patrice Meyer-Bisch"},"content":{"rendered":"<h2>11 JUIN 2017 : CULTURE ET GRANDE PAUVRET\u00c9<\/h2>\n<p><strong>Colloque de Cerisy | Communication de Patrice Meyer-Bisch &#8211; VID\u00c9O ci-dessous<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-21556 size-thumbnail alignleft\" src=\"http:\/\/www.atd-quartmonde.org\/wp-content\/uploads\/2017\/06\/patriceMeyerBisch-175x175.jpg\" alt=\"\" width=\"175\" height=\"175\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Patrice Meyer-Bisch<\/strong> est Philosophe, pr\u00e9sident de l&rsquo;Observatoire de la diversit\u00e9 et des droits culturels \u00e0 l&rsquo; Universit\u00e9 de Fribourg<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>\u00ab L\u2019action culturelle est effectivement primordiale. Elle permet de poser la question de l\u2019exclusion humaine d\u2019une mani\u00e8re plus radicale que ne le fait l\u2019acc\u00e8s au droit au logement, au travail, aux ressources ou \u00e0 la sant\u00e9. On pourrait penser que l\u2019acc\u00e8s \u00e0 ces autres droits devient in\u00e9luctable, lorsque le droit \u00e0 la culture est reconnu. \u00bb<\/em> Joseph Wresinski dans <em>\u00ab\u00a0Culture et grande pauvret\u00e9\u00a0\u00bb.<\/em><\/p>\n<p>Patrice Meyer-Bisch analyse cette approche qui consid\u00e8re la pauvret\u00e9 et l\u2019extr\u00eame pauvret\u00e9 comme une violation des droits de l&rsquo;homme ; plus sp\u00e9cialement les violations et les r\u00e9alisations des droits culturels au sein de l\u2019ensemble des droits de l&rsquo;homme, selon le principe d\u2019indivisibilit\u00e9 auquel Joseph Wresinski tenait beaucoup. Les droits culturels sont avant tout les droits de trouver, d\u2019exprimer et de partager, les savoirs et d\u00e9sirs de savoirs qui sont au plus profond de soi. Comment valoriser, croiser et porter les savoirs les plus vuln\u00e9rables, les t\u00e9moins les plus r\u00e9v\u00e9lateurs de la honte et de son endroit : la dignit\u00e9 ?<br \/>\nPatrice Meyer Bish nous fait r\u00e9fl\u00e9chir \u00e0 partir de deux angles :<br \/>\n1) \u00ab Observer \u00bb la honte ;<br \/>\n2)\u00a0 Les droits culturels et les savoirs de vuln\u00e9rabilit\u00e9.<\/p>\n<h2>VID\u00c9O DE LA CONF\u00c9RENCE<\/h2>\n<figure class=\"video-embed\" style=\"width:474px;height:267px;max-width: 100%;\" onclick=\"this.outerHTML='&lt;iframe src=&quot;https:\/\/player.vimeo.com\/video\/221172221?dnt=1&amp;amp;app_id=122963?autoplay=1&quot; width=&quot;474&quot; height=&quot;267&quot; frameborder=&quot;0&quot; allow=&quot;autoplay; fullscreen; picture-in-picture; clipboard-write&quot;&gt;&lt;\/iframe&gt;'\"><img decoding=\"async\" src=\"\" title=\"\" class=\"video-thumbnail\"><img decoding=\"async\" src=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/themes\/ATDJW\/images\/play_video.png\" class=\"video-play\"><figcaption>\n<h1>Play with Vimeo<\/h1>\n<p>By clicking the video, you accept that YouTube places cookies on your computer.<\/p>\n<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11 JUIN 2017 : CULTURE ET GRANDE PAUVRET\u00c9 Colloque de Cerisy | Communication de Patrice Meyer-Bisch &#8211; VID\u00c9O ci-dessous &nbsp; (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":1778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[67],"tags":[],"class_list":["post-1777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colloque-cerisy-2017"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"11 JUIN 2017 : CULTURE ET GRANDE PAUVRET\u00c9 Colloque de Cerisy | Communication de Patrice Meyer-Bisch &#8211; VID\u00c9O ci-dessous &nbsp; (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-13T08:45:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-03T07:25:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"404\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jeff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"jeff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/\"},\"author\":{\"name\":\"jeff\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/a65032f53b564dd904a3b6c0b49b233b\"},\"headline\":\"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch\",\"datePublished\":\"2017-07-13T08:45:26+00:00\",\"dateModified\":\"2018-07-03T07:25:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/\"},\"wordCount\":265,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/07\\\/P-Meyer-Bisch.jpg\",\"articleSection\":[\"Colloque Cerisy 2017\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/\",\"name\":\"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/07\\\/P-Meyer-Bisch.jpg\",\"datePublished\":\"2017-07-13T08:45:26+00:00\",\"dateModified\":\"2018-07-03T07:25:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/a65032f53b564dd904a3b6c0b49b233b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/07\\\/P-Meyer-Bisch.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/07\\\/P-Meyer-Bisch.jpg\",\"width\":750,\"height\":404},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/a65032f53b564dd904a3b6c0b49b233b\",\"name\":\"jeff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g\",\"caption\":\"jeff\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/jeff\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/","og_locale":"fr_FR","og_type":"article","og_title":"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR","og_description":"11 JUIN 2017 : CULTURE ET GRANDE PAUVRET\u00c9 Colloque de Cerisy | Communication de Patrice Meyer-Bisch &#8211; VID\u00c9O ci-dessous &nbsp; (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2017-07-13T08:45:26+00:00","article_modified_time":"2018-07-03T07:25:18+00:00","og_image":[{"width":750,"height":404,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg","type":"image\/jpeg"}],"author":"jeff","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"jeff","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/"},"author":{"name":"jeff","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/a65032f53b564dd904a3b6c0b49b233b"},"headline":"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch","datePublished":"2017-07-13T08:45:26+00:00","dateModified":"2018-07-03T07:25:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/"},"wordCount":265,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg","articleSection":["Colloque Cerisy 2017"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/","name":"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg","datePublished":"2017-07-13T08:45:26+00:00","dateModified":"2018-07-03T07:25:18+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/a65032f53b564dd904a3b6c0b49b233b"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2018\/07\/P-Meyer-Bisch.jpg","width":750,"height":404},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/droits-culturels-et-pauvretes-observer-la-honte-p-patrice-meyer-bisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Droits culturels et pauvret\u00e9s. Observer la honte | P. Patrice Meyer-Bisch"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/a65032f53b564dd904a3b6c0b49b233b","name":"jeff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1f7f9774a9bd55616144b66647670f1246d9c1d7c547d4642e76862a77b47884?s=96&d=mm&r=g","caption":"jeff"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/jeff\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/1777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":1,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"predecessor-version":[{"id":1779,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/1777\/revisions\/1779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/1778"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}