{"id":2381,"date":"2015-12-19T15:04:02","date_gmt":"2015-12-19T14:04:02","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/?p=2381"},"modified":"2020-09-04T15:17:38","modified_gmt":"2020-09-04T13:17:38","slug":"sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/","title":{"rendered":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski"},"content":{"rendered":"<div>\n<div class=\"inner-content\">\n<p><strong>Ce vendredi 18 d\u00e9cembre a vu la naissance de la Fondation Joseph Wresinski, abrit\u00e9e par l\u2019Institut de France \u00e0 Paris. Elle a pour but\u00a0d\u2019aider au\u00a0rayonnement de la pens\u00e9e de Joseph Wresinski dans nos\u00a0soci\u00e9t\u00e9s en soutenant des projets de recherche, des colloques, des publications\u2026<\/strong><\/p>\n<p>Le 13 juin 1983, Joseph Wresinski, secr\u00e9taire g\u00e9n\u00e9ral du Mouvement ATD Quart Monde, <a href=\"http:\/\/www.joseph-wresinski.org\/fr\/Le-Quart-Monde-dans-le-monde,509\/\">prenait la parole<\/a> devant l\u2019<a href=\"http:\/\/www.asmp.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Acad\u00e9mie des Sciences Morales et Politiques<\/a>, \u00e0 l\u2019Institut de France \u00e0 Paris. Cette Acad\u00e9mie reconnaissait ainsi la pertinence des analyses et des propositions du fondateur du Mouvement. 32 ans plus tard, l\u2019apport de cet homme et du Mouvement qu\u2019il a cr\u00e9\u00e9 en rassemblant des personnes et des familles ayant l\u2019exp\u00e9rience personnelle de la pauvret\u00e9 et des citoyens de tous bords qui s\u2019en sont solidaris\u00e9s, reste d\u2019une actualit\u00e9 br\u00fblante.<\/p>\n<p><strong>Pour affronter les grandes questions de notre temps, la violence, la mutation \u00e9conomique et \u00e9cologique, la crise spirituelle et d\u2019identit\u00e9 de nos soci\u00e9t\u00e9s, la recherche d\u2019un vivre ensemble dans la paix, la construction d\u2019une d\u00e9mocratie authentique, la pens\u00e9e Wresinski s\u2019offre \u00e0 nous comme une ressource pr\u00e9cieuse, originale et encore trop m\u00e9connue et \u00e9tudi\u00e9e<\/strong>. Les efforts n\u2019ont pourtant pas manqu\u00e9. Outre la publication de ces \u00e9crits et prises de paroles, entam\u00e9es au lendemain de sa mort en f\u00e9vrier 1988, des s\u00e9minaires, des colloques ont \u00e9t\u00e9 organis\u00e9s. Le<a href=\"https:\/\/www.atd-quartmonde.org\/nos-actions\/changer-la-societe\/memoire-et-recherche\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Centre International Joseph Wresinski <\/a>a \u00e9t\u00e9 cr\u00e9\u00e9 \u00e0 Baillet-en-France dans le Val d\u2019Oise pour permettre de rassembler et faire fructifier cet important h\u00e9ritage, en rassemblant toutes les archives du Mouvement et de son fondateur.<\/p>\n<p>Ce 18 d\u00e9cembre 2015, c\u2019est un nouvel outil au service de ce rayonnement qui a vu le jour. Isabelle Pypaert Perrin, d\u00e9l\u00e9gu\u00e9e g\u00e9n\u00e9rale du Mouvement international ATD Quart Monde, a \u00e9t\u00e9 re\u00e7ue \u00e0 l\u2019<a href=\"http:\/\/www.institut-de-france.fr\/\" target=\"_blank\" rel=\"noopener noreferrer\">Institut de France<\/a> , par son Chancelier, Monsieur Gabriel de Broglie, pour signer une convention cr\u00e9ant la Fondation Joseph Wresinski.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2382\" src=\"http:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/signature-Fondation.jpg\" alt=\"\" width=\"700\" height=\"410\" srcset=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/signature-Fondation.jpg 700w, https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/signature-Fondation-400x234.jpg 400w, https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/signature-Fondation-683x400.jpg 683w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La convention sign\u00e9e pr\u00e9cise en ces termes la mission de cette Fondation:<\/p>\n<p><em>La Fondation Joseph Wresinski a pour but de promouvoir l\u2019\u00e9mergence et la diffusion d\u2019une culture du refus de la mis\u00e8re en apportant son soutien \u00e0 tout projet\u00a0: <\/em><\/p>\n<ul>\n<li><em>Permettant de saisir la vie, la pens\u00e9e, l\u2019action et la spiritualit\u00e9 du p\u00e8re Joseph Wresinski, fondateur du Mouvement International ATD Quart Monde, ainsi que l\u2019influence qu\u2019il a exerc\u00e9e de son vivant et son impact, et d\u2019en assurer la diffusion dans le monde\u00a0;<\/em><\/li>\n<li><em>T\u00e9moignant de la vie et des luttes des populations en grande pauvret\u00e9 ;<\/em><\/li>\n<li><em>T\u00e9moignant de la vie et de l\u2019action du Mouvement International ATD Quart Monde, de son histoire, de son actualit\u00e9, de sa pens\u00e9e et de l\u2019influence qu\u2019il a dans les soci\u00e9t\u00e9s dans lesquelles il \u00e9volue.<\/em><\/li>\n<\/ul>\n<p>Un nouvel outil, qui sera op\u00e9rationnel dans quelques temps, apr\u00e8s la mise en place de son Conseil d\u2019administration compos\u00e9 de trois membres des Acad\u00e9mies et trois repr\u00e9sentants du Mouvement, est ainsi mis \u00e0 la disposition de notre effort pour que la pens\u00e9e des plus pauvres devienne chaque jour un peu plus un rep\u00e8re pour notre temps. Il permettra, en France et dans le monde, gr\u00e2ce aux int\u00e9r\u00eats de son capital de d\u00e9part et \u00e0 de nouveaux legs et donations, de soutenir des projets de recherche, l\u2019organisation de colloques, d\u2019expositions, la r\u00e9alisation de traductions, l\u2019attribution de bourses et de prix, et toute autre activit\u00e9 concourant aux objectifs d\u00e9finis plus haut.<\/p>\n<p>L\u2019Institut de France regroupe cinq Acad\u00e9mies dont l\u2019Acad\u00e9mie fran\u00e7aise et celle des Sciences morales et politiques. Elle abrite en son sein une soixantaine de Fondations actives dans le champ de la recherche, de la culture, de la science et du patrimoine.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce vendredi 18 d\u00e9cembre a vu la naissance de la Fondation Joseph Wresinski, abrit\u00e9e par l\u2019Institut de France \u00e0 Paris. (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":2383,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[73],"tags":[],"class_list":["post-2381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite-de-la-fondation-joseph-wresinski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"Ce vendredi 18 d\u00e9cembre a vu la naissance de la Fondation Joseph Wresinski, abrit\u00e9e par l\u2019Institut de France \u00e0 Paris. (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-19T14:04:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-04T13:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"708\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski\",\"datePublished\":\"2015-12-19T14:04:02+00:00\",\"dateModified\":\"2020-09-04T13:17:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/\"},\"wordCount\":668,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/institut_de_france2.jpg\",\"articleSection\":[\"Actualit\u00e9 de la Fondation Joseph Wresinski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/\",\"name\":\"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/institut_de_france2.jpg\",\"datePublished\":\"2015-12-19T14:04:02+00:00\",\"dateModified\":\"2020-09-04T13:17:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/institut_de_france2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/institut_de_france2.jpg\",\"width\":708,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/","og_locale":"fr_FR","og_type":"article","og_title":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR","og_description":"Ce vendredi 18 d\u00e9cembre a vu la naissance de la Fondation Joseph Wresinski, abrit\u00e9e par l\u2019Institut de France \u00e0 Paris. (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2015-12-19T14:04:02+00:00","article_modified_time":"2020-09-04T13:17:38+00:00","og_image":[{"width":708,"height":472,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean Tonglet","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski","datePublished":"2015-12-19T14:04:02+00:00","dateModified":"2020-09-04T13:17:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/"},"wordCount":668,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg","articleSection":["Actualit\u00e9 de la Fondation Joseph Wresinski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/","name":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg","datePublished":"2015-12-19T14:04:02+00:00","dateModified":"2020-09-04T13:17:38+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2020\/09\/institut_de_france2.jpg","width":708,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/sous-legide-de-linstitut-de-france-une-fondation-joseph-wresinski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Sous l\u2019\u00e9gide de l\u2019Institut de France, une Fondation Joseph Wresinski"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/2381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=2381"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/2381\/revisions"}],"predecessor-version":[{"id":2386,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/2381\/revisions\/2386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/2383"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=2381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=2381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=2381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}