{"id":249,"date":"2021-09-17T00:00:11","date_gmt":"2021-09-16T22:00:11","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/2008\/04\/23\/la-justice-des-lois-ce-n-est-pas\/"},"modified":"2021-09-17T00:20:35","modified_gmt":"2021-09-16T22:20:35","slug":"la-justice-des-lois-ce-n-est-pas","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/","title":{"rendered":"Justice au c\u0153ur!"},"content":{"rendered":"<p><i>A tout juste un mois du 17 octobre, \u00ab\u00a0Journ\u00e9e mondiale du refus de la mis\u00e8re\u00a0\u00bb, ce discours du p\u00e8re Joseph Wresinski nous rappelle le sens qu&rsquo;il donnait \u00e0 la manifestation convoqu\u00e9e \u00e0 Paris, le 17 octobre 1987. S\u2019adressant, le 15 novembre 1986,\u00a0 \u00e0 une assembl\u00e9e des membres du Mouvement aux Pays-Bas, \u00e0 Heerlen, il s\u2019expliquait sur les raisons qui l\u2019avaient pouss\u00e9 \u00e0 proposer au Mouvement le slogan \u00ab Justice au coeur \u00bb, pour la campagne men\u00e9e en 1987 pour marquer le 30\u00e8me anniversaire de sa cr\u00e9ation. Campagne dont l&rsquo;aboutissement sera l\u2019inauguration, le 17 octobre 1987, sur le Parvis des Libert\u00e9s et des Droits de l\u2019Homme, d\u2019une dalle en l\u2019honneur des victimes de la mis\u00e8re\u00a0\u00bb.<\/i><\/p>\n<p>\u00ab\u00a0Que l\u2019injustice s\u2019arr\u00eate&#8230;Tout le film que nous venons de voir nous le crie\u00a0: \u00ab\u00a0\u00e7a suffit, il y a une fin \u00e0 tout&#8230;\u00a0\u00bb Mais les personnes qui nous parlent ainsi, la m\u00e8re de famille qui dit cela\u00a0: \u00ab\u00a0que l\u2019injustice s\u2019arr\u00eate\u00a0\u00bb, que veulent-elles dire vraiment\u00a0?<\/p>\n<p>Elles veulent dire qu\u2019il faut que la justice arrive enfin. Mais qu\u2019entendent-elles par l\u00e0\u00a0? De nouvelles lois, bien s\u00fbr, une l\u00e9gislation nouvelle assurant un revenu garanti, la s\u00e9curit\u00e9 de l\u2019emploi, un logement d\u00e9cent\u00a0? Naturellement, les familles de cette cit\u00e9 fran\u00e7aise et ces autres familles de toutes nationalit\u00e9s que nous voyons dans le film, r\u00e9unies dans une soir\u00e9e internationale \u00e0 Paris, d\u00e9sirent tout cela. C\u2019est leur droit et c\u2019est notre responsabilit\u00e9 d\u2019obtenir ces s\u00e9curit\u00e9s, prot\u00e9g\u00e9es par la loi. Toutefois, toutes les familles en grande difficult\u00e9, que j\u2019ai connues, depuis trente ans, \u00e0 travers la France, l\u2019Europe et le monde, ne se sont jamais content\u00e9es de cette justice des l\u00e9gislations, de cette justice qui ne serait fond\u00e9e que sur le droit. A Paris et Marseille, \u00e0 Londres et Munich, \u00e0 Dakar et Port au Prince, les familles m\u2019ont toujours parl\u00e9 d\u2019une autre justice, de la justice du c\u0153ur.<\/p>\n<p>\u00ab\u00a0Comment les gens peuvent-ils voir souffrir mes enfants \u00e0 l\u2019\u00e9cole, sans en avoir, eux-m\u00eames, le c\u0153ur meurtri\u00a0?\u00a0\u00bb &#8230; \u00ab\u00a0Comment l\u2019employeur a-t-il pu avoir si peu de c\u0153ur, pour renvoyer mon mari\u00a0?\u00a0\u00bb &#8230; \u00ab\u00a0Comment l\u2019assistante sociale a-t-elle pu avoir le c\u0153ur aussi dur, et si injuste en m\u2019accusant de n\u2019\u00eatre pas une bonne m\u00e8re. Le vrai cri des familles, votre cri \u00e0 vous, familles des Pays-Bas, n\u2019est-il pas toujours d\u2019abord celui-l\u00e0\u00a0? \u00ab\u00a0Comment ont-ils eu le c\u0153ur \u00e0 nous blesser, \u00e0 nous m\u00e9priser, \u00e0 nous humilier, \u00e0 nous faire sentir sans arr\u00eat que nous n\u2019\u00e9tions que des moins que rien\u00a0?<\/p>\n<p>\u00ab\u00a0Ce n\u2019est pas juste, c\u2019est d\u2019abord cela qui n\u2019est pas juste,\u00a0\u00bbdites-vous souvent, quand je vous rencontre \u00e0 la ferme de Wijhe. La premi\u00e8re injustice, celle qui doit, la premi\u00e8re, s\u2019arr\u00eater, est l\u2019injustice du c\u0153ur. Cette plus terrible des injustices qui fait qu\u2019un homme puisse se croire sup\u00e9rieur \u00e0 un autre homme, se croire en droit de le m\u00e9priser.<\/p>\n<p>Je songe \u00e0 cette maman hollandaise de Koevorden, qui me racontait comment enfant, jeune fille, elle vivait avec ses parents sur une p\u00e9niche.<\/p>\n<p>\u00ab\u00a0Chez nous, c\u2019\u00e9tait bien, c\u2019\u00e9tait propre\u00a0\u00bb,me disait-elle, mais les gens de la ville ne le croyaient pas.<\/p>\n<p>Ils nous m\u00e9prisaient, ils pensaient que nous n\u2019\u00e9tions pas propres et mes camarades de classe ne pouvaient pas venir jouer chez moi, sur la p\u00e9niche\u00a0\u00bb.<\/p>\n<p>C\u2019est cette injustice du c\u0153ur, cette injustice dans le regard de l\u2019entourage qui a fait que plus tard la jeune fille devenue, elle-m\u00eame, \u00e9pouse et maman, a compris toutes les autres injustices, celles des lois. Elle comprend aujourd\u2019hui pourquoi, avec sa famille, elle est oblig\u00e9e d\u2019habiter un appartement qui, depuis plus de dix ans, attend des travaux de r\u00e9novation. Elle attend une ann\u00e9e apr\u00e8s l\u2019autre, parce que la ville doit faire des \u00e9conomies. Or, c\u2019est toujours l\u2019immeuble qu\u2019elle habite qui se trouve ray\u00e9 du budget municipal.<\/p>\n<p>Injustice criante car des familles ayant plus de ressources se voient bien log\u00e9es par la ville. Mais la maman, elle, comprend d\u2019o\u00f9 vient cette injustice dans la gestion de sa ville. Les fonctionnaires qui traitent de ce dossier dans les bureaux de l\u2019H\u00f4tel de Ville, \u00e9taient des enfants quand elle \u00e9tait petite fille. Et d\u00e8s l\u2019\u00e9cole, on leur disait que sur les p\u00e9niches vivaient des gens pas propres, des enfants avec lesquels il ne fallait pas jouer. Enfants ces fonctionnaires n\u2019ont pas appris cette justice au c\u0153ur qui dit que tout autre enfant est un fr\u00e8re, un camarade.<\/p>\n<p>Alors, aujourd\u2019hui, comment auraient-ils la justice dans leurs dossiers, dans leurs lois\u00a0?<\/p>\n<p>Cette maman dont je vous parle, qui nous racontait tout cela, si simplement, me disait aussi\u00a0: \u00ab\u00a0de toutes ces choses, longtemps je n\u2019ai pu parler \u00e0 personne. Aujourd\u2019hui, ici, je peux dire ce que j\u2019ai v\u00e9cu, car ici, on trouve des gens \u00e0 qui on peut parler\u00a0\u00bb.<\/p>\n<p>Les Droits de l\u2019Homme sont d\u2019abord une affaire d\u2019hommes.<\/p>\n<p>\u00ab\u00a0Des gens \u00e0 qui on peut parler\u00a0\u00bb disait cette m\u00e8re de famille. Et c\u2019est ce que disent toutes les familles qui viennent \u00e0 la ferme de Wijhe . \u00ab\u00a0Ici, on trouve des gens \u00e0 qui on peut parler\u00a0\u00bb.<\/p>\n<p>Pourquoi peut-on leur parler\u00a0? Parce qu\u2019ils ont le d\u00e9sir profond, puissant, d\u2019entendre, de comprendre, de partager. Parce que la justice n\u2019est pas seulement dans leur t\u00eate, dans leurs paroles, mais dans leur c\u0153ur. Cette justice qui fait que quand l\u2019autre a mal, vous avez mal, vous-m\u00eame. Quand l\u2019autre est humili\u00e9, vous vous sentez, vous aussi, humili\u00e9.<\/p>\n<p>Je veux vous dire quelques mots de ces volontaires \u00ab\u00a0\u00e0 qui l\u2019on peut parler\u00a0\u00bb, de ceux que vous appelez, avec raison, les \u00ab\u00a0permanents\u00a0\u00bb.<\/p>\n<p>Permanents, ils le sont en quoi\u00a0? Permanents de la justice au c\u0153ur qui fait que le jour, ils travaillent, ils agissent, ils vivent avec les familles. Justice au c\u0153ur qui fait que, la nuit, ils se r\u00e9veillent encore, inquiets de ne pas en avoir fait assez. Inquiets de ce qui doit r\u00e9ussir, demain, pour que l\u2019injustice s\u2019arr\u00eate dans le c\u0153ur des hommes. Parce qu\u2019alors, elle s\u2019arr\u00eatera aussi dans les lois.<\/p>\n<p>Ces \u00ab\u00a0permanents\u00a0\u00bb, ces volontaires ont appris des familles du Quart Monde que la grande pauvret\u00e9 est la violation la plus totale des Droits de l\u2019Homme.<\/p>\n<p>En Quart Monde, en effet, il n\u2019y a ni droit \u00e0 l\u2019instruction, ni droit au travail. Il n\u2019y a ni libert\u00e9 de choix du domicile, ni moyens de s\u2019associer librement dans une organisation de son choix.<\/p>\n<p>\u00ab\u00a0Les autres ne nous voient pas, c\u2019est comme si nous n\u2019existions pas\u00a0\u00bb, disent les familles. Et ceux qui n\u2019existent pas, quelle place auraient-ils dans nos syndicats ou partis politiques, dans nos Eglises ou nos associations\u00a0?<\/p>\n<p>La grande pauvret\u00e9 un d\u00e9ni de tous les Droits de l\u2019Homme, qu\u2019ils soient politiques, \u00e9conomiques, sociaux ou culturels. Les familles du Quart Monde, et les volontaires ont appris, compris cela, ensemble. Et vous, les alli\u00e9s, qui \u00eates venus, les rejoindre, vous l\u2019avez compris aussi. Et ainsi, en trente ans, a grandi et s\u2019est fortifi\u00e9 le Mouvement ATD Quart Monde, Mouvement pour les Droits de l\u2019Homme.<\/p>\n<p>Mais des organisations pour les Droits de l\u2019Homme, il y en a beaucoup dans le monde. Sommes-nous diff\u00e9rents\u00a0? Je crois qu\u2019\u00e0 cause de vous, les familles du Quart Monde, nous ne sommes pas tout \u00e0 fait une organisation comme une autre. Pourquoi\u00a0?<\/p>\n<p>Parce que nous, les Droits de l\u2019Homme existent seulement s\u2019ils sont assur\u00e9s jusque dans la famille la plus d\u00e9munie, la plus oubli\u00e9e, la plus r\u00e9prouv\u00e9e, la plus m\u00e9pris\u00e9e. Et parce que pour nous, les Droits de l\u2019Homme sont assur\u00e9s, garantis au fil du temps, quand ils ne sont pas seulement dans les lois mais d\u2019abord dans le c\u0153ur et la vie personnelle des hommes.<\/p>\n<p>Depuis la sortie de la seconde guerre mondiale, dans nos pays d\u2019Europe occidentale nous avons fait de grands progr\u00e8s en mati\u00e8re des Droits de l\u2019Homme. Personne ne peut le nier.<\/p>\n<p>Nos pays se sont donn\u00e9s de bonnes l\u00e9gislations. Mais les Hollandais, les Fran\u00e7ais, les Belges, les Allemands, les Britanniques n\u2019ont plus gard\u00e9 l\u2019id\u00e9al de la justice au c\u0153ur. Peu \u00e0 peu, ils ont acquis la conviction que la justice pouvait \u00eatre r\u00e9duite \u00e0 une affaire de l\u00e9gislation.<\/p>\n<p>Les Droits de l\u2019Homme avaient pourtant germ\u00e9 dans le c\u0153ur des hommes.<\/p>\n<p>Des hommes s\u2019\u00e9taient battus pour eux, parce que leur c\u0153ur croyait dans la nature et la valeur unique de tous les hommes. Et peu \u00e0 peu, sans que nous nous en rendions compte, de cette affaire de l\u2019homme pour l\u2019homme de cette affaire de foi et de c\u0153ur nous avons fait une affaire des seules structures politiques et juridiques de nos soci\u00e9t\u00e9s.<\/p>\n<p>C\u2019est \u00e0 cause de cela que nos c\u0153urs ne parlaient plus, quand nous voyions une famille habitant un taudis, des enfants profond\u00e9ment malheureux, rejet\u00e9s dans des classes d\u2019enseignement sp\u00e9cial. Nos c\u0153urs n\u2019\u00e9taient plus habit\u00e9s par la justice et nous avons pu supporter que des parents, des enfants, des travailleurs soient dans le malheur. Nous avons souvent fini par les m\u00e9priser \u00e0 cause de leur malheur. A les r\u00e9prouver, parce qu\u2019ils ne profitaient pas de nos lois.<\/p>\n<p>L\u2019ATD Quart Monde a pour vocation de rappeler la vraie histoire des Droits de l\u2019Homme. Les familles du Quart Monde nous rappellent que nous devons reprendre le fil de cette histoire d\u2019un id\u00e9al n\u00e9 au c\u0153ur des hommes, parce qu\u2019ils aimaient l\u2019humanit\u00e9.<\/p>\n<p>Les Droits de l\u2019Homme affaire de c\u0153ur, de foi, affaire de civilisation.<\/p>\n<p>Affaire de chaque homme\u00a0: ce sont des hommes et des femmes qui croient que c\u2019est leur affaire, la cause de leur vie, qui forment ce volontariat dont les familles pensent qu\u2019on peut tout lui dire de la souffrance qu\u2019inflige l\u2019injustice du c\u0153ur, plus que ne peut faire souffrir la seule injustice des lois.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A tout juste un mois du 17 octobre, \u00ab\u00a0Journ\u00e9e mondiale du refus de la mis\u00e8re\u00a0\u00bb, ce discours du p\u00e8re Joseph (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":3888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[63,49],"tags":[],"class_list":["post-249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conferences-publiques","category-ecrits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Justice au c\u0153ur! - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Justice au c\u0153ur! - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"A tout juste un mois du 17 octobre, \u00ab\u00a0Journ\u00e9e mondiale du refus de la mis\u00e8re\u00a0\u00bb, ce discours du p\u00e8re Joseph (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-16T22:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-16T22:20:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Justice au c\u0153ur!\",\"datePublished\":\"2021-09-16T22:00:11+00:00\",\"dateModified\":\"2021-09-16T22:20:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/\"},\"wordCount\":1746,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/AR0300126006.jpg\",\"articleSection\":[\"Conf\u00e9rences publiques\",\"Ecrits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/\",\"name\":\"Justice au c\u0153ur! - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/AR0300126006.jpg\",\"datePublished\":\"2021-09-16T22:00:11+00:00\",\"dateModified\":\"2021-09-16T22:20:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/AR0300126006.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/AR0300126006.jpg\",\"width\":775,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-des-lois-ce-n-est-pas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Justice au c\u0153ur!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Justice au c\u0153ur! - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/","og_locale":"fr_FR","og_type":"article","og_title":"Justice au c\u0153ur! - Joseph Wresinski FR","og_description":"A tout juste un mois du 17 octobre, \u00ab\u00a0Journ\u00e9e mondiale du refus de la mis\u00e8re\u00a0\u00bb, ce discours du p\u00e8re Joseph (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2021-09-16T22:00:11+00:00","article_modified_time":"2021-09-16T22:20:35+00:00","og_image":[{"width":775,"height":1100,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmestre","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Justice au c\u0153ur!","datePublished":"2021-09-16T22:00:11+00:00","dateModified":"2021-09-16T22:20:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/"},"wordCount":1746,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg","articleSection":["Conf\u00e9rences publiques","Ecrits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/","name":"Justice au c\u0153ur! - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg","datePublished":"2021-09-16T22:00:11+00:00","dateModified":"2021-09-16T22:20:35+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2021\/08\/AR0300126006.jpg","width":775,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-des-lois-ce-n-est-pas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Justice au c\u0153ur!"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":6,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/249\/revisions"}],"predecessor-version":[{"id":3901,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/249\/revisions\/3901"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}