{"id":287,"date":"2007-07-19T15:30:28","date_gmt":"2007-07-19T13:30:28","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/2007\/07\/19\/aux-volontaires\/"},"modified":"2018-03-15T22:03:17","modified_gmt":"2018-03-15T21:03:17","slug":"aux-volontaires","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/","title":{"rendered":"Aux Volontaires."},"content":{"rendered":"<p><em>Ce message adress\u00e9 aux volontaires a \u00e9t\u00e9 enregistr\u00e9 par le p\u00e8re Joseph Wresinski \u00e0 l\u2019H\u00f4pital Foch, le 8 f\u00e9vrier 1988,\u00e0 la veille de son op\u00e9ration. Connu aussi sous l&rsquo;appellation \u00ab\u00a0lettre cassette\u00a0\u00bb, il a \u00e9t\u00e9 publi\u00e9 peu apr\u00e8s sa mort par l&rsquo;hebdomadaire \u00ab\u00a0La Vie\u00a0\u00bb.<\/em><\/p>\n<p>Mes amis,<\/p>\n<p>A la veille de mon op\u00e9ration, m\u00eame si je m\u2019y rends en toute confiance, je ne peux pas m\u2019emp\u00eacher de penser. Ainsi, quand on est comme moi pour le moment, entre les mains des m\u00e9decins et des infirmi\u00e8res, je peux \u00e0 nouveau mieux mesurer ce que vivent les pauvres dans leur quotidien, eux qui sont \u00e0 la merci, ou plut\u00f4t, eux qui sont oblig\u00e9s de tenir compte des jugements, des avis des uns et des autres, en ce qui concerne leur propre vie. Lorsqu\u2019on est ainsi oblig\u00e9 d\u2019\u00eatre d\u00e9pendant de tout le monde, il faut surtout se faire petit, ne pas se faire remarquer. C\u2019est une premi\u00e8re r\u00e9flexion.<\/p>\n<p>Une seconde chose que j\u2019aimerais vous dire, \u00e0 vous les volontaires, est que nous devons rester tr\u00e8s, tr\u00e8s proches des familles. Nous devons rester avant tout fid\u00e8les \u00e0 notre combat familial. Et ceci, non pas parce que nous serions des gens de principe, mais parce que la famille est notre alli\u00e9e. C\u2019est elle qui doit nous permettre de r\u00e9aliser ce que nous voulons comme soci\u00e9t\u00e9 de droit.<!--more--><\/p>\n<p>Mais nous nous devons de rester tr\u00e8s, tr\u00e8s proches surtout des familles les plus d\u00e9favoris\u00e9es. Ceci je me dois de vous le rappeler, car nous aurons toujours la tentation de nous appuyer sur les \u00e9l\u00e9ments les plus dynamiques, les plus courageux, les plus intelligents. Nous devons nous appuyer sur eux, bien s\u00fbr, mais nous ne devons pas nous laisser embrigader et prendre par eux. Ils ne doivent pas faire \u00e9cran entre les plus pauvres et nous. Nous devons veiller \u00e0 ce que ceux-ci aussi soient les agents de droit, au milieu de leurs fr\u00e8res et de leur propre milieu. Si nous ne devons pas nous laisser disperser par des actions tout azimut, il nous faut toujours nous poser la question\u00a0: l\u2019action que nous menons permet-elle aux plus d\u00e9favoris\u00e9s de sortir de leur situation et de devenir agents des droits de l\u2019homme\u00a0?<\/p>\n<p>Nous n\u2019avons pas \u00e0 avoir peur d\u2019\u00eatre hardis, m\u00eame si nous pensons (ce qui est juste d\u2019ailleurs) que la population n\u2019est pas capable d\u2019assumer d\u2019embl\u00e9e ce que nous lui pr\u00e9sentons. Cela nous impose simplement la n\u00e9cessit\u00e9 d\u2019aller par \u00e9tapes\u00a0: mais on ne va pas par \u00e9tapes sans programmer. Nous devons savoir quel est le but que nous voulons, et quels sont les moyens que nous prenons pour atteindre ce but. \u00catre des gens libres, libres dans leur propre soci\u00e9t\u00e9, agents de libert\u00e9 pour les autres, cela suppose que nous transmettions la culture qui est la n\u00f4tre et que nous vivons. Que nous transmettions toutes les connaissances qui sont les n\u00f4tres, que nous les partagions vraiment et donc que nous inventions aussi des moyens pour les faire partager, pour que les familles les assument. Nous ne sommes pas simplement des gens qui apportent des id\u00e9es et un langage, nous devons \u00eatre des gens qui apportent la pl\u00e9nitude de l\u2019homme, l\u2019harmonie de l\u2019homme, donc des gens qui apportent l\u2019art, la po\u00e9sie, et qui ne sont pas seulement des gens de la technique.<\/p>\n<p>Pour cela, nous devons nous impr\u00e9gner nous-m\u00eames de ce que les hommes ont le plus achev\u00e9, d\u2019expression musicale, de peinture&#8230; Il faut mettre les gens au coeur de la nature, la leur faire aimer, entrevoir la merveilleuse harmonie de la terre et du ciel. Dans la mesure o\u00f9 nous avons la Foi, il faut aussi que nous projetions les familles dans le monde invisible, de l\u2019infini, de fa\u00e7on \u00e0 ce qu\u2019elles soient elles-m\u00eames membres, pas simplement d\u2019une communaut\u00e9, d\u2019un quartier, mais membres de l\u2019univers et acteurs de libert\u00e9.<\/p>\n<p>Ceci suppose que nous soyons r\u00e9ellement int\u00e9gr\u00e9s au monde, que nous aimions le monde. Nous ne pouvons pas introduire les familles dans le monde de demain, et dans le monde d\u2019aujourd\u2019hui, sans que nous-m\u00eames nous n\u2019y soyons. Il ne s\u2019agit pas d\u2019\u00eatre aveugles et de ne pas voir les d\u00e9fauts des hommes. Mais il nous faut toujours nous rappeler que tout homme a droit \u00e0 notre confiance, tant que nous n\u2019avons pas de preuve du contraire. Il faut aimer les d\u00e9bats politiques, les d\u00e9bats philosophiques, il faut aimer les hommes qui se battent pour une foi. Il nous faut participer \u00e0 l\u2019esp\u00e9rance de tous ceux qui luttent, sans nous laisser pi\u00e9ger. Sans oublier qu\u2019il nous faut leur rappeler sans cesse que le plus pauvre doit faire partie de leur combat et de leur pens\u00e9e.<\/p>\n<p>Tout cela ne peut s\u2019obtenir sans de gros efforts de notre part. Efforts pour conna\u00eetre la population, les familles, conna\u00eetre leur histoire, leur milieu, leurs origines, l\u2019histoire de leur vie pr\u00e9sente, leur quotidien. Il nous faut vouloir communier profond\u00e9ment \u00e0 ce que les familles portent de plus profond en elles. Non pas seulement d\u2019une mani\u00e8re superficielle, mais en profondeur. Nous avons les instruments qu\u2019il nous faut mettre en oeuvre, qu\u2019il nous faut utiliser\u00a0: la psychologie, la sociologie, l\u2019\u00e9conomie&#8230; Il est s\u00fbr que nous n\u2019avons pas toutes les sciences infuses. Mais vouloir b\u00e2tir des hommes libres, c\u2019est les rendre ma\u00eetres des instruments dont les hommes se servent \u00e0 travers les temps pour cr\u00e9er un monde plus juste, un monde plus \u00e9galitaire o\u00f9 la paix soit v\u00e9cue non pas seulement comme un id\u00e9al, mais comme une r\u00e9alit\u00e9 entre les uns et les autres, parce que les uns et les autres font l\u2019exp\u00e9rience quotidienne, toujours renouvel\u00e9e et \u00e9valu\u00e9e de l\u2019amour entre eux tous.<\/p>\n<p>Pour conna\u00eetre, il nous faudra entendre, \u00e9couter et \u00e9crire. Si nous ne sommes pas seulement les gens de l\u2019\u00e9criture, de la lecture et de la parole, nous devons \u00eatre pourtant les gens de l\u2019\u00e9criture de la connaissance des familles. Nous devons \u00eatre les gens de la parole pour que les hommes que nous rencontrons soient entra\u00een\u00e9s \u00e0 lutter pour la justice pour les plus pauvres, pour que la justice soit vraiment r\u00e9tablie en terre de mis\u00e8re. Et puis nous devons aussi \u00e9norm\u00e9ment lire, nous former.<\/p>\n<p>Il faut aussi que notre temps appartienne \u00e0 la population. Il est normal que des travailleurs aient des vacances, il est normal que nous aussi nous ayons des vacances. Il n\u2019est pas normal que nous soyons r\u00e9ticents \u00e0 profiter de ce qui est n\u00e9cessaire aux autres pour se reposer. Pourtant, notre temps, c\u2019est comme pour ceux qui s\u2019aiment, notre temps ne nous appartient pas. Et si nous avons du temps pour nous, c\u2019est toujours pour nous enrichir de fa\u00e7on \u00e0 enrichir les plus pauvres.<\/p>\n<p>Faire conna\u00eetre la population donc, nous instruire personnellement, donner notre temps, pour ceux qui prient donner aussi notre pri\u00e8re. Car il est important que nous soyons dans un climat de spiritualit\u00e9. Quand je parle de spiritualit\u00e9, je ne parle d\u2019ailleurs pas d\u2019appartenir \u00e0 telle ou telle religion, quoiqu\u2019il est important que nous ayons une foi, sinon dans un Dieu, au moins dans les hommes. Mais nous avons l\u2019exigence de cr\u00e9er un climat de spiritualit\u00e9 parce que l\u2019esprit doit nous habiter.<\/p>\n<p>L\u2019esprit est une sorte de sens de l\u2019autre, une sorte de communion \u00e0 l\u2019autre qui fait que vraiment l\u2019autre, plus il est petit, plus il est faible, plus il est pour nous le plus important, le plus grand. Quand on parle de spiritualit\u00e9, cela nous ram\u00e8ne aussi au religieux, aux relations avec Dieu. On peut dire que c\u2019est la fine pointe de la spiritualit\u00e9, c\u2019est le summum. Mais nous avons \u00e0 vivre en tous les cas une spiritualit\u00e9 entre les hommes, ce qui veut dire une certaine mani\u00e8re de voir les hommes, de nous comporter avec eux. De m\u00eame que nous nous mettons en \u00e9tat de contemplation et de pri\u00e8re vis-\u00e0-vis de Dieu, que nous essayons de faire le silence, nous essayons de nous rapprocher le plus possible de Dieu, de faire un avec Lui. Quelqu\u2019un disait\u00a0: \u00ab\u00a0Je l\u2019avise et il m\u2019avise\u00a0\u00bb. Nous devons avoir la spiritualit\u00e9 de nos fr\u00e8res. C\u2019est-\u00e0-dire que nous devons arriver \u00e0 vivre d\u2019une certaine mani\u00e8re avec les autres, que les autres comptent pour nous, que nous nous identifions \u00e0 eux, parce qu\u2019ils sont comme nous. Ils m\u00e8nent exactement le m\u00eame combat, avec les m\u00eames difficult\u00e9s, avec aussi les m\u00eames doutes, les m\u00eames peines, les m\u00eames chagrins et aussi les m\u00eames espoirs et les m\u00eames joies. C\u2019est cela la spiritualit\u00e9. Nous vivons la spiritualit\u00e9 si nous arrivons \u00e0 nous apurer l\u2019esprit, si nous arrivons \u00e0 nous faire perdre ce qui est secondaire pour nous attacher \u00e0 ce qui est absolument l\u2019essentiel, l\u2019essentiel de nous-m\u00eames, l\u2019essentiel de l\u2019autre, l\u2019essentiel du combat, nous trouverons notre spiritualit\u00e9. La spiritualit\u00e9 c\u2019est aussi d\u2019avoir cette sorte de confiance que la fraternit\u00e9 est la base m\u00eame de la r\u00e9ussite de tous les combats. C\u2019est dans la mesure o\u00f9 les plus pauvres nous verront vraiment unis, nous aimant vraiment, qu\u2019ils nous suivront.<\/p>\n<p>Ce sont les pauvres qui nous r\u00e9unissent. Pour ceux qui croient, c\u2019est le Christ qui s\u2019approche de nous quand nous nous rapprochons des pauvres. C\u2019est le Christ qui parle avec nous, quand nous parlons aux pauvres, lui qui sent ce que nous sentons, qui porte avec les pauvres le poids de la mis\u00e8re, de la souffrance. C\u2019est cela que j\u2019appelais la spiritualit\u00e9 pour ceux qui ont la Foi.<\/p>\n<p>Pour nous tous, je pense que nous pouvons dire que ce qui nous r\u00e9unit, c\u2019est le pauvre et c\u2019est le plus pauvre, le plus souffrant, le plus d\u00e9laiss\u00e9, le plus rejet\u00e9, le plus abandonn\u00e9. Alors de m\u00eame, quand nous disons que nous sommes volontaires, ce n\u2019est pas simplement un \u00e9tat que nous acceptons ou que nous choisissons un \u00e9tat d\u2019\u00eatre \u00e0 la merci des plus pauvres pour apprendre d\u2019eux, parfois avec beaucoup d\u2019\u00e9tonnement. Certes, nous avons renonc\u00e9 \u00e0 une promotion personnelle, \u00e0 une r\u00e9ussite, mais \u00eatre volontaires, cela veut dire beaucoup plus. Cela veut dire que, des pauvres, nous avons fait nos fr\u00e8res et nos soeurs. Leurs enfants sont nos enfants. Et nous vivons en perp\u00e9tuelle communion avec eux. Ils sont pr\u00e9sents \u00e0 nous et en nous. Nous les reconnaissons et nous les contemplons, dans le sens que nous les consid\u00e9rons comme \u00e9tant nos ma\u00eetres, comme \u00e9tant notre angoisse, notre peine, notre souci. Le souci de leur lib\u00e9ration nous habite en permanence. Notre spiritualit\u00e9 c\u2019est cela\u00a0: \u00eatre en esprit, avoir notre esprit saisi par la population, et que tout ce que nous faisons, tout ce que nous disons, soit une chance pour la population.<\/p>\n<p>J\u2019ai confiance.<\/p>\n<p>P\u00e8re Joseph<\/p>\n<p>\u00a9 Mouvement ATD Quart Monde, Pierrelaye, France<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce message adress\u00e9 aux volontaires a \u00e9t\u00e9 enregistr\u00e9 par le p\u00e8re Joseph Wresinski \u00e0 l\u2019H\u00f4pital Foch, le 8 f\u00e9vrier 1988,\u00e0 (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[33,49],"tags":[],"class_list":["post-287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-correspondance","category-ecrits"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aux Volontaires. - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aux Volontaires. - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"Ce message adress\u00e9 aux volontaires a \u00e9t\u00e9 enregistr\u00e9 par le p\u00e8re Joseph Wresinski \u00e0 l\u2019H\u00f4pital Foch, le 8 f\u00e9vrier 1988,\u00e0 (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-19T13:30:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-15T21:03:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Aux Volontaires.\",\"datePublished\":\"2007-07-19T13:30:28+00:00\",\"dateModified\":\"2018-03-15T21:03:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/\"},\"wordCount\":1924,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/Lettre-cassette.jpg\",\"articleSection\":[\"Correspondance\",\"Ecrits\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/\",\"name\":\"Aux Volontaires. - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/Lettre-cassette.jpg\",\"datePublished\":\"2007-07-19T13:30:28+00:00\",\"dateModified\":\"2018-03-15T21:03:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/Lettre-cassette.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/Lettre-cassette.jpg\",\"width\":700,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/aux-volontaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aux Volontaires.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aux Volontaires. - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Aux Volontaires. - Joseph Wresinski FR","og_description":"Ce message adress\u00e9 aux volontaires a \u00e9t\u00e9 enregistr\u00e9 par le p\u00e8re Joseph Wresinski \u00e0 l\u2019H\u00f4pital Foch, le 8 f\u00e9vrier 1988,\u00e0 (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2007-07-19T13:30:28+00:00","article_modified_time":"2018-03-15T21:03:17+00:00","og_image":[{"width":700,"height":460,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmestre","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Aux Volontaires.","datePublished":"2007-07-19T13:30:28+00:00","dateModified":"2018-03-15T21:03:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/"},"wordCount":1924,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg","articleSection":["Correspondance","Ecrits"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/","name":"Aux Volontaires. - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg","datePublished":"2007-07-19T13:30:28+00:00","dateModified":"2018-03-15T21:03:17+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/Lettre-cassette.jpg","width":700,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/aux-volontaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Aux Volontaires."}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=287"}],"version-history":[{"count":5,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/287\/revisions"}],"predecessor-version":[{"id":1542,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/287\/revisions\/1542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/1454"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}