{"id":305,"date":"2007-07-10T19:52:58","date_gmt":"2007-07-10T17:52:58","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/2007\/07\/10\/pourquoi-raviver-des-souffrances\/"},"modified":"2021-05-19T14:11:51","modified_gmt":"2021-05-19T12:11:51","slug":"pourquoi-raviver-des-souffrances","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/","title":{"rendered":"Raviver des souffrances endormies ?"},"content":{"rendered":"<p>\u00ab\u00a0Ce fut une question de confiance pour la famille Geva d\u2019accepter de nous raconter l\u2019histoire des siens, depuis sept g\u00e9n\u00e9rations.<\/p>\n<p>Non pas que Monsieur et Madame Geva avaient honte de leurs anc\u00eatres, mais pourquoi raviver des souffrances endormies, pourquoi faire revivre les labeurs et l\u2019usure de la mine, l\u2019\u00e9puisement des travaux de ferme et dans les carri\u00e8res&#8230;<\/p>\n<p>Leurs anc\u00eatres ont tant pein\u00e9 et travaill\u00e9 qu\u2019aucun d\u2019eux n\u2019allait vivre au-del\u00e0 de 40 ans. Ils ont connu tant de privations et d\u2019ignominies que les enfants qui survivaient n\u2019\u00e9taient que les rescap\u00e9s de nombreux enfants morts en bas \u00e2ge.<\/p>\n<p>Aujourd\u2019hui, la mis\u00e8re est moins criarde pour Paul Geva et n\u2019est-il pas le seul de sa lign\u00e9e qui connaisse ses petits enfants et qui tente de leur transmettre l\u2019image d\u2019un monde o\u00f9 les travailleurs seront respect\u00e9s, o\u00f9 la justice sera fraternelle pour tous, o\u00f9 l\u2019instruction et le m\u00e9tier seront l\u2019h\u00e9ritage de tous, o\u00f9 la solidarit\u00e9 jouera \u00e0 plein au plus bas de l\u2019\u00e9chelle sociale.<\/p>\n<p>H\u00e9ritier d\u2019un Quart Monde d\u2019honneur et de courage, Monsieur Geva a h\u00e9sit\u00e9 longtemps \u00e0 nous montrer ses lettres de noblesse. Il l\u2019a fait gr\u00e2ce \u00e0 la confiance qu\u2019il porte \u00e0 Madame Rabier.<\/p>\n<p>Ce fut aussi un cas de conscience pour lui d\u2019accepter que soit publi\u00e9 ce r\u00e9cit. Qui s\u2019en servira\u00a0? Qui l\u2019exploitera\u00a0? Pour qui\u00a0? Pour quoi faire\u00a0? Puis il s\u2019est convaincu qu\u2019il ne pouvait se taire, qu\u2019il devait parler, car des millions de laiss\u00e9s pour compte doivent savoir qu\u2019ils sont des hommes, que tous les citoyens doivent le reconna\u00eetre et nouer avec les plus d\u00e9favoris\u00e9s des liens de solidarit\u00e9.<\/p>\n<p>Ainsi, aujourd\u2019hui, il nous parle pour restituer aux sous-prol\u00e9taires leur honneur de travailleurs, mais aussi pour nous transmettre le message des pauvres. Parce qu\u2019elle atteint la dignit\u00e9 de ceux qui la supportent, la mis\u00e8re est le mal absolu et le seul combat qui vaille est de la d\u00e9truire\u00a0\u00bb.<\/p>\n<p style=\"text-align: right\">Joseph Wresinski<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Ce fut une question de confiance pour la famille Geva d\u2019accepter de nous raconter l\u2019histoire des siens, depuis sept g\u00e9n\u00e9rations. (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2698,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[49,65],"tags":[],"class_list":["post-305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecrits","category-editoriaux-et-prefaces"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raviver des souffrances endormies ? - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raviver des souffrances endormies ? - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"\u00ab\u00a0Ce fut une question de confiance pour la famille Geva d\u2019accepter de nous raconter l\u2019histoire des siens, depuis sept g\u00e9n\u00e9rations. (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-10T17:52:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-19T12:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Raviver des souffrances endormies ?\",\"datePublished\":\"2007-07-10T17:52:58+00:00\",\"dateModified\":\"2021-05-19T12:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/\"},\"wordCount\":359,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/1200x680_colporteur-518020674.jpg\",\"articleSection\":[\"Ecrits\",\"Editoriaux et pr\u00e9faces\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/\",\"name\":\"Raviver des souffrances endormies ? - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/1200x680_colporteur-518020674.jpg\",\"datePublished\":\"2007-07-10T17:52:58+00:00\",\"dateModified\":\"2021-05-19T12:11:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/1200x680_colporteur-518020674.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/1200x680_colporteur-518020674.jpg\",\"width\":1200,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/pourquoi-raviver-des-souffrances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raviver des souffrances endormies ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raviver des souffrances endormies ? - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/","og_locale":"fr_FR","og_type":"article","og_title":"Raviver des souffrances endormies ? - Joseph Wresinski FR","og_description":"\u00ab\u00a0Ce fut une question de confiance pour la famille Geva d\u2019accepter de nous raconter l\u2019histoire des siens, depuis sept g\u00e9n\u00e9rations. (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2007-07-10T17:52:58+00:00","article_modified_time":"2021-05-19T12:11:51+00:00","og_image":[{"width":1200,"height":680,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmestre","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Raviver des souffrances endormies ?","datePublished":"2007-07-10T17:52:58+00:00","dateModified":"2021-05-19T12:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/"},"wordCount":359,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg","articleSection":["Ecrits","Editoriaux et pr\u00e9faces"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/","name":"Raviver des souffrances endormies ? - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg","datePublished":"2007-07-10T17:52:58+00:00","dateModified":"2021-05-19T12:11:51+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/1200x680_colporteur-518020674.jpg","width":1200,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/pourquoi-raviver-des-souffrances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Raviver des souffrances endormies ?"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=305"}],"version-history":[{"count":4,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/305\/revisions"}],"predecessor-version":[{"id":3594,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/305\/revisions\/3594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/2698"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}