{"id":307,"date":"2007-07-10T12:50:36","date_gmt":"2007-07-10T10:50:36","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/2007\/07\/10\/retrouver-son-identite\/"},"modified":"2020-09-25T18:26:33","modified_gmt":"2020-09-25T16:26:33","slug":"retrouver-son-identite","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/","title":{"rendered":"Retrouver son identit\u00e9"},"content":{"rendered":"<p><i>En 1987, le p\u00e8re Joseph Wresinski s\u2019adressait aux historiens dans le cadre d\u2019une session organis\u00e9e par l\u2019Institut de recherche et de formation aux relations humaines\u00a0: \u00ab\u00a0Le Quart Monde partenaire de l\u2019histoire\u00a0\u00bb. Ce texte a \u00e9t\u00e9 publi\u00e9 dans les Dossiers et documents de la Revue Quart Monde, n\u00b0\u00a01, 1988. Cet appel \u00e0 l\u2019\u00e9criture d\u2019une v\u00e9ritable histoire de la pauvret\u00e9, m\u00eame s\u2019il a \u00e9t\u00e9 partiellement entendu, reste d\u2019une urgente actualit\u00e9. <\/i><\/p>\n<p><strong> Retrouver son identit\u00e9<\/strong><\/p>\n<p>Le souci que les plus pauvres retrouvent leur identit\u00e9 par leur histoire est ancien dans le Mouvement ATD Quart Monde. Depuis maintenant plus de vingt cinq ans, nous nous effor\u00e7ons de recueillir les t\u00e9moignages sur la vie des pauvres et surtout les t\u00e9moignages que les pauvres eux-m\u00eames nous donnent sur leur vie d\u2019une mani\u00e8re ou d\u2019une autre. Cet effort doit permettre de conscientiser les sous-prol\u00e9taires de fa\u00e7on \u00e0 ce que munis d\u2019une identit\u00e9, ils puissent s\u2019affirmer comme agents actifs au sein de nos soci\u00e9t\u00e9s modernes et de d\u00e9truire la mis\u00e8re.<\/p>\n<p>Savoir d\u2019o\u00f9 l\u2019on vient est une mani\u00e8re de retrouver son identit\u00e9 et de l\u2019affirmer aux yeux des autres, dit Madame Michelle Perrot. Savoir d\u2019o\u00f9 l\u2019on vient, s\u2019introduire dans un lignage, s\u2019assurer des s\u00e9curit\u00e9s int\u00e9rieures et personnelles, c\u2019est donner une force aux groupes dans lesquels on vit, c\u2019est se permettre de s\u2019exprimer \u00e0 l\u2019int\u00e9rieur et surtout de s\u2019affirmer \u00e0 l\u2019ext\u00e9rieur de ces groupes.<\/p>\n<p>Notre tentative consiste \u00e0 redonner l\u2019histoire aux pauvres mais, aussi l\u2019histoire des plus pauvres \u00e0 la soci\u00e9t\u00e9, afin, que la soci\u00e9t\u00e9 en tienne compte pour les ann\u00e9es et m\u00eame les si\u00e8cles \u00e0 venir, afin qu\u2019elle ne recommence pas les erreurs qu\u2019elle a commises. Ce que nous avons vu ces derni\u00e8res ann\u00e9es des mesures prises \u00e0 propos de ce que l\u2019on appelle, ind\u00fbment, les nouveaux pauvres, montre l\u2019\u00e9chec extr\u00eamement grave d\u2019une soci\u00e9t\u00e9 qui ne sait pas traiter avec dignit\u00e9 et grandeur ses travailleurs les plus pauvres. Mais cette soci\u00e9t\u00e9 a \u00e9t\u00e9 mal servie par les sociologues, les humanistes, les d\u00e9fenseurs des droits de l\u2019homme, les pr\u00eatres et le monde religieux. Notre soci\u00e9t\u00e9 attendait d\u2019eux l\u2019appel de la dignit\u00e9 des pauvres, de la reconnaissance des pauvres et cela, les scientifiques, les universitaires, le monde social, politique et syndical ne le lui ont pas donn\u00e9.<\/p>\n<p>Cette tentative nous ne pouvons pas l\u2019assumer si des scientifiques ne nous accompagnent pas, ne nous parrainent pas, aussi bien au niveau de la sociologie que de la psychologie, de l\u2019\u00e9conomie, des droits de l\u2019homme et de la religion. Nous ne pouvons pas risquer l\u2019amateurisme.<\/p>\n<p>Les plus pauvres nous ont parrain\u00e9s. Cela fait maintenant vingt ans qu\u2019ils acceptent de nous dire leur vie. Ils nous la racontent dans le partage que nous faisons avec eux des pr\u00e9occupations qui sont les leurs et sont aussi les n\u00f4tres. Or nous ne sommes pas des chercheurs, nous sommes des volontaires, nous ne sommes pas des travailleurs sociaux ni scientifiques mais des volontaires, et le danger qui nous guette est de faire de la pseudo-science historique.<\/p>\n<p>Il serait tr\u00e8s grave que nous nous enfermions et que nous enfermions les sous-prol\u00e9taires dans une histoire mal d\u00e9cod\u00e9e. Il n\u2019est pas grave pour Oscar Lewis, qui a \u00e9crit la vie de la famille Sanchez, de dire qu\u2019il y a une culture de la pauvret\u00e9. Ce n\u2019est pas grave pour lui, ni pour les historiens\u00a0; c\u2019est tr\u00e8s grave pour nous. Ce serait grave si nous faisions un cheminement avec les familles sur une fausse science. De m\u00eame qu\u2019il ne faudrait pas que dans le domaine de l\u2019histoire nous donnions \u00e0 la soci\u00e9t\u00e9 l\u2019occasion de se tromper sur les pauvres. Il est temps que nous fassions l\u2019histoire de la pauvret\u00e9 en sachant que la pauvret\u00e9 est le lieu d\u2019une stratification absolument inconnue.<\/p>\n<p>Par quelque bout que nous prenions le monde de la pauvret\u00e9 quand nous le p\u00e9n\u00e9trons, nous d\u00e9couvrons une richesse insoup\u00e7onnable, des valeurs v\u00e9cues compl\u00e8tement cach\u00e9es, ignor\u00e9es, nous rencontrons des clivages dans tous les domaines, le pouvoir de la haine, l\u2019amour et le besoin de libert\u00e9. Le monde de la mis\u00e8re est une terre absolument inconnue.<\/p>\n<p>Nous avons la responsabilit\u00e9 en rendant l\u2019histoire \u00e0 la population de lui rendre l\u2019histoire authentique de fa\u00e7on \u00e0 ce qu\u2019elle ne se b\u00e2tisse pas sur de l\u2019\u00e0 peu pr\u00e8s historique. On ne b\u00e2tit pas un avenir sur des fables.<\/p>\n<p>Je demande le concours de ceux qui sont des scientifiques de l\u2019histoire, je le leur demande r\u00e9ellement avec beaucoup de chaleur et d\u2019insistance. La population a besoin d\u2019eux pour que nous ne la trompions pas. Nous devons avoir un tr\u00e8s grand respect quand nous la contactons et que nous sollicitons son dire sur sa propre histoire.<\/p>\n<p>Si vous entreprenez cette d\u00e9marche-l\u00e0 et si le Mouvement ATD Quart Monde peut y apporter quelque chose, que ce soit, les uns et les autres, avec beaucoup d\u2019humilit\u00e9. Dans une telle d\u00e9marche, les pauvres ont peut-\u00eatre beaucoup plus besoin de notre part d\u2019humilit\u00e9 que de justice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1987, le p\u00e8re Joseph Wresinski s\u2019adressait aux historiens dans le cadre d\u2019une session organis\u00e9e par l\u2019Institut de recherche et (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[49,65],"tags":[],"class_list":["post-307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecrits","category-editoriaux-et-prefaces"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retrouver son identit\u00e9 - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrouver son identit\u00e9 - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"En 1987, le p\u00e8re Joseph Wresinski s\u2019adressait aux historiens dans le cadre d\u2019une session organis\u00e9e par l\u2019Institut de recherche et (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2007-07-10T10:50:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-25T16:26:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"Retrouver son identit\u00e9\",\"datePublished\":\"2007-07-10T10:50:36+00:00\",\"dateModified\":\"2020-09-25T16:26:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/\"},\"wordCount\":915,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/julien_pierre_Wordle-550x350-1.jpg\",\"articleSection\":[\"Ecrits\",\"Editoriaux et pr\u00e9faces\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/\",\"name\":\"Retrouver son identit\u00e9 - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/julien_pierre_Wordle-550x350-1.jpg\",\"datePublished\":\"2007-07-10T10:50:36+00:00\",\"dateModified\":\"2020-09-25T16:26:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/julien_pierre_Wordle-550x350-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2007\\\/07\\\/julien_pierre_Wordle-550x350-1.jpg\",\"width\":550,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/retrouver-son-identite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrouver son identit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrouver son identit\u00e9 - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/","og_locale":"fr_FR","og_type":"article","og_title":"Retrouver son identit\u00e9 - Joseph Wresinski FR","og_description":"En 1987, le p\u00e8re Joseph Wresinski s\u2019adressait aux historiens dans le cadre d\u2019une session organis\u00e9e par l\u2019Institut de recherche et (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2007-07-10T10:50:36+00:00","article_modified_time":"2020-09-25T16:26:33+00:00","og_image":[{"width":550,"height":350,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmestre","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"Retrouver son identit\u00e9","datePublished":"2007-07-10T10:50:36+00:00","dateModified":"2020-09-25T16:26:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/"},"wordCount":915,"commentCount":2,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg","articleSection":["Ecrits","Editoriaux et pr\u00e9faces"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/","name":"Retrouver son identit\u00e9 - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg","datePublished":"2007-07-10T10:50:36+00:00","dateModified":"2020-09-25T16:26:33+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2007\/07\/julien_pierre_Wordle-550x350-1.jpg","width":550,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/retrouver-son-identite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Retrouver son identit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=307"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/307\/revisions"}],"predecessor-version":[{"id":2697,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/307\/revisions\/2697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/2696"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}