{"id":4024,"date":"2022-03-17T13:21:25","date_gmt":"2022-03-17T12:21:25","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/fr\/?p=4024"},"modified":"2022-03-17T13:21:25","modified_gmt":"2022-03-17T12:21:25","slug":"jamais-plus-un-oiseau-mort-comme-signe-de-detresse","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/","title":{"rendered":"Jamais plus un oiseau mort comme signe de d\u00e9tresse"},"content":{"rendered":"<p>Il est un \u00e9v\u00e9nement de mon enfance<br \/>\nqui eut un profond retentissement dans ma vie.<br \/>\nC\u2019\u00e9tait une \u00e9poque o\u00f9 la mis\u00e8re s\u2019\u00e9tait abattue chez nous.<br \/>\nQuelles en \u00e9taient les causes ?<br \/>\nJe les ignore \u00e0 pr\u00e9sent :<br \/>\nelles se sont enfouies avec combien d\u2019autres souvenirs<br \/>\nau fond de ma conscience d\u2019homme,<br \/>\npour faire la trame de ces mille choses<br \/>\nqui s\u2019agitent en nous<br \/>\net qui s\u2019appellent peine, souffrance, stupeur, d\u00e9sespoir.<\/p>\n<p>Ce qui me reste et resurgit souvent,<br \/>\nme rappelant nos angoisses d\u2019enfant, c\u2019est un oiseau mort.<br \/>\nC\u2019\u00e9tait un chardonneret.<br \/>\nNous l\u2019avions recueilli mon fr\u00e8re et moi,<br \/>\nun matin apr\u00e8s la messe matinale que j\u2019allais servir,<br \/>\ndepuis l\u2019\u00e2ge de cinq ans, hiver comme \u00e9t\u00e9,<br \/>\nau bas de la rue Brault,<br \/>\n\u00e0 cet endroit o\u00f9 la mont\u00e9e de la Maine,<br \/>\nrefluant les eaux par les \u00e9gouts,<br \/>\ninondait les jardins et les b\u00e2timents bas du Bon-Pasteur.<\/p>\n<p>Cet oiseau sans doute s\u2019\u00e9tait enfui d\u2019une cage.<br \/>\nIl \u00e9tait bless\u00e9 et il s\u2019\u00e9tait laiss\u00e9 prendre sans se d\u00e9battre.<br \/>\nIl \u00e9tait devenu notre ami sans d\u00e9monstration ni d\u00e9bordement,<br \/>\n\u00e0 la mani\u00e8re des pauvres qui re\u00e7oivent et ne savent<br \/>\ncomment se comporter pour dire merci.<\/p>\n<p>Vinrent donc des jours o\u00f9 nous \u00e9tions tous tr\u00e8s malheureux.<br \/>\nMaman d\u00e9laissait la marche de notre maison,<br \/>\nque jusqu\u2019ici elle avait d\u00e9fendu de devenir un taudis :<br \/>\n\u00ab Range ceci, range\u00a0 cela, balaye,<br \/>\npousse-toi que je nettoie la table\u2026 \u00bb<\/p>\n<p>L\u2019unique table o\u00f9 maman pr\u00e9parait les l\u00e9gumes, les repas,<br \/>\nd\u00e9posait la vaisselle, dressait le couvert,<br \/>\no\u00f9 nous faisions nos devoirs le soir,<br \/>\no\u00f9 nous lisions \u2013, ce qui l\u2019aga\u00e7ait :<br \/>\n\u00ab N\u2019as-tu pas fini de lire quand il y a tant de travail ! \u00bb<\/p>\n<p>Pauvre m\u00e8re ! Apr\u00e8s le repas du soir et le jeudi,<br \/>\nnous enfilions notre ration de papier \u00e0 cigarettes Zig-Zag<br \/>\ndans leur \u00e9tui de carton afin de gagner ensemble quelque argent.<br \/>\nEst-ce de ce temps que me suit la naus\u00e9e du tabac<br \/>\net de tout ce qui s\u2019y rapporte ?<\/p>\n<p>Or, en ces jours, nous ne faisions m\u00eame plus ce travail.<br \/>\nLe soir, nous restions l\u00e0,<br \/>\navant d\u2019aller dormir, sans oser dire un mot,<br \/>\ncomme si notre voix allait provoquer d\u2019autres catastrophes.<br \/>\nAllions-nous encore \u00e0 l\u2019\u00e9cole\u00a0? Je ne sais plus.<br \/>\nJe me rappelle seulement mon petit fr\u00e8re Martin<br \/>\nqui ne faisait que pleurer.<br \/>\nIl semblait que le temps s\u2019\u00e9tait arr\u00eat\u00e9 pour nous,<br \/>\nque rien ne comptait plus.<br \/>\nNous \u00e9tions comme si nous \u00e9tions morts.<br \/>\nNous survivions au jour le jour.<\/p>\n<p>Combien ce temps a-t-il dur\u00e9 ?<br \/>\nPeu sans doute mais il \u00e9tait tellement intense et terrible<br \/>\nqu\u2019il prend dans mon souvenir<br \/>\nune place exceptionnellement grande.<br \/>\nOui, sans doute n\u2019a-t-il dur\u00e9 que quelques jours.<br \/>\nSinon\u00a0 les gosses que nous \u00e9tions auraient \u00e9clat\u00e9 malgr\u00e9 tout,<br \/>\net nous nous serions \u00e9chapp\u00e9s de la souffrance de maman.<br \/>\nPeut-\u00eatre d\u2019ailleurs<br \/>\nnous en \u00e9chappions-nous \u00e0 certains moments.<\/p>\n<p>Puis un jour, le soleil est revenu,<br \/>\ndans cette pi\u00e8ce o\u00f9 nous vivions<br \/>\net que, m\u00eame l\u2019\u00e9t\u00e9, l\u2019ombre envahissait \u00e0 quatre heures.<br \/>\nComment s\u2019est-il montr\u00e9\u00a0?<br \/>\nEst-ce par une bonne nouvelle, un don, une parole gentille ?<br \/>\nJe ne le sais plus.<br \/>\nMais le temps suivait, \u00e0 nouveau, son cours normal,<br \/>\nla vie reprenait tout doucement, \u2013 tout redevenait comme avant.<\/p>\n<p>C\u2019est \u00e0 ce moment que nous avons remarqu\u00e9<br \/>\nque l\u2019oiseau ne chantait plus.<br \/>\nNous regardions en silence vers cette cage,<br \/>\ncet ami envers qui nous nous sentions coupables de n\u00e9gligence.<br \/>\nPourquoi l\u2019avions-nous d\u00e9laiss\u00e9 ?<br \/>\nEst-ce parce qu\u2019en ces temps de d\u00e9tresse,<br \/>\nil ne pouvait rien nous apporter ?<br \/>\nN\u2019est-ce pas plut\u00f4t parce que,<br \/>\nquand la douleur est trop grande,<br \/>\ntout s\u2019arr\u00eate, le temps, les sentiments, le Bon Dieu :<br \/>\n\u00ab S\u2019Il existait ! Non, c\u2019est mieux qu\u2019Il n\u2019existe pas,<br \/>\ncar nous devrions le maudire \u00bb,<br \/>\nme disait Madame Duburguois.<\/p>\n<p>L\u2019oiseau, lui, \u00e9tait mort.<br \/>\nIl \u00e9tait mort de faim,<br \/>\npour lui aussi la vie s\u2019\u00e9tait arr\u00eat\u00e9e, nous l\u2019avions oubli\u00e9.<br \/>\nComme nous avions omis de nous laver,<br \/>\nde manger, de parler, de prier.<\/p>\n<p>Apparemment, l\u2019heure de malheur \u00e9tait pass\u00e9e,<br \/>\nmais tout devait se remettre en place.<br \/>\nIl a fallu que maman progressivement<br \/>\nreprenne son r\u00f4le de m\u00e8re sans inqui\u00e9tude, de m\u00e8re assur\u00e9e.<br \/>\n\u00catres et choses devaient reprendre leur place.<br \/>\nLes relations avec les voisins,<br \/>\nles mots que notre m\u00e8re avait peut-\u00eatre dits en trop,<br \/>\nil a fallu petit \u00e0 petit qu\u2019elle les retire.<br \/>\nM\u00eame vis-\u00e0-vis de ses enfants, les agacements,<br \/>\nles incompr\u00e9hensions<br \/>\nqui \u00e9taient n\u00e9s pendant ce temps-l\u00e0 devaient s\u2019oublier.<\/p>\n<p>Nous-m\u00eames, nous retrouvions le chemin de l\u2019\u00e9cole,<br \/>\ncelui de la messe matinale.<br \/>\nNous reprenions nos Zig-Zag.<br \/>\nNous devions ne plus oublier notre pri\u00e8re.<br \/>\nIl nous fallait nous laver et ne pas encombrer la table.<br \/>\nIl fallut que nous recr\u00e9ions la vie d\u2019hier.<\/p>\n<p>Mais est-ce que l\u2019on peut renouer ainsi,<br \/>\nlorsque des circonstances semblables se renouvellent trop souvent<br \/>\ncomme c\u2019est le cas pour les pauvres ?<br \/>\nComment repartir toujours \u00e0 nouveau<br \/>\napr\u00e8s ces arr\u00eats dans le temps<br \/>\ndont le symbole est rest\u00e9 dans ma m\u00e9moire<br \/>\nen cet oiseau mort au fond de sa cage,<br \/>\nles petites pattes recroquevill\u00e9es en l\u2019air,<br \/>\ncomme si elles \u00e9taient les signes tangibles de ces malheurs<br \/>\n\u00e0 peine cicatris\u00e9s et d\u00e9j\u00e0 resurgis.<\/p>\n<p>Lorsque continuellement, le temps s\u2019arr\u00eate brusquement,<br \/>\nque les \u00e9v\u00e9nements laissent de si profondes traces,<br \/>\nest-il possible de juger des choses et des \u00eatres<br \/>\ncomme tout le monde,<br \/>\nde rattraper le temps perdu,<br \/>\nde remettre tout en ordre et tout en place ?<br \/>\nEst-il possible de croire \u00e0 un ordre de\u00a0 vie,<br \/>\nde b\u00e2tir sa vie, de vivre ?<br \/>\nA moins de rencontrer de grands amours aupr\u00e8s de soi,<br \/>\nje ne le pense pas.<\/p>\n<p>En \u00e9crivant ces derniers mots, je ne puis m\u2019\u00e9viter<br \/>\nde penser \u00e0 l\u2019amour que le Christ a offert aux d\u00e9munis.<br \/>\nPour qu\u2019ils le partagent avec Lui, Il s\u2019est identifi\u00e9 \u00e0 eux,<br \/>\nIl s\u2019est rendu pr\u00e9sent \u00e0 leur vie,<br \/>\nIl a particip\u00e9 \u00e0 leur condition.<br \/>\nC\u2019est ainsi que Lui, L\u2019\u00c9ternel, est entr\u00e9 dans le temporel.<br \/>\nLui aussi a connu ce temps-l\u00e0 qui s\u2019interrompt,<br \/>\ns\u2019arr\u00eate par les drames, les catastrophes,<br \/>\nles angoisses incessantes.<br \/>\nIl s\u2019est retrouv\u00e9 comme mort dans le pr\u00e9sent des mis\u00e9rables.<br \/>\nPar chaque drame, chaque catastrophe,<br \/>\ngr\u00e2ce aux attaques et aux coups bas,<br \/>\nil s\u2019est identifi\u00e9 davantage aux pauvres<br \/>\njusqu\u2019\u00e0 ce qu\u2019au Golgotha,<br \/>\nil devienne le premier parmi les souffrants.<br \/>\nC\u2019est \u00e0 cette heure-l\u00e0 que l\u2019amour a vaincu la mis\u00e8re<br \/>\net que les pauvres ont \u00e9t\u00e9 introduits dans l\u2019\u00c9ternit\u00e9.<br \/>\nC\u2019est pourquoi d\u00e9sormais \u2013 sur la terre comme au ciel \u2013,<br \/>\nle Christ ne sera jamais plus seul :<br \/>\nL\u2019accueillir, ce sera les accueillir tous,<br \/>\nL\u2019aider sera les aider tous, L\u2019aimer sera les aimer tous.<\/p>\n<p>Mes amis, qui que nous soyons, nous proclamons l\u2019amour.<br \/>\nNous savons que seul il cr\u00e9era<br \/>\nun temps nouveau pour les malheureux,<br \/>\net, que gr\u00e2ce \u00e0 lui, jamais plus un seul homme, d\u00e9j\u00e0 vieilli,<br \/>\nn\u2019oubliera qu\u2019un jour de d\u00e9tresse,<br \/>\nle temps s\u2019est arr\u00eat\u00e9 pour lui et les siens,<br \/>\net que le signe de cet arr\u00eat \u00e9tait un oiseau mort.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est un \u00e9v\u00e9nement de mon enfance qui eut un profond retentissement dans ma vie. C\u2019\u00e9tait une \u00e9poque o\u00f9 la (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,49,62],"tags":[],"class_list":["post-4024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-ecrits","category-extraits-de-livres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"Il est un \u00e9v\u00e9nement de mon enfance qui eut un profond retentissement dans ma vie. C\u2019\u00e9tait une \u00e9poque o\u00f9 la (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-17T12:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"1065\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Jamais plus un oiseau mort comme signe de d\u00e9tresse\",\"datePublished\":\"2022-03-17T12:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/\"},\"wordCount\":1247,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg\",\"articleSection\":[\"Actualit\u00e9s\",\"Ecrits\",\"Extraits de livres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/\",\"name\":\"Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg\",\"datePublished\":\"2022-03-17T12:21:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg\",\"width\":795,\"height\":1065},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jamais plus un oiseau mort comme signe de d\u00e9tresse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/","og_locale":"fr_FR","og_type":"article","og_title":"Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR","og_description":"Il est un \u00e9v\u00e9nement de mon enfance qui eut un profond retentissement dans ma vie. C\u2019\u00e9tait une \u00e9poque o\u00f9 la (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2022-03-17T12:21:25+00:00","og_image":[{"width":795,"height":1065,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean Tonglet","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Jamais plus un oiseau mort comme signe de d\u00e9tresse","datePublished":"2022-03-17T12:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/"},"wordCount":1247,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg","articleSection":["Actualit\u00e9s","Ecrits","Extraits de livres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/","name":"Jamais plus un oiseau mort comme signe de d\u00e9tresse - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg","datePublished":"2022-03-17T12:21:25+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/01\/Female-American-Goldfinch-in-moulting-plumage.-Photo-by-Craig-Houghton.jpg","width":795,"height":1065},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/jamais-plus-un-oiseau-mort-comme-signe-de-detresse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Jamais plus un oiseau mort comme signe de d\u00e9tresse"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=4024"}],"version-history":[{"count":4,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4024\/revisions"}],"predecessor-version":[{"id":4029,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4024\/revisions\/4029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/4025"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=4024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=4024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=4024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}