{"id":4299,"date":"2023-04-21T00:00:30","date_gmt":"2023-04-20T22:00:30","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/fr\/?p=4299"},"modified":"2023-04-25T10:05:13","modified_gmt":"2023-04-25T08:05:13","slug":"la-justice-impossible","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/","title":{"rendered":"La justice impossible"},"content":{"rendered":"<p>Toute d\u00e9marche est plus compliqu\u00e9e quand on est dans une situation perp\u00e9tuellement changeante, qu&rsquo;on vit dans un quartier \u00e9loign\u00e9 et mal desservi et qu&rsquo;on ignore le monde qui, lui, ne vous conna\u00eet pratiquement que quand vous le g\u00eanez. Pour faire valoir ses droits, il faut les conna\u00eetre, il faut savoir se d\u00e9fendre ou trouver des d\u00e9fenseurs, il faut savoir s&rsquo;exprimer. Pour faire valoir ses droits, il faut aussi se savoir et pouvoir \u00eatre responsable de son avenir et de celui de sa famille. Il faut se reconna\u00eetre, de droit, une place \u00e0 part enti\u00e8re dans la communaut\u00e9 des hommes. Nous avons vu que tout cela est impossible au Quart Monde qui vit dans la d\u00e9pendance, la vuln\u00e9rabilit\u00e9, les humiliations qui le font renoncer aux droits qu&rsquo;il pourrait faire valoir en s&rsquo;abaissant encore un peu plus.<\/p>\n<p>Ainsi ce p\u00e8re de famille dont la femme \u00e9tait d\u00e9c\u00e9d\u00e9e et qui, envers et contre tout, se battait pour \u00e9lever lui-m\u00eame son enfant. Travailleur non reconnu parce qu&rsquo;effectuant des besognes ingrates souvent clandestines, toujours pour des p\u00e9riodes tr\u00e8s courtes, il ne touchait pas les allocations familiales parce qu&rsquo;il ne s&rsquo;\u00e9tait pas d\u00e9clar\u00e9 en ch\u00f4mage. Pourtant, l&rsquo;assistante sociale venait le voir et essayait de r\u00e9gler sa situation. Mais lui r\u00e9pondait : \u00ab\u00a0Je n&rsquo;ai besoin de personne, je suis capable de me d\u00e9brouiller tout seul, je ne veux pas avoir de merci \u00e0 donner !\u00a0\u00bb<\/p>\n<p>Nous-m\u00eames ne comprenions pas ce refus de faire les d\u00e9marches n\u00e9cessaires pour obtenir ses droits. Pourtant, nous aurions pu deviner l&rsquo;humiliation que repr\u00e9sentait pour lui cette d\u00e9pendance envers l&rsquo;assistante sociale, envers le service de ch\u00f4mage. Nous aurions d\u00fb reconna\u00eetre et admirer ce dernier soubresaut d&rsquo;appel \u00e0 la dignit\u00e9, \u00e0 la reconnaissance du droit d&rsquo;\u00eatre un homme libre. \u00ab\u00a0Mieux vaut la faim que la honte\u00a0\u00bb&#8230;<\/p>\n<p>Dans tous ces domaines o\u00f9 l&rsquo;homme du Quart Monde n&rsquo;a pas la pleine possession des droits universellement reconnus \u00e0 tout homme, cette privation conduit \u00e0 une situation d&rsquo;indignit\u00e9 qui renforce encore son exclusion, qui le rejette plus loin encore dans l&rsquo;indigence et l&rsquo;ignorance. La privation du droit place l&rsquo;homme dans un univers o\u00f9 il n&rsquo;a prise sur rien, o\u00f9 il ne peut rencontrer personne, compter sur personne. Elle le conduit \u00e0 l&rsquo;ins\u00e9curit\u00e9 permanente et \u00e0 la peur.<\/p>\n<p>A cette peur, certains r\u00e9agissent par la violence, d&rsquo;autres par l&rsquo;enfermement et l&rsquo;abandon. Comme cette famille qui, au bout de sa longue cha\u00eene de malheurs, s&rsquo;\u00e9tait vu retirer, sur intervention des services sociaux, tous ses enfants sauf les trois derniers-n\u00e9s. D\u00e9sormais la cour est barricad\u00e9e. Quand on l&rsquo;appelle, Madame r\u00e9pond de derri\u00e8re la grille, sans l&rsquo;ouvrir. Quand elle doit sortir, elle enferme les enfants \u00e0 cl\u00e9, m\u00eame l&rsquo;a\u00een\u00e9 de 8 ans qui, temporairement revenu au foyer, ne va pas \u00e0 l&rsquo;\u00e9cole. La famille se retire elle-m\u00eame du monde, parachevant l&rsquo;exclusion qu&rsquo;on lui a toujours fait subir. Cette attitude devait provoquer un jour une descente de police, la d\u00e9molition des portes, l&rsquo;entr\u00e9e de force pour retirer les enfants qui restaient et les mettre, eux aussi, \u00e0 l&rsquo;assistance publique.<\/p>\n<p>D&rsquo;autres, nous le disions, r\u00e9agissent par la violence, certains par la boisson. Et le foss\u00e9 d&rsquo;incompr\u00e9hension et de rejet ne fait que s&rsquo;\u00e9largir, le monde environnant \u00e0 son tour prend peur et r\u00e9pond en \u00e9cartant un peu plus ceux qu&rsquo;elle avait d\u00e9j\u00e0 rejet\u00e9s. Ainsi se noue le cercle vicieux du non-droit et de l&rsquo;exclusion.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toute d\u00e9marche est plus compliqu\u00e9e quand on est dans une situation perp\u00e9tuellement changeante, qu&rsquo;on vit dans un quartier \u00e9loign\u00e9 et (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4298,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,49,62],"tags":[],"class_list":["post-4299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-ecrits","category-extraits-de-livres"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La justice impossible - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La justice impossible - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"Toute d\u00e9marche est plus compliqu\u00e9e quand on est dans une situation perp\u00e9tuellement changeante, qu&rsquo;on vit dans un quartier \u00e9loign\u00e9 et (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T22:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-25T08:05:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"771\" \/>\n\t<meta property=\"og:image:height\" content=\"590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"La justice impossible\",\"datePublished\":\"2023-04-20T22:00:30+00:00\",\"dateModified\":\"2023-04-25T08:05:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/\"},\"wordCount\":626,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg\",\"articleSection\":[\"Actualit\u00e9s\",\"Ecrits\",\"Extraits de livres\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/\",\"name\":\"La justice impossible - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg\",\"datePublished\":\"2023-04-20T22:00:30+00:00\",\"dateModified\":\"2023-04-25T08:05:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/04\\\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg\",\"width\":771,\"height\":590},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/la-justice-impossible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La justice impossible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La justice impossible - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/","og_locale":"fr_FR","og_type":"article","og_title":"La justice impossible - Joseph Wresinski FR","og_description":"Toute d\u00e9marche est plus compliqu\u00e9e quand on est dans une situation perp\u00e9tuellement changeante, qu&rsquo;on vit dans un quartier \u00e9loign\u00e9 et (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2023-04-20T22:00:30+00:00","article_modified_time":"2023-04-25T08:05:13+00:00","og_image":[{"width":771,"height":590,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean Tonglet","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"La justice impossible","datePublished":"2023-04-20T22:00:30+00:00","dateModified":"2023-04-25T08:05:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/"},"wordCount":626,"commentCount":1,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg","articleSection":["Actualit\u00e9s","Ecrits","Extraits de livres"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/","name":"La justice impossible - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg","datePublished":"2023-04-20T22:00:30+00:00","dateModified":"2023-04-25T08:05:13+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/04\/Eugene-Laermans-1864-1940-les-intrus-1903.jpg","width":771,"height":590},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/la-justice-impossible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"La justice impossible"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=4299"}],"version-history":[{"count":3,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4299\/revisions"}],"predecessor-version":[{"id":4307,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4299\/revisions\/4307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/4298"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=4299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=4299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=4299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}