{"id":44,"date":"2014-09-23T10:12:22","date_gmt":"2014-09-23T08:12:22","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/fr\/2014\/09\/23\/l-eglise-devant-les-pauvres\/"},"modified":"2021-05-27T09:39:55","modified_gmt":"2021-05-27T07:39:55","slug":"l-eglise-devant-les-pauvres","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/","title":{"rendered":"L\u2019Eglise devant les pauvres"},"content":{"rendered":"<p><i>&#8211; On parle des pauvres, mais il n\u2019y a pas de mot pour d\u00e9signer les gens dans la mis\u00e8re\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0On peut parler des plus d\u00e9munis, les communistes disent \u201c les plus d\u00e9favoris\u00e9s \u201d. C\u2019est vrai, on manque de pr\u00e9cision pour bien distinguer entre pauvret\u00e9 et mis\u00e8re, peut-\u00eatre parce qu\u2019on passe de l\u2019une \u00e0 l\u2019autre par toute une gamme d\u2019\u00e9checs et de d\u00e9ch\u00e9ances. L\u2019extr\u00eame mis\u00e8re est pourtant une situation tr\u00e8s particuli\u00e8re qui existe partout, mais cach\u00e9e dans un ensemble, le monde de la mis\u00e8re vit \u00e0 l\u2019int\u00e9rieur du monde des pauvres. <i><br \/>\n<img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Des bons pauvres\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Oui, on s\u2019int\u00e9resse aux bons pauvres bien m\u00e9ritants, bien dignes, et on fait l\u2019impasse sur les mis\u00e9reux, les gens pas int\u00e9ressants, douteux, feignants, dangereux, comme on se h\u00e2te de le dire pour s\u2019en \u00e9carter. Ceux qu\u2019on chasse des \u00e9glises \u00e0 cause de leur allure et de leur odeur. Un jour, \u00e0 Saint-Sulpice, pendant la communion, j\u2019ai vu un homme qui avan\u00e7ait en titubant, il \u00e9tait ivre. Je me suis dit\u00a0: \u201c Que va faire le pr\u00eatre\u00a0? \u201d Il lui a donn\u00e9 la communion, et tous l\u2019ont entour\u00e9 fraternellement. C\u2019est \u00e7a, des chr\u00e9tiens, c\u2019est \u00e7a la mis\u00e9ricorde, faire abstraction de tout pour ne voir dans un homme que son besoin de compr\u00e9hension, d\u2019indulgence. Cette sc\u00e8ne m\u2019a mieux fait comprendre la mis\u00e9ricorde de Dieu. On me dit\u00a0: \u201c Vous \u00eates complice de la paresse, du vice. \u201d Je suis le complice de Dieu, mais du Dieu que m\u2019ont fait conna\u00eetre ces plus pauvres. Et complice de l\u2019\u00c9glise qui les aime. <i><br \/>\n<img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0\u00c7a ne se voit pas toujours.<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Je n\u2019ai jamais rencontr\u00e9 un pr\u00eatre vraiment pr\u00eatre et un la\u00efc vraiment engag\u00e9 qui ne soient pas boulevers\u00e9s devant le monde de la mis\u00e8re et d\u00e9sireux de faire quelque chose. Ce n\u2019est pas une invention d\u2019aujourd\u2019hui, c\u2019est un h\u00e9ritage. D\u00e8s le d\u00e9but de l\u2019\u00c9glise on a eu le souci des pauvres. Bien plus qu\u2019un souci, une communion. Toutes ces congr\u00e9gations et ces institutions au service des plus mal vus de la soci\u00e9t\u00e9. Pas seulement pour les servir mais pour recevoir d\u2019eux quelque chose d\u2019inestimable\u00a0: ils maintiennent l\u2019\u00c9glise en \u00e9tat d\u2019amour et d\u2019humilit\u00e9.<\/p>\n<p><i>-D\u2019 humilit\u00e9\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Elle est s\u00fbrement pleine de bonne volont\u00e9 mais pas toujours efficace, elle est impuissante, c\u2019est sa grande souffrance. Elle invente \u00e0 chaque \u00e9poque pour faire reculer tel genre nouveau de mis\u00e8re et l\u2019\u00e9ternelle mis\u00e8re de malchance qui niche partout, mais elle finit par n\u2019avoir pas assez de moyens et peut-\u00eatre plus assez de c\u0153ur devant ces trop difficiles \u00e0 aider. Elle ne sait plus leur parler, elle n\u2019ose plus. Il y a des lieux, des temps et des gens d\u2019\u00c9glise qui perdent le contact avec les plus pauvres. L\u2019histoire est remplie de ces \u00e9lans vers la mis\u00e8re qui finissent en coll\u00e8ges pour les riches. Mais je le dis, je l\u2019affirme, prise globalement et surtout regard\u00e9e dans son c\u0153ur profond et ses saints, l\u2019\u00c9glise est l\u2019Eglise des pauvres. L\u00e0 o\u00f9 je suis je vois tr\u00e8s bien pourquoi c\u2019est elle qui peut aller le plus loin pour eux.<\/p>\n<p><i>-Pourquoi\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Elle transforme leur c\u0153ur, elle les sauve, elle les remet dans l\u2019esp\u00e9rance et dans l\u2019amour. Ces d\u00e9munis en viennent \u00e0 se donner eux aussi, ils cherchent \u00e0 rendre service et \u00e7a desserre l\u2019\u00e9tau de leur mis\u00e8re, ils sont capables de penser aux autres, de se priver. Devant des choses pareilles je vous assure qu\u2019on est avec Dieu, dans l\u2019action de Dieu.<\/p>\n<p><i>&#8211; L\u2019 Eglise va vers les pauvres, mais les pauvres sont-ils chez eux dans l\u2019 \u00c9glise\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0C\u2019est l\u2019ordre m\u00eame du Seigneur\u00a0! \u201c Va chercher ceux qui ne sont pas encore \u00e0 ma table, va les chercher dans les rues, dans les bidonvilles, les cit\u00e9s d\u2019urgence, les coins \u00e0 ch\u00f4meurs. Va vers eux et ils viendront chez toi. \u201d Alors, l\u00e0, se pose le probl\u00e8me de l\u2019attirance. Quand les pauvres voient un pr\u00eatre, une religieuse, un la\u00efc engag\u00e9, une communaut\u00e9 paroissiale, il faut que ces pauvres puissent sentir qu\u2019on les attend, qu\u2019on va les aimer.<\/p>\n<p><i>&#8211; Les milieux chr\u00e9tiens, m\u00eame modestes, rejettent plus ou moins consciemment les gens \u00e0 mis\u00e8re d\u00e9plaisante, insoutenable. Je dis cela parce que c\u2019est ma propre r\u00e9action, ils me font peur, j\u2019essaie de les oublier.<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Nous sommes dans un monde qui s\u2019est b\u00e2ti des citadelles, qui met partout des garde-fous, et le plus terrible &#8211; celui dont vous parlez\u00a0-, l\u2019oubli. On gomme l\u2019insoutenable et c\u2019est vrai qu\u2019on a peur. Mais c\u2019est le moment de se dire\u00a0: quel est le Dieu que j\u2019adore\u00a0? Et avec qui je l\u2019adore\u00a0?<\/p>\n<p><i>&#8211; Quel est le Dieu de Joseph Wresinski\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Je ne suis pas un homme de monast\u00e8re, l\u2019oraison ce n\u2019est pas ma rencontre d\u2019un Dieu invisible, je le rencontre dans le d\u00e9sespoir des plus perdus, dans les larmes de honte, dans le froid et la faim, les so\u00fbleries, la prostitution. C\u2019est \u00e7a, mon clo\u00eetre.<\/p>\n<p><i>&#8211; Et le Dieu de ce clo\u00eetre\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Celui qui me dit que je suis pauvre aussi, affreusement pauvre.. L\u00e0, si je n\u2019ai pas de l\u2019amour \u00e0 donner, qu\u2019est-ce que je suis pour elle, un d\u00e9panneur\u00a0? Quand on s\u2019engage \u00e0 l\u2019ATD on vient pour d\u00e9panner, bien s\u00fbr, mais on d\u00e9couvre vite qu\u2019ils attendent autre chose. Ils veulent \u00eatre regard\u00e9s, \u00e9cout\u00e9s, sinon rien ne se passe, rien n\u2019est chang\u00e9. Je revois ma pauvre m\u00e8re. Apr\u00e8s la visite de quelqu\u2019un qui lui apportait des chaussures, des choses, elle se met \u00e0 pleurer\u00a0: \u201c Tu vois comme on m\u2019a trait\u00e9e\u00a0! \u201d J\u2019ai vu des mis\u00e9reux \u00e9cras\u00e9s, avachis, et qui tout \u00e0 coup se dressaient devant l\u2019assistante sociale\u00a0: \u201c Je ne suis pas un chien\u00a0! \u201d Ils avaient craqu\u00e9, ils avaient d\u00e9cid\u00e9 d\u2019arr\u00eater tout effort pour vivre et vous arrivez, vous sentez dans leurs yeux comme ils se transforment parce que quelqu\u2019un croit encore en eux. Apr\u00e8s, d\u2019ailleurs, \u00e7a reste tr\u00e8s difficile, ils vous d\u00e9\u00e7oivent toujours, ou du moins ils d\u00e9\u00e7oivent. Ce que vous voudriez pour eux, il faut s\u2019arracher des tripes un amour qui les laisse libres.<\/p>\n<p><i>&#8211; Comme l\u2019amour de Dieu pour nous\u00a0?<\/i><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Oui, mon Dieu c\u2019est celui qui nous aime en nous laissant libres m\u00eame quand nous le d\u00e9cevons, mais il ne cesse pas de nous accompagner. J\u2019essaie d\u2019\u00eatre un peu cela. On sauve une famille en lui faisant avoir des allocations dans des conditions invraisemblables et aussit\u00f4t ils claquent tout avec les voisins\u00a0: allez, c\u2019est la f\u00eate des allocations familiales\u00a0! Quand on me demande si j\u2019ai des r\u00e9ussites je r\u00e9ponds\u00a0: si je cherchais \u00e0 tout prix des r\u00e9ussites, mes r\u00e9ussites feraient de moi le ma\u00eetre des pauvres et non le compagnon qui respecte et qui laisse libre.<\/p>\n<p><i>&#8211; Votre Dieu, c\u2019est celui avec qui vous devez tout le temps rester pour les aimer.<\/i><br \/>\n<img loading=\"lazy\" decoding=\"async\" style=\"height: 11px;width: 8px\" src=\"\/wp-content\/uploads\/sites\/2\/2016\/07\/puce-68c92.gif\" alt=\"-\" width=\"8\" height=\"11\" \/>\u00a0Oui, c\u2019est bien cela mon oraison, ma vie d\u2019union, les aimer avec lui et comme lui\u00a0; il faut qu\u2019il me le r\u00e9apprenne constamment, Je n\u2019aurais jamais cru que \u00e7a pouvait \u00eatre si difficile, je commence un peu \u00e0 comprendre ce qu\u2019on dit quand on r\u00e9p\u00e8te un peu vite que Dieu est amour. Nous ne pouvons \u00eatre avec lui que si nous n\u2019avons qu\u2019une envie\u00a0: \u00eatre l\u00e0 comme lui. Ces hommes, ces femmes, ces enfants dans la pire d\u00e9tresse, quand je vois qu\u2019ils ont encore le courage de chanter et de rire, je me sens purifi\u00e9 de tout, je ne tiens qu\u2019\u00e0 la tendresse de Dieu, il n\u2019y a plus rien dans leur vie et dans la mienne que cette tendresse. En plein hiver, dans une baraque glac\u00e9e, j\u2019ai vu une maman laver son petit dans un seau d\u2019eau froide. Je sentais en moi l\u2019amour de Dieu pour eux, je ne pouvais que leur communiquer cela, mais je vous assure que les pauvres ont l\u2019oreille fine. Vous pouvez faire des discours, ils ne se trompent ni sur votre foi ni sur ce que vous avez dans le c\u0153ur.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; On parle des pauvres, mais il n\u2019y a pas de mot pour d\u00e9signer les gens dans la mis\u00e8re\u00a0? \u00a0On (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-44","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Eglise devant les pauvres - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Eglise devant les pauvres - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"&#8211; On parle des pauvres, mais il n\u2019y a pas de mot pour d\u00e9signer les gens dans la mis\u00e8re\u00a0? \u00a0On (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-23T08:12:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-27T07:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1444\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"L\u2019Eglise devant les pauvres\",\"datePublished\":\"2014-09-23T08:12:22+00:00\",\"dateModified\":\"2021-05-27T07:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/\"},\"wordCount\":1465,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/\",\"name\":\"L\u2019Eglise devant les pauvres - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg\",\"datePublished\":\"2014-09-23T08:12:22+00:00\",\"dateModified\":\"2021-05-27T07:39:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/09\\\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg\",\"width\":1444,\"height\":1182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/l-eglise-devant-les-pauvres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Eglise devant les pauvres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Eglise devant les pauvres - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Eglise devant les pauvres - Joseph Wresinski FR","og_description":"&#8211; On parle des pauvres, mais il n\u2019y a pas de mot pour d\u00e9signer les gens dans la mis\u00e8re\u00a0? \u00a0On (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2014-09-23T08:12:22+00:00","article_modified_time":"2021-05-27T07:39:55+00:00","og_image":[{"width":1444,"height":1182,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webmestre","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"L\u2019Eglise devant les pauvres","datePublished":"2014-09-23T08:12:22+00:00","dateModified":"2021-05-27T07:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/"},"wordCount":1465,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg","articleSection":["Articles"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/","name":"L\u2019Eglise devant les pauvres - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg","datePublished":"2014-09-23T08:12:22+00:00","dateModified":"2021-05-27T07:39:55+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2014\/09\/CIJW-0070-631-004-Noisy-le-Grand-1963-3.jpg","width":1444,"height":1182},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/l-eglise-devant-les-pauvres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019Eglise devant les pauvres"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":4,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/44\/revisions"}],"predecessor-version":[{"id":3650,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/44\/revisions\/3650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/2268"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=44"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=44"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}