{"id":4698,"date":"2025-11-20T18:00:14","date_gmt":"2025-11-20T17:00:14","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/fr\/?p=4698"},"modified":"2025-11-22T14:00:37","modified_gmt":"2025-11-22T13:00:37","slug":"les-enfants-sont-champions-damour","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/","title":{"rendered":"Les enfants sont des champions d&rsquo;amour!"},"content":{"rendered":"<p>Quand on parle des enfants, on a toujours des surprises, on a toujours des surprises. Je revois Patricia, son p\u00e8re \u00e9tait croque-mort et c&rsquo;\u00e9tait horrible chez elle parce que tout \u00e9tait recouvert de linceuls ! La nappe \u00e9tait linceul, les serviettes \u00e9taient des linceuls. La m\u00e8re \u00e9tait partie, et il y avait six enfants \u00e0 la maison en plus de Patricia. Le soir, elle couchait dans le lit de son p\u00e8re et elle s&rsquo;attachait \u00e0 lui avec des \u00e9pingles pour ne pas que la police vienne la prendre avec ses fr\u00e8res et s\u0153urs. Dans ce combat avec la police, elle se cachait avec ses fr\u00e8res et s\u0153urs, avec ma complicit\u00e9 d&rsquo;ailleurs, entre la toiture et le plafond du jardin d&rsquo;enfants et, elle passait des fois plusieurs nuits, pour pas que la police l&#8217;emm\u00e8ne. Et puis une fois que tout cela a \u00e9t\u00e9 pass\u00e9, la maman est revenue, c&rsquo;\u00e9tait le soleil. Et puis, beaucoup plus tard, quand j&rsquo;ai rencontr\u00e9 Patricia dans la vie, elle m&rsquo;a dit: Quand j&rsquo;\u00e9tais enfant, c&rsquo;\u00e9tait merveilleux, j&rsquo;\u00e9tais tellement heureuse, c&rsquo;est papa qui prenait tout \u00bb.<\/p>\n<p>Je crois que c&rsquo;est \u00e7a les enfants. Les enfants, de tout ils font des petits bonheurs et c&rsquo;est la joie des grands parce que quand on reconna\u00eet les petits bonheurs des enfants non seulement on a envie de leur donner des grands bonheurs mais on est confiant que dans la vie, ils ne sont pas marqu\u00e9s, ils n&rsquo;ont pas de haine. J&rsquo;ai toujours remarqu\u00e9 &#8212; et c&rsquo;est absolument extraordinaire &#8212; que les enfants de la mis\u00e8re ils ont grandi mais ils ont grandi sans haine.<\/p>\n<p>Peut-\u00eatre parce que c&rsquo;\u00e9tait trop dur \u00e0 porter? Peut-\u00eatre aussi parce que les p\u00e8res et leurs m\u00e8res faisaient tellement d&rsquo;efforts et les enfants reconnaissaient les efforts que les uns et les autres faisaient. C&rsquo;est peut-\u00eatre \u00e0 cause de \u00e7a que les enfants de la mis\u00e8re restaient tellement attach\u00e9s \u00e0 leurs parents. Souvent, on est \u00e9tonn\u00e9, on dit: \u00ab Mais ils restent l\u00e0, ils ne s&rsquo;en vont pas! On parle d&rsquo;agglutinement mais ce n&rsquo;est pas vrai. C&rsquo;est parce qu&rsquo;ils se rendent bien compte que leur p\u00e8re et leur m\u00e8re ont tellement subi de coups pour eux. Ils ont \u00e9t\u00e9, oh ce n&rsquo;est pas le bouclier, c&rsquo;est beaucoup plus que \u00e7a, ils ont \u00e9t\u00e9 des c\u0153urs qui ont envelopp\u00e9 leur c\u0153ur. C&rsquo;est extraordinaire.<\/p>\n<p>Parler des enfants, c&rsquo;est ces gosses qui, un soir de f\u00e9vrier o\u00f9 il faisait froid, il faisait froid, le vent \u00e9tait glac\u00e9, qui allaient vendre leurs billes parce que c&rsquo;\u00e9tait la f\u00eate de leur maman. Ca faisait plusieurs jours qu&rsquo;il n&rsquo;y avait pas eu de pain \u00e0 la maison et il n&rsquo;y avait rien \u00e0 manger. Ils \u00e9taient venus me voir mais je n&rsquo;avais rien non plus. J&rsquo;avais \u00e9t\u00e9 mendier un peu \u00e0 droite et \u00e0 gauche, j&rsquo;avais eu du pain rassis et je le leur avais donn\u00e9. Mais ce jour-l\u00e0, ils se sont dit: \u00abC&rsquo;est la f\u00eate de ma m\u00e8re, qu&rsquo;est-ce qu&rsquo;on va donner \u00e0 maman? \u00bb Alors, ils ont vendu leurs billes et ils ont amen\u00e9 un pain le soir \u00e0 la maman.<\/p>\n<p>C&rsquo;est \u00e7a les gosses. Il n&rsquo;y a jamais rien dans les gosses de la mis\u00e8re. Je vois aussi Nono dans la boue, c&rsquo;\u00e9tait effrayant, il avait plu, il y avait des flaques d&rsquo;eau partout. Il y a une dame bien chic qui arrive, elle lui apporte du chocolat et Nono va vers sa petite s\u0153ur pour lui partager le chocolat.<\/p>\n<p><a name=\"_GoBack\"><\/a>C&rsquo;est \u00e7a les gosses de la mis\u00e8re. Moi j&rsquo;\u00e9tais comme \u00e7a quand j&rsquo;\u00e9tais gosse, j&rsquo;inventais, je trouvais, je cherchais, je piquais, je raflais, je me d\u00e9brouillais pour qu&rsquo;on n&rsquo;ait pas trop faim \u00e0 la maison. C&rsquo;est pareil les gosses de la mis\u00e8re, c&rsquo;est des champions, des champions d&rsquo;amour. C&rsquo;est dommage qu&rsquo;on ne le reconnaisse pas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand on parle des enfants, on a toujours des surprises, on a toujours des surprises. Je revois Patricia, son p\u00e8re (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":4697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,49,61],"tags":[],"class_list":["post-4698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-ecrits","category-interviews"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les enfants sont des champions d&#039;amour! - Joseph Wresinski FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les enfants sont des champions d&#039;amour! - Joseph Wresinski FR\" \/>\n<meta property=\"og:description\" content=\"Quand on parle des enfants, on a toujours des surprises, on a toujours des surprises. Je revois Patricia, son p\u00e8re (...) Lire la suite &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski FR\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-20T17:00:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-22T13:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1290\" \/>\n\t<meta property=\"og:image:height\" content=\"987\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Les enfants sont des champions d&rsquo;amour!\",\"datePublished\":\"2025-11-20T17:00:14+00:00\",\"dateModified\":\"2025-11-22T13:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/\"},\"wordCount\":701,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/FB_IMG_1763637612062.jpg\",\"articleSection\":[\"Actualit\u00e9s\",\"Ecrits\",\"Interviews\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/\",\"name\":\"Les enfants sont des champions d'amour! - Joseph Wresinski FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/FB_IMG_1763637612062.jpg\",\"datePublished\":\"2025-11-20T17:00:14+00:00\",\"dateModified\":\"2025-11-22T13:00:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/FB_IMG_1763637612062.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/FB_IMG_1763637612062.jpg\",\"width\":1290,\"height\":987},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/les-enfants-sont-champions-damour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les enfants sont des champions d&rsquo;amour!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/\",\"name\":\"Joseph Wresinski FR\",\"description\":\"Un site propos\u00e9 par le centre Joseph Wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/fr\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les enfants sont des champions d'amour! - Joseph Wresinski FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/","og_locale":"fr_FR","og_type":"article","og_title":"Les enfants sont des champions d'amour! - Joseph Wresinski FR","og_description":"Quand on parle des enfants, on a toujours des surprises, on a toujours des surprises. Je revois Patricia, son p\u00e8re (...) Lire la suite &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/","og_site_name":"Joseph Wresinski FR","article_published_time":"2025-11-20T17:00:14+00:00","article_modified_time":"2025-11-22T13:00:37+00:00","og_image":[{"width":1290,"height":987,"url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jean Tonglet","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Les enfants sont des champions d&rsquo;amour!","datePublished":"2025-11-20T17:00:14+00:00","dateModified":"2025-11-22T13:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/"},"wordCount":701,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg","articleSection":["Actualit\u00e9s","Ecrits","Interviews"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/","url":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/","name":"Les enfants sont des champions d'amour! - Joseph Wresinski FR","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg","datePublished":"2025-11-20T17:00:14+00:00","dateModified":"2025-11-22T13:00:37+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/11\/FB_IMG_1763637612062.jpg","width":1290,"height":987},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/fr\/les-enfants-sont-champions-damour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.joseph-wresinski.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les enfants sont des champions d&rsquo;amour!"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#website","url":"https:\/\/www.joseph-wresinski.org\/fr\/","name":"Joseph Wresinski FR","description":"Un site propos\u00e9 par le centre Joseph Wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/fr\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/fr\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/comments?post=4698"}],"version-history":[{"count":2,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4698\/revisions"}],"predecessor-version":[{"id":4700,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/posts\/4698\/revisions\/4700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media\/4697"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/media?parent=4698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/categories?post=4698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/fr\/wp-json\/wp\/v2\/tags?post=4698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}