{"id":2146,"date":"2024-02-14T00:00:43","date_gmt":"2024-02-13T23:00:43","guid":{"rendered":"https:\/\/www.joseph-wresinski.org\/it\/?p=2146"},"modified":"2024-02-12T13:30:38","modified_gmt":"2024-02-12T12:30:38","slug":"essere-servitori","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/","title":{"rendered":"Essere servitori"},"content":{"rendered":"<p>Quando sono stato ordinato sacerdote, mi hanno chiesto: \u00abQual \u00e8 il passo del Vangelo che ispira la tua vita?\u00bb. Ho risposto subito: \u00abPrendi il largo e getta le tue reti!\u00bb. \u00c8 questo ci\u00f2 che ha animato i primi anni del mio sacerdozio: andare verso gli altri, incontrare gli altri. E pi\u00f9 erano poveri, pi\u00f9 desideravo incontrarli, volevo unire la mia vita alla loro. Ma mi sono reso conto che in realt\u00e0 questo non richiedeva effettivamente di essere servitore nel senso stretto del termine, cio\u00e8 qualcuno che \u00e8 totalmente dipendente dagli ordini del padrone. E quindi non era lo stare in mezzo ai poveri, soffrire il freddo e, come loro, non avere pane, che faceva di me il vero servitore di quel popolo della miseria in mezzo al quale vivevo. Io avevo le mie difese. E avevo anche la mia personalit\u00e0. Avevo ci\u00f2 che avevo imparato in seminario, e poi avevo alle spalle tutta una Chiesa. Poteva magari mancarmi il pane in una baraccopoli, ma sapevo che il giorno che avessi voluto&#8230;c\u2019era comunque una Chiesa dietro di me che fondamentalmente era la mia forza.<\/p>\n<p>Essere servitori non \u00e8 poi tanto facile quanto si pensi. Perch\u00e9 si hanno sempre delle scorte e di fatto si ha sempre qualche biscotto in tasca.<\/p>\n<p>Alla fine, ci\u00f2 che ho scoperto nella mia vita da sacerdote, nella mia vita in mezzo alle persone e ai poveri, \u00e8 che non potevo essere realmente servitore di nessuno di loro se prima di tutto non ero servitore di coloro che si univano a me, coloro che avevano accettato di lasciare ogni cosa per diventare volontari del Movimento ATD Quarto Mondo, che erano diventati i miei compagni di viaggio. Il giorno in cui ho capito questo, non potete neanche immaginare che liberazione \u00e8 stata per me.<\/p>\n<p>Perch\u00e9 quando io stesso ero impegnato in mezzo ai poveri, non osavo dirlo, ma pensavo: \u00abSono proprio un brav\u2019uomo, una brava persona, ne faccio, di cose!!!\u00bb.<\/p>\n<p>Il giorno in cui ho scoperto che quelli che potevano insegnarmi ad essere servitore non erano i poveri, bens\u00ec coloro che dovevano prepararsi, maturare, formarsi per riuscire a vivere in mezzo ai poveri, per me \u00e8 stata una grande liberazione. A partire da quel momento ho cominciato a credere che non solo tutti gli uomini potevano essere salvati, ma potevano anche essere salvatori.<br \/>\nEra straordinario, una vera e propria rivoluzione, per me. Ho scoperto che potevo avere piena fiducia negli altri. In fondo, li ho conosciuti mentre servivano, nel momento della lavanda dei piedi. Li ho conosciuti quando avevano delle difficolt\u00e0 spirituali, affettive, fisiche, di salute o di altro genere. Li ho conosciuti nei momenti di grande entusiasmo e di grande delusione. Li ho conosciuti con la loro codardia e anche con il loro coraggio. Posso dire di averli messi al centro della mia vita, del mio cuore, come fossero i soli esseri dei quali mi importava. \u00c8 per questo motivo che, dopo una quindicina di anni, mi sono completamente dedicato all\u2019incontro, non dico nemmeno alla formazione, dei volontari che vivono nel mondo, nei luoghi della miseria. Dico a me stesso che sono un uomo liberato, perch\u00e9 credo in loro, perch\u00e9 sono certo che tutti loro sono chiamati ad essere dei liberatori, perch\u00e9 tutti noi siamo chiamati ad esserlo. A condizione che impariamo prima di tutto a servire quelli che abbiamo vicino, a servirli veramente, non soltanto a parole, ma in maniera che tutta la nostra vita ne risulti cambiata, stravolta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando sono stato ordinato sacerdote, mi hanno chiesto: \u00abQual \u00e8 il passo del Vangelo che ispira la tua vita?\u00bb. Ho (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/\">Continua a leggere <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":2147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[12,80,61],"tags":[],"class_list":["post-2146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-interviste","category-scritti"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Essere servitori - Joseph Wresinski IT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Essere servitori - Joseph Wresinski IT\" \/>\n<meta property=\"og:description\" content=\"Quando sono stato ordinato sacerdote, mi hanno chiesto: \u00abQual \u00e8 il passo del Vangelo che ispira la tua vita?\u00bb. Ho (...) Continua a leggere &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski IT\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-13T23:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jean Tonglet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean Tonglet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/\"},\"author\":{\"name\":\"Jean Tonglet\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"headline\":\"Essere servitori\",\"datePublished\":\"2024-02-13T23:00:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/\"},\"wordCount\":571,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2024\\\/02\\\/PJW_SEL15.jpg\",\"articleSection\":[\"Attualit\u00e0\",\"Interviste\",\"Scritti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/\",\"name\":\"Essere servitori - Joseph Wresinski IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2024\\\/02\\\/PJW_SEL15.jpg\",\"datePublished\":\"2024-02-13T23:00:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2024\\\/02\\\/PJW_SEL15.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2024\\\/02\\\/PJW_SEL15.jpg\",\"width\":2121,\"height\":1512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/essere-servitori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Essere servitori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/\",\"name\":\"Joseph Wresinski IT\",\"description\":\"Un sito proposto dal centro joseph wresinski\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/#\\\/schema\\\/person\\\/93469e0206778753beddb73f4e07c8e0\",\"name\":\"Jean Tonglet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g\",\"caption\":\"Jean Tonglet\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/it\\\/author\\\/jean\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Essere servitori - Joseph Wresinski IT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/","og_locale":"it_IT","og_type":"article","og_title":"Essere servitori - Joseph Wresinski IT","og_description":"Quando sono stato ordinato sacerdote, mi hanno chiesto: \u00abQual \u00e8 il passo del Vangelo che ispira la tua vita?\u00bb. Ho (...) Continua a leggere &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/","og_site_name":"Joseph Wresinski IT","article_published_time":"2024-02-13T23:00:43+00:00","og_image":[{"width":2121,"height":1512,"url":"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg","type":"image\/jpeg"}],"author":"Jean Tonglet","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Jean Tonglet","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/"},"author":{"name":"Jean Tonglet","@id":"https:\/\/www.joseph-wresinski.org\/it\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"headline":"Essere servitori","datePublished":"2024-02-13T23:00:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/"},"wordCount":571,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg","articleSection":["Attualit\u00e0","Interviste","Scritti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/","url":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/","name":"Essere servitori - Joseph Wresinski IT","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg","datePublished":"2024-02-13T23:00:43+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/it\/wp-content\/uploads\/sites\/16\/2024\/02\/PJW_SEL15.jpg","width":2121,"height":1512},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/it\/essere-servitori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/it\/"},{"@type":"ListItem","position":2,"name":"Essere servitori"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/it\/#website","url":"https:\/\/www.joseph-wresinski.org\/it\/","name":"Joseph Wresinski IT","description":"Un sito proposto dal centro joseph wresinski","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/it\/#\/schema\/person\/93469e0206778753beddb73f4e07c8e0","name":"Jean Tonglet","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/599cfd98b536979bcebf2d6839f0c694333341f1caf7ba53413b62de5453de40?s=96&d=mm&r=g","caption":"Jean Tonglet"},"url":"https:\/\/www.joseph-wresinski.org\/it\/author\/jean\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/posts\/2146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/comments?post=2146"}],"version-history":[{"count":1,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/posts\/2146\/revisions"}],"predecessor-version":[{"id":2148,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/posts\/2146\/revisions\/2148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/media\/2147"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/media?parent=2146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/categories?post=2146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/it\/wp-json\/wp\/v2\/tags?post=2146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}