{"id":1721,"date":"2017-03-14T14:54:08","date_gmt":"2017-03-14T13:54:08","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/nl\/?p=1721"},"modified":"2018-02-05T11:16:07","modified_gmt":"2018-02-05T10:16:07","slug":"mensen-gedoemd-armoede-leven","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/","title":{"rendered":"Waar mensen gedoemd zijn in armoede te leven"},"content":{"rendered":"<p>Dit citaat van Wresinski kunnen jullie als meme delen op internet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1719\" src=\"http:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden.jpg\" alt=\"\" width=\"510\" height=\"396\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dit citaat van Wresinski kunnen jullie als meme delen op internet.<\/p>\n","protected":false},"author":7,"featured_media":1720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[76],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL\" \/>\n<meta property=\"og:description\" content=\"Dit citaat van Wresinski kunnen jullie als meme delen op internet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski NL\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-14T13:54:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-05T10:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"510\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"katia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"katia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/\"},\"author\":{\"name\":\"katia\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/#\\\/schema\\\/person\\\/bb3b9e9d350ddd2953416f14af30b1aa\"},\"headline\":\"Waar mensen gedoemd zijn in armoede te leven\",\"datePublished\":\"2017-03-14T13:54:08+00:00\",\"dateModified\":\"2018-02-05T10:16:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/\"},\"wordCount\":19,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2017\\\/03\\\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg\",\"articleSection\":[\"Foto's\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/\",\"name\":\"Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2017\\\/03\\\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg\",\"datePublished\":\"2017-03-14T13:54:08+00:00\",\"dateModified\":\"2018-02-05T10:16:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/#\\\/schema\\\/person\\\/bb3b9e9d350ddd2953416f14af30b1aa\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2017\\\/03\\\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2017\\\/03\\\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg\",\"width\":510,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/mensen-gedoemd-armoede-leven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Waar mensen gedoemd zijn in armoede te leven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/\",\"name\":\"Joseph Wresinski NL\",\"description\":\"Een website door het Joseph Wresinski Centrum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/#\\\/schema\\\/person\\\/bb3b9e9d350ddd2953416f14af30b1aa\",\"name\":\"katia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g\",\"caption\":\"katia\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/nl\\\/author\\\/katia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/","og_locale":"nl_NL","og_type":"article","og_title":"Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL","og_description":"Dit citaat van Wresinski kunnen jullie als meme delen op internet.","og_url":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/","og_site_name":"Joseph Wresinski NL","article_published_time":"2017-03-14T13:54:08+00:00","article_modified_time":"2018-02-05T10:16:07+00:00","og_image":[{"width":510,"height":396,"url":"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg","type":"image\/jpeg"}],"author":"katia","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"katia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/"},"author":{"name":"katia","@id":"https:\/\/www.joseph-wresinski.org\/nl\/#\/schema\/person\/bb3b9e9d350ddd2953416f14af30b1aa"},"headline":"Waar mensen gedoemd zijn in armoede te leven","datePublished":"2017-03-14T13:54:08+00:00","dateModified":"2018-02-05T10:16:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/"},"wordCount":19,"commentCount":1,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg","articleSection":["Foto's"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/","url":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/","name":"Waar mensen gedoemd zijn in armoede te leven - Joseph Wresinski NL","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg","datePublished":"2017-03-14T13:54:08+00:00","dateModified":"2018-02-05T10:16:07+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/#\/schema\/person\/bb3b9e9d350ddd2953416f14af30b1aa"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/nl\/wp-content\/uploads\/sites\/18\/2017\/03\/Waar-mensen-gedoemd-zijn-in-armoede-te-leven-worden2.jpg","width":510,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/nl\/mensen-gedoemd-armoede-leven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/nl\/"},{"@type":"ListItem","position":2,"name":"Waar mensen gedoemd zijn in armoede te leven"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/nl\/#website","url":"https:\/\/www.joseph-wresinski.org\/nl\/","name":"Joseph Wresinski NL","description":"Een website door het Joseph Wresinski Centrum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/nl\/#\/schema\/person\/bb3b9e9d350ddd2953416f14af30b1aa","name":"katia","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/36a6c89672713f92abd7f6e92cad0796e903bcb2b77995623d5f160ed0a2209e?s=96&d=mm&r=g","caption":"katia"},"url":"https:\/\/www.joseph-wresinski.org\/nl\/author\/katia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":5,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":2106,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/posts\/1721\/revisions\/2106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/media\/1720"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/nl\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}