{"id":768,"date":"2008-10-24T04:30:58","date_gmt":"2008-10-24T02:30:58","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/zh\/article322322\/"},"modified":"2020-10-07T14:04:42","modified_gmt":"2020-10-07T12:04:42","slug":"article322322","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/","title":{"rendered":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f"},"content":{"rendered":"<p><i>(\u4e2d\u6cd5\u5c0d\u7167)<\/i><\/p>\n<p>\u4f5c\u8005: \u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa(Joseph Wresinski)<\/p>\n<p><strong>\u7aae\u4eba\u88ab\u7981\u6b62\u53bb\u6e21\u9748\u6027\u751f\u6d3b\uff0c\u90a3\u662f\u6700\u56b4\u91cd\uff0c\u5f71\u97ff\u6700\u6df1\u7684\u4e00\u7a2e\u525d\u596a\u3002<\/strong><\/p>\n<p>\u81f3\u8ca7\u8005\u6bd4\u4efb\u4f55\u4eba\u90fd\u8a8d\u8b58\u4eba\u6027\u7684\u8edf\u5f31\uff0c\u9762\u5c0d\u5404\u7a2e\u7acb\u5373\u6027\u7684\u9700\u8981\uff0c\u4ed6\u6bcf\u5929\u9047\u5230\u7684\u96c7\u4e3b\u3001\u52a9\u4eba\u8005\u3001\u7fa9\u5de5\u5011\uff0c \u90fd\u5404\u6709\u5404\u7684\u60f3\u6cd5\u3001\u5206\u6790\u8207\u5efa\u8b70\u3002\u4f46\u662f\uff0c\u81f3\u8ca7\u8005\u8207\u9019\u4e9b\u4eba\u76f8\u9047\u6642\uff0c\u6700\u6df1\u7684\u7b49\u5f85\u537b\u4e0d\u5728\u9019\u500b\u5c64\u6b21\u3002\u4ed6\u5728\u9019\u4e9b\u4eba\u8eab\u4e0a\u9996\u5148\u770b\u5230\u7684\u662f\u4ed6\u5011\u9032\u5165\u4eba\u6027\u7684\u80fd\u529b\uff0c\u662f\u4ed6\u5011\u8d85\u8d8a\u773c\u524d\u9019\u4e9b\u7acb\u5373\u6027\u554f\u984c\uff0c\u6293\u4f4f\u672c\u8cea\u7684\u80fd\u529b\uff0c\u9019\u610f\u5473\u8457\uff1a\u751f\u547d\u3001\u6b7b\u4ea1\uff0c\u800c\u4e14\u70ba\u751a\u9ebc\u4e0d\u8aaa\uff0c\u9084\u6709\u5929\u4e3b\uff01<\/p>\n<p>\u95dc\u65bc\u7aae\u4eba\u5c0d\u5929\u4e3b\uff0c\u5c0d\u6b7b\u5f8c\u4e16\u754c\u7684\u60f3\u6cd5\uff0c\u6211\u5011\u77e5\u9053\u4e9b\u4ec0\u9ebc\uff1f\u95dc\u65bc\u7aae\u4eba\u5c0d\u4eba\u985e\u9748\u6027\u7684\u8a8d\u8b58\uff0c\u6211\u5011\u53c8\u77e5\u9053\u4e86\u591a\u5c11\uff1f\u4ed6\u5c0d\u5171\u540c\u751f\u6d3b\u7684\u610f\u9858\uff0c\u5c0d\u51dd\u805a\u773e\u751f\u7684\u8ffd\u5c0b\uff0c\u6211\u5011\u53c8\u77e5\u9053\u4e9b\u4ec0\u9ebc\uff1f\u5728\u4ed6\u773c\u88e1\uff0c\u6211\u5011\u70ba\u8ab0\u800c\u751f\uff1f\u70ba\u4e86\u90a3\u4e00\u500b\u795e\u660e\uff1f\u90a3\u4e00\u985e\u610f\u8b58\u578b\u614b\uff1f\u90a3\u4e00\u7a2e\u771f\u7406\uff1f\u4ed6\u5c0d\u4eba\u985e\u8ffd\u5c0b\u5b8c\u6574\u6027\u8207\u7368\u7279\u6027\u7684\u5967\u7955\u6240\u64c1\u6709\u7684\u77e5\u8b58\uff0c\u6211\u5011\u53c8\u77e5\u9053\u4e86\u591a\u5c11\uff1f\u6211\u5011\u70ba\u4f55\u4ee5\u7aae\u4eba\u4e4b\u540d\u63a7\u8a34\u9019\u4e16\u754c\u7684\u7a2e\u7a2e\u52a3\u8de1\uff0c\u537b\u4e0d\u82b1\u5fc3\u601d\u53bb\u8a8d\u8b58\u4ed6\u7684\u60f3\u6cd5\uff1f\u70ba\u4ec0\u9ebc\u6211\u5011\u4e00\u6709\u6a5f\u6703\u5c31\u767c\u52d5\u4ed6\u5011\u53bb\u5c0d\u6297\u5176\u4ed6\u4eba\uff0c\u537b\u4e0d\u53bb\u7406\u89e3\u4ed6\u5011\u5c0d\u9019\u4e9b\u4eba\u6700\u6df1\u7684\u7b49\u5f85\uff1f\u96e3\u9053\u6211\u5011\u4ee5\u70ba\u597d\u597d\u7684\u7ba1\u7406\u793e\u6703\u6551\u6fdf\u91d1\u6216\u63d0\u4f9b\u4ed6\u5011\u4e00\u4e9b\u5e73\u5eb8\u7684\u4f4f\u5b85\uff0c\u6bd4\u5206\u4eab\u4ed6\u5011\u5c0d\u4e16\u754c\u3001\u5c0d\u795e\u660e\u7684\u601d\u60f3\u66f4\u70ba\u6709\u529b\uff1f\u96e3\u9053\u6211\u5011\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u4e0d\u6703\u601d\u8003\uff0c\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f\u4e0d\u53bb\u8d85\u8d8a\u9019\u500b\u7981\u5236\uff0c\u4e00\u5207\u7684\u6587\u5316\u6027\u6d3b\u52d5\u90fd\u5c07\u4ed8\u4e4b\u95d5\u5982\u3002\u56e0\u70ba\u7aae\u4eba\u7684\u9748\u4fee\u63d0\u9192\u5927\u5bb6\uff0c\u6211\u5011\u540c\u5c6c\u4e00\u500b\u4eba\u6027\u3002\u5982\u679c\u6211\u5011\u4e0d\u9032\u5165\u9019\u500b\u9748\u4fee\uff0c\u5c31\u4e0d\u5fc5\u4f86\u8ddf\u4ed6\u8ac7\u6587\u5316\u3002<\/p>\n<p>\u694a\u6dd1\u79c0\u7bc0\u8b6f\u81ea\u300a\u6587\u5316\u8207\u6975\u7aef\u8ca7\u7aae\u300b\uff0c\u82e5\u745f\u2027\u8d6b\u5fcd\u65af\u57fa\u8457\uff0c\u7b2c\u56db\u4e16\u754c\u51fa\u7248\u793e\uff0c2004\u5e74\uff0c\u5df4\u9ece\uff0c\u980122-24\u3002<\/p>\n<p>********************************************************<\/p>\n<p>Plus que toute autre personne au monde, le plus pauvre sait la faiblesse de l\u2019homme. Tous les jours, il est affront\u00e9 \u00e0 des employ\u00e9s, des acteurs sociaux, des b\u00e9n\u00e9voles qui , tous, ont leur id\u00e9e, leur analyse, leur proposition pour r\u00e9pondre \u00e0 ses besoins imm\u00e9diats. Et pourtant, ce n\u2019est pas \u00e0 ce niveau-l\u00e0 que le plus pauvre tente de les rencontrer. ce qu\u2019il voit en ces personnes, c\u2019est avant tout leur capacit\u00e9 \u00e0 entrer en lien avec l\u2019humanit\u00e9 qui est la sienne. c\u2019est leur capacit\u00e9 \u00e0 saisir tout ce qui se trouve au-del\u00e0 m\u00eame de tous les probl\u00e8mes imm\u00e9diats, c\u2019est-\u00e0-dire: la vie, la mort et, pourquoi pas, Dieu!<\/p>\n<p>Que savons-nous de cette pens\u00e9e du pauvre sur Dieu, sur &#8220;l\u2019apr\u00e8s&#8221; de la vie? Que savons-nous de ce qu\u2019il conna\u00eet de la spiritualit\u00e9 de l\u2019humanit\u00e9? Que savons-nous de sa volont\u00e9 de vivre ensemble, de sa volont\u00e9 de rechercher ce qui nous rassemble? A son avis, pour qui vivons-nous? Pour quel Dieu? Pour quelle id\u00e9ologie? Pour quelle v\u00e9rit\u00e9? Que savons-nous de sa connaissance sur cet insondable myst\u00e8re de l\u2019homme \u00e0 la recherche de sa totalit\u00e9, de son unicit\u00e9? Pourquoi, en son nom, accusons-nous le monde de tous les maux sans m\u00eame conna\u00eetre sa pens\u00e9e \u00e0 lui? Pourquoi le mobilisons-nous \u00e0 l\u2019occasion contre les autres, sans savoir ce que lui-m\u00eame attend d\u2019eux? Ne pensons-nous pas que partager cette pens\u00e9e sur le monde et sur Dieu est tout aussi mobilisateur qu\u2019une bonne gestion des allocations familiales, que l\u2019octroi d\u2019un logement m\u00e9diocre? Ou pensons-nous vraiment que le plus pauvre ne pense pas, qu\u2019il n\u2019a pas de vie spirituelle? Sans d\u00e9passement de cet interdit, toute action culturelle est vaine, car la spiritualit\u00e9 du pauvre est de nous rappeler que nous sommes d\u2019une m\u00eame humanit\u00e9. Si nous n\u2019entrons pas dans cette spiritualit\u00e9-l\u00e0, inutile de venir lui parler de culture.<\/p>\n<p>In <i>Culture et Grande pauvret\u00e9<\/i>, Paris, 2004, (\u00c9dition Quart Monde),p22-24.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(\u4e2d\u6cd5\u5c0d\u7167) \u4f5c\u8005: \u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa(J (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/\">\u7ee7\u7eed\u9605\u8bfb <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[83],"tags":[],"class_list":["post-768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecrits-spirituels"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587\" \/>\n<meta property=\"og:description\" content=\"(\u4e2d\u6cd5\u5c0d\u7167) \u4f5c\u8005: \u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa(J (...) \u7ee7\u7eed\u9605\u8bfb &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski \u4e2d\u6587\" \/>\n<meta property=\"article:published_time\" content=\"2008-10-24T02:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-07T12:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"693\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f\",\"datePublished\":\"2008-10-24T02:30:58+00:00\",\"dateModified\":\"2020-10-07T12:04:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/\"},\"wordCount\":351,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/10\\\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg\",\"articleSection\":[\"\u7075\u4fee\u4f5c\u54c1\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/\",\"name\":\"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/10\\\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg\",\"datePublished\":\"2008-10-24T02:30:58+00:00\",\"dateModified\":\"2020-10-07T12:04:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/10\\\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2020\\\/10\\\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg\",\"width\":693,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article322322\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/\",\"name\":\"Joseph Wresinski \u4e2d\u6587\",\"description\":\"\u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa\u4e2d\u5fc3\u63d0\u4f9b\u7684\u7f51\u7ad9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/","og_locale":"zh_CN","og_type":"article","og_title":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587","og_description":"(\u4e2d\u6cd5\u5c0d\u7167) \u4f5c\u8005: \u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa(J (...) \u7ee7\u7eed\u9605\u8bfb &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/","og_site_name":"Joseph Wresinski \u4e2d\u6587","article_published_time":"2008-10-24T02:30:58+00:00","article_modified_time":"2020-10-07T12:04:42+00:00","og_image":[{"width":693,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"webmestre","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"2 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f","datePublished":"2008-10-24T02:30:58+00:00","dateModified":"2020-10-07T12:04:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/"},"wordCount":351,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg","articleSection":["\u7075\u4fee\u4f5c\u54c1"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/","url":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/","name":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f - Joseph Wresinski \u4e2d\u6587","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg","datePublished":"2008-10-24T02:30:58+00:00","dateModified":"2020-10-07T12:04:42+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/zh\/article322322\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2020\/10\/CIJW-0070-843-101-1984-famille-de-martine-lecorre-4-693x400-1.jpg","width":693,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article322322\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/zh\/"},{"@type":"ListItem","position":2,"name":"\u4f60\u771f\u7684\u4ee5\u70ba\u8d64\u8ca7\u8005\u6c92\u6709\u9748\u4fee\u751f\u6d3b\uff1f"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#website","url":"https:\/\/www.joseph-wresinski.org\/zh\/","name":"Joseph Wresinski \u4e2d\u6587","description":"\u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa\u4e2d\u5fc3\u63d0\u4f9b\u7684\u7f51\u7ad9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/zh\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":11,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/768\/revisions"}],"predecessor-version":[{"id":1049,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/768\/revisions\/1049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/media\/1520"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/media?parent=768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/categories?post=768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/tags?post=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}