{"id":790,"date":"2008-09-16T10:02:42","date_gmt":"2008-09-16T08:02:42","guid":{"rendered":"http:\/\/www.joseph-wresinski.org\/zh\/article289289\/"},"modified":"2021-06-09T12:26:10","modified_gmt":"2021-06-09T10:26:10","slug":"article289289","status":"publish","type":"post","link":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/","title":{"rendered":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse)"},"content":{"rendered":"<p>\u5982\u4f55\u8d70\u9032\u5730\u7b2c\u56db\u4e16\u754c\u7684\u6b77\u53f2\u6838\u5fc3\uff1f \u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa\u76f4\u63a5\u5411\u4e00\u7fa4\u670b\u53cb\u8981\u6c42\u5206\u64d4\u8cac\u4efb\uff0c \u9019\u4e9b\u670b\u53cb\u4f86\u81ea\u975e\u6d32\uff0c 1981\u5e74\u4ed6\u5011\u805a\u96c6\u5728\u806f\u5408\u570b\u6559\u79d1\u6587\u7d44\u7e54\u53ca\u7b2c\u56db\u4e16\u754c\u7d44\u7e54\u7e3d\u90e8\uff0c \u4ed6\u5011\u5728\u81ea\u5df1\u7684\u570b\u5bb6\u70ba\u6700\u8ca7\u7aae\u7684\u65cf\u7fa4\u6295\u8eab\uff0c \u540c\u6642\u4e5f\u662f\u7b2c\u56db\u4e16\u754c\u7684\u901a\u8a0a\u6703\u54e1\u3002<\/p>\n<p><strong>\u6f14\u8aaa\u5927\u7db1<\/strong><\/p>\n<p>\u2022\u548c\u6211\u5011\u6240\u656c\u91cd\u7684\u8cd3\u5ba2\u5206\u4eab\u6211\u5011\u6700\u73cd\u8cb4\u7684\u6771\u897f<\/p>\n<p>\u2022\u4e00\u6bb5\u8a95\u751f\u65bc\u5b64\u55ae\u8207\u75db\u82e6\u4e2d\u7684\u6b77\u53f2<\/p>\n<p>\u2022\u8d64\u8ca7\u8005\u88ab\u6392\u65a5\u7684\u4e8b\u5be6\u5f70\u986f\u51fa\u4f86<\/p>\n<p>\u2022\u737b\u51fa\u81ea\u5df1\u7684\u751f\u547d\uff0c\u5411\u4ed6\u4eba\u8b49\u660e\u4ed6\u4e5f\u80fd\uff0c\u4ed6\u4e5f\u662f\u5171\u540c\u8ca0\u8cac\u4eba<\/p>\n<p>\u2022\u6700\u8ca7\u7aae\u7684\u4eba\u662f\u6211\u5011\u7684\u5c0e\u5e2b<\/p>\n<p>\u2022\u201c\u5728\u6211\u5011\u7684\u6b77\u53f2\u4e2d\u5c0b\u627e\u201d<\/p>\n<p>\u2022\u70ba\u7406\u89e3\u800c\u5beb<\/p>\n<p>\u2022\u4ea4\u4ed8\u4e00\u500b\u79d8\u5bc6\uff0c\u610f\u5373\u5206\u4eab\u4e00\u4efd\u8cac\u4efb<\/p>\n<h3><\/h3>\n<figure class=\"alignnone wp-caption\"><\/figure>\n<p>\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2<br \/>\n1981\u5e74\u5728\u806f\u5408\u570b\u6559\u79d1\u6587\u7d44\u7e54\u53ca\u7b2c\u56db\u4e16\u754c\u904b\u52d5\u7e3d\u90e8\uff0c\u82e5\u745f\u2027\u8d6b\u5fcd\u65af\u57fa\u5411\u4e00\u7fa4\u4f86\u81ea\u975e\u6d32\u7684\u670b\u53cb\u5206\u4eab\u7b2c\u56db\u4e16\u754c\u904b\u52d5\u7684\u6b77\u53f2\u3002<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5982\u4f55\u8d70\u9032\u5730\u7b2c\u56db\u4e16\u754c\u7684\u6b77\u53f2\u6838\u5fc3\uff1f \u82e5\u745f.\u8d6b (&#8230;) <a class=\"more-link\" href=\"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/\">\u7ee7\u7eed\u9605\u8bfb <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"categories":[69],"tags":[],"class_list":["post-790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allocutions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587\" \/>\n<meta property=\"og:description\" content=\"\u5982\u4f55\u8d70\u9032\u5730\u7b2c\u56db\u4e16\u754c\u7684\u6b77\u53f2\u6838\u5fc3\uff1f \u82e5\u745f.\u8d6b (...) \u7ee7\u7eed\u9605\u8bfb &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/\" \/>\n<meta property=\"og:site_name\" content=\"Joseph Wresinski \u4e2d\u6587\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-16T08:02:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T10:26:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmestre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmestre\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/\"},\"author\":{\"name\":\"webmestre\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"headline\":\"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse)\",\"datePublished\":\"2008-09-16T08:02:42+00:00\",\"dateModified\":\"2021-06-09T10:26:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/\"},\"wordCount\":4,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2008\\\/09\\\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg\",\"articleSection\":[\"\u6f14\u8aaa\u8207\u8a0a\u606f\"],\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/\",\"name\":\"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2008\\\/09\\\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg\",\"datePublished\":\"2008-09-16T08:02:42+00:00\",\"dateModified\":\"2021-06-09T10:26:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2008\\\/09\\\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2008\\\/09\\\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg\",\"width\":580,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/article289289\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/\",\"name\":\"Joseph Wresinski \u4e2d\u6587\",\"description\":\"\u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa\u4e2d\u5fc3\u63d0\u4f9b\u7684\u7f51\u7ad9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/#\\\/schema\\\/person\\\/c666928d4be7b5b71419e1a78b02d04a\",\"name\":\"webmestre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g\",\"caption\":\"webmestre\"},\"url\":\"https:\\\/\\\/www.joseph-wresinski.org\\\/zh\\\/author\\\/webmestre\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/","og_locale":"zh_CN","og_type":"article","og_title":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587","og_description":"\u5982\u4f55\u8d70\u9032\u5730\u7b2c\u56db\u4e16\u754c\u7684\u6b77\u53f2\u6838\u5fc3\uff1f \u82e5\u745f.\u8d6b (...) \u7ee7\u7eed\u9605\u8bfb &rarr;","og_url":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/","og_site_name":"Joseph Wresinski \u4e2d\u6587","article_published_time":"2008-09-16T08:02:42+00:00","article_modified_time":"2021-06-09T10:26:10+00:00","og_image":[{"width":580,"height":400,"url":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg","type":"image\/jpeg"}],"author":"webmestre","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"webmestre","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"1 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#article","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/"},"author":{"name":"webmestre","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"headline":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse)","datePublished":"2008-09-16T08:02:42+00:00","dateModified":"2021-06-09T10:26:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/"},"wordCount":4,"commentCount":0,"image":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg","articleSection":["\u6f14\u8aaa\u8207\u8a0a\u606f"],"inLanguage":"zh-Hans","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/","url":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/","name":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse) - Joseph Wresinski \u4e2d\u6587","isPartOf":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#primaryimage"},"image":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#primaryimage"},"thumbnailUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg","datePublished":"2008-09-16T08:02:42+00:00","dateModified":"2021-06-09T10:26:10+00:00","author":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a"},"breadcrumb":{"@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.joseph-wresinski.org\/zh\/article289289\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#primaryimage","url":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg","contentUrl":"https:\/\/www.joseph-wresinski.org\/zh\/wp-content\/uploads\/sites\/14\/2008\/09\/CIJW-0070-811-051-20-22-05-1981-Pierrelaye-Hotel-de-Ville-Paris-seminaire-Forum-Afrique-5-580x400-1.jpg","width":580,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.joseph-wresinski.org\/zh\/article289289\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.joseph-wresinski.org\/zh\/"},{"@type":"ListItem","position":2,"name":"\u4e00\u6bb5\u73cd\u8cb4\u7684\u6b77\u53f2(Une histoire pr\u00e9cieuse)"}]},{"@type":"WebSite","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#website","url":"https:\/\/www.joseph-wresinski.org\/zh\/","name":"Joseph Wresinski \u4e2d\u6587","description":"\u82e5\u745f.\u8d6b\u5fcd\u65af\u57fa\u4e2d\u5fc3\u63d0\u4f9b\u7684\u7f51\u7ad9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.joseph-wresinski.org\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Person","@id":"https:\/\/www.joseph-wresinski.org\/zh\/#\/schema\/person\/c666928d4be7b5b71419e1a78b02d04a","name":"webmestre","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/416a097a3f95c03b93462266ddf7a1b5b815e837b340f6b881ae80c56b8c6d56?s=96&d=mm&r=g","caption":"webmestre"},"url":"https:\/\/www.joseph-wresinski.org\/zh\/author\/webmestre\/"}]}},"_links":{"self":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/comments?post=790"}],"version-history":[{"count":4,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/790\/revisions"}],"predecessor-version":[{"id":1701,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/posts\/790\/revisions\/1701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/media\/1697"}],"wp:attachment":[{"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/media?parent=790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/categories?post=790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.joseph-wresinski.org\/zh\/wp-json\/wp\/v2\/tags?post=790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}